{"id":11597,"date":"2018-03-12T13:45:54","date_gmt":"2018-03-12T08:15:54","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=11597"},"modified":"2022-03-23T16:35:24","modified_gmt":"2022-03-23T16:35:24","slug":"carmatec-firma-un-accordo-con-efatoora-per-una-partnership-tecnologica","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/it_it\/press-and-events\/carmatec-signs-agreement-with-efatoora-for-tech-partnership\/","title":{"rendered":"Carmatec firma una partnership tecnologica con la nuova e dinamica start-up di Dubai, eFatoora; Pronti a aprire nuovi orizzonti nella tecnologia digitale"},"content":{"rendered":"<p>BANGALORE, India, 9 marzo 2018, Carmatec \u2014 Con un&#039;altra mossa strategica per espandere il business nel suolo digitalmente &quot;fertile&quot; del Medio Oriente, la multinazionale del settore della trasformazione digitale <a href=\"http:\/\/carmatec.ae\/\">Carmatec<\/a> ha annunciato di aver siglato un accordo di partnership con la Tech Startup con sede a Dubai,<a href=\"http:\/\/www.efatoora.ae\/\"> eFatoora<\/a>. La collaborazione si concentra sullo sfruttamento delle tecnologie emergenti come Blockchain su progetti ad alto impatto per realizzare progressi straordinari e guidare la visione di Sua Altezza Sheikh Hamdan Bin Mohammed Bin Rashid Al Maktoum di una Dubai senza carta nel 2021. In termini di progressi tecnologici, BlockChain promette di aprire sostanziali opportunit\u00e0, in particolare per il commercio e la logistica, i mercati dei capitali, le assicurazioni, la propriet\u00e0 intellettuale, la sanit\u00e0 e il settore governativo a Dubai.<\/p>\n<h3><\/h3>\n<h3><strong>A proposito di Carmatec<\/strong><\/h3>\n<p>Con questa partnership, <a href=\"https:\/\/www.carmatec.com\/it_it\/\">Carmatec<\/a>\u2013 che \u00e8 leader globale nelle trasformazioni digitali e nelle soluzioni IT \u2013 rafforzer\u00e0 i suoi legami con i paesi del Golfo ed esplorer\u00e0 opportunit\u00e0 in nuovi settori di mercato. Fino a febbraio 2018, Carmatec ha apportato contributi tecnici significativi ai settori dell&#039;e-commerce, BFSI, media, stampa, pubblicit\u00e0, sanit\u00e0, edilizia, automobile e forniture IT in Medio Oriente. La pluripremiata azienda \u00e8 specializzata nell&#039;offerta di soluzioni di abilitazione digitale, aziendali, cloud e IT a start-up e organizzazioni di piccole e grandi dimensioni e ha un ampio elenco di clienti provenienti da 20 paesi.<\/p>\n<h3><\/h3>\n<h3><strong>A proposito di eFatoora<\/strong><\/h3>\n<p>Classificata tra le prime 10 startup a cui prestare attenzione dalla <a href=\"https:\/\/www.gitexfuturestars.com\/\">GITEX Future Stelle 2017<\/a>, <a href=\"http:\/\/www.efatoora.ae\/\">eFatoora<\/a> ha fatto scalpore nel settore tecnologico di Dubai per la sua ultima piattaforma basata su Blockchain. Questa nuova piattaforma offre un programma di &quot;contratti intelligenti&quot; per il settore BFSI (bancario, servizi finanziari e assicurativi) che eliminer\u00e0 la necessit\u00e0 dell&#039;intermediario e ridurr\u00e0 i costi operativi per i fornitori di servizi finanziari. Inoltre, la piattaforma promette di eliminare i problemi legati allo scambio di denaro e alle transazioni relative a propriet\u00e0 e azioni e introduce un valore di trasparenza nell&#039;intero processo. Il progetto \u00e8 in linea con la missione di eFatoora di rendere Dubai la citt\u00e0 pi\u00f9 intelligente e felice consentendo la tecnologia sostenibile in tutta la citt\u00e0.<\/p>","protected":false},"excerpt":{"rendered":"<p>BANGALORE, India, March 9, 2018, Carmatec &#8212; In another strategic move to expand business in the digitally \u2018fertile\u2019 Middle Eastern soil, the multinational digital transformation business Carmatec has announced that it has signed a partnership agreement with the Dubai-based Tech Startup, eFatoora. The collaboration is focused around leveraging emerging technologies such as Blockchain on high-impact [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-11597","post","type-post","status-publish","format-standard","hentry","category-blog","category-press-and-events"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/posts\/11597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/comments?post=11597"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/posts\/11597\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media?parent=11597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/categories?post=11597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/tags?post=11597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}