{"id":6877,"date":"2016-10-01T11:31:20","date_gmt":"2016-10-01T06:01:20","guid":{"rendered":"http:\/\/www.carmatec.com\/?post_type=project&#038;p=6877"},"modified":"2022-09-27T15:34:49","modified_gmt":"2022-09-27T15:34:49","slug":"unohire","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/it_it\/portfolio\/unohire\/","title":{"rendered":"Unohire"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/unohire-1-1080x338-1.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8668\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/unohire-1-1080x338-1.jpg\" alt=\"unohire\" width=\"1080\" height=\"338\"><\/a><\/div>\n<h3 class=\"common_sub_head\">Requisiti del progetto<\/h3>\n<p align=\"justify\">Il requisito del progetto era quello di costruire un portale del lavoro intelligente e intuitivo che consentisse un funzionamento regolare per quattro diversi tipi di utenti, consentendo loro di svolgere varie funzioni. Il requisito includeva anche lo sviluppo di un&#039;applicazione mobile per l&#039;utente in cerca di lavoro e l&#039;utente datore di lavoro. Avremmo dovuto fornire soluzioni web e mobili end-to-end dalla progettazione alla distribuzione dell&#039;applicazione. Il progetto richiedeva un team multifunzionale di designer, sviluppatori web, sviluppatori mobile e sviluppatori PHP che lavorassero in tandem in modo efficiente per costruire da zero una piattaforma superlativa. Il mercato di riferimento per il sito Web sono gli Emirati Arabi Uniti e il Regno Unito.<\/p>\n<h3 class=\"common_sub_head\">Soluzioni offerte<\/h3>\n<p align=\"justify\">La soluzione proposta era un backend PHP con un design fresco e contemporaneo insieme ad un branding unico e memorabile con l&#039;utilizzo anche della grafica fondamentale del sito web. Il sito web proposto sarebbe altamente reattivo, SEO friendly, completamente interattivo, facile da usare e dall&#039;aspetto moderno per dare all&#039;azienda cliente un vantaggio sul mercato.<\/p>\n<p align=\"justify\">L&#039;applicazione \u00e8 stata creata pensando alla facilit\u00e0 d&#039;uso e alla scalabilit\u00e0 futura. E anche considerando la possibilit\u00e0 di integrare perfettamente nuove funzionalit\u00e0 nelle prossime fasi di sviluppo in futuro.<\/p>\n<h3 class=\"common_sub_head\">Caratteristiche<\/h3>\n<p>Il sito web avr\u00e0 4 utenti come ospite, persona in cerca di lavoro, datore di lavoro e amministratore.<\/p>\n<ul>\n<li>L&#039;utente ospite pu\u00f2 visualizzare tutti i lavori e utilizzare i filtri per scoprire lavori correlati, settore specifico ecc.<\/li>\n<li>Un utente ospite pu\u00f2 presentare domanda solo se \u00e8 registrato nel sistema.<\/li>\n<li>L&#039;utente registrato pu\u00f2 aggiornare il proprio profilo, salvare i lavori cercati, visualizzare le candidature ecc.<\/li>\n<li>I datori di lavoro possono gestire il proprio account, gli utenti, i lavori, ecc.<\/li>\n<li>Il sistema sposter\u00e0 i lavori inattivi nella cartella di scadenza e il datore di lavoro dovr\u00e0 attivarli per renderli attivi.<\/li>\n<li>Un utente amministratore monitora il sito web, assegna ruoli e garantisce il buon funzionamento dello stesso.<\/li>\n<\/ul>\n<h3 class=\"common_sub_head\">Tecnologia utilizzata<\/h3>\n<p>PHP, Html\/Css\/JS, Java Android, parser JSON e XML<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\">&nbsp;<\/h2>","protected":false},"excerpt":{"rendered":"<p>Project Requirement The project requirement was to build an intelligent and intuitive job portal which would enable smooth operation for four different types of users, enabling them to perform various functions. The requirement also included a mobile application development for the Job Seeker user and the Employer user. We were supposed to provide end-to-end web [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28364,"template":"","portfolio_categories":[31,33,35],"class_list":["post-6877","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-internet","portfolio_categories-mobile","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio\/6877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media\/28364"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media?parent=6877"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio_categories?post=6877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}