{"id":35764,"date":"2023-03-03T11:35:48","date_gmt":"2023-03-03T11:35:48","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=portfolio&#038;p=35764"},"modified":"2023-04-04T12:46:46","modified_gmt":"2023-04-04T12:46:46","slug":"munafa","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/it_it\/portfolio\/munafa\/","title":{"rendered":"Munafa"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1600\" height=\"500\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi.jpg\" alt=\"Rupifi\" class=\"wp-image-35795\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi.jpg 1600w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi-18x6.jpg 18w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi-400x125.jpg 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/desk-screen-Rupifi-1536x480.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>descrizione del progetto<\/strong><\/h3>\n\n\n\n<p>Rupifi \u00e8 una piattaforma digitale B2B che offre prestiti, capitale circolante e servizi di pagamento alle piccole imprese. Carmatec \u00e8 orgogliosa di aver collaborato con Rupifi per sviluppare la piattaforma comunitaria MUNAFA. Il nostro team di sviluppatori esperti ha lavorato instancabilmente per creare un sito Web che funger\u00e0 da fonte affidabile di informazioni, contenuti e collegamenti commerciali per le MPMI indiane, supportandole in ogni fase del loro viaggio. Il sito Web \u00e8 stato creato per soddisfare gli utenti finali, con un pannello di amministrazione per l&#039;azienda. Il sito Web offre funzionalit\u00e0 come la visualizzazione dei post, le notifiche per i nuovi post e le opzioni di ricerca. Il sito Web include anche elenchi di post, con la possibilit\u00e0 per gli utenti di cercare, filtrare e ordinare i post in base alle proprie preferenze.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h3 class=\"wp-block-heading\"><strong>Caratteristiche<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Processo di registrazione facile e semplice<\/li>\n\n\n\n<li>Interfaccia utente estetica e flusso di lavoro coerente<\/li>\n\n\n\n<li>Integrazione delle condivisioni sociali<\/li>\n\n\n\n<li>Funzionalit\u00e0 di ricerca basata sui post<\/li>\n\n\n\n<li>Integrazione con Google Analytics, Gateway SMS, Notifiche push e Posizione GPS<\/li>\n\n\n\n<li>Funzionalit\u00e0 di ottimizzazione SEO tra cui generazione di mappe del sito, tag OG personalizzabili, titolo e meta tag, URL ottimizzati per i motori di ricerca e ottimizzazione della velocit\u00e0 della pagina<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"795\" height=\"513\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/dRupifi.png\" alt=\"munafa\" class=\"wp-image-35796\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/dRupifi.png 795w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/dRupifi-300x194.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/dRupifi-768x496.png 768w\" sizes=\"(max-width: 795px) 100vw, 795px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Soluzione offerta<\/strong><\/h3>\n\n\n\n<p>Arrivando a un livello di comprensione della visione proposta, Carmatec ne ha analizzato le fattibilit\u00e0<br>e i risultati attesi in tal modo proposti per sviluppare una piattaforma esclusiva di vasta portata<br>sul mercato offrendo un web progressivo intuitivo e PWA.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Tecnologia<\/strong><\/h3>\n\n\n\n<p>WordPress, <a href=\"https:\/\/www.carmatec.com\/it_it\/sviluppo-progressivo-di-app-web\/\" target=\"_blank\" rel=\"noreferrer noopener\">Applicazione Web progressiva<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Rupifi \u00e8 una piattaforma digitale B2B che offre prestiti, capitale circolante e servizi di pagamento alle piccole imprese. Carmatec \u00e8 orgogliosa di aver collaborato con Rupifi per sviluppare la piattaforma comunitaria MUNAFA.<\/p>","protected":false},"author":2,"featured_media":35795,"template":"","portfolio_categories":[36],"class_list":["post-35764","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-design"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio\/35764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media\/35795"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media?parent=35764"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio_categories?post=35764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}