{"id":3017,"date":"2015-03-11T07:45:50","date_gmt":"2015-03-11T02:15:50","guid":{"rendered":"http:\/\/\/?post_type=project&#038;p=3017"},"modified":"2023-03-13T14:42:48","modified_gmt":"2023-03-13T14:42:48","slug":"tecnologia-della-griglia-suprema","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/it_it\/portfolio\/supreme-grid-tech\/","title":{"rendered":"Tecnologia della griglia suprema"},"content":{"rendered":"<p><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/office.png\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8920\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/office.png\" alt=\"ufficio\" width=\"1600\" height=\"500\"><\/a><\/p>\n<h3 class=\"common_sub_head\">descrizione del progetto<\/h3>\n<p style=\"text-align: justify;\">Un progetto di sviluppo di siti Web e applicazioni per un&#039;importante azienda indiana che fornisce soluzioni di gestione intelligente dell&#039;energia per i domini SmartGrid e solare fornendo strutture di monitoraggio e controllo end-to-end. Anche questo \u00e8 stato un progetto ampio che ha coinvolto web design, sviluppo web e sviluppo di applicazioni.<\/p>","protected":false},"excerpt":{"rendered":"<p>Project Description A website and application development project for a major Indian company providing Intelligent Energy Management Solutions for the SmartGrid &amp; Solar domains by providing End-to-End monitoring &amp; Control frameworks. This was again an extensive project with web design, web development and application development involved.<\/p>","protected":false},"author":2,"featured_media":31283,"template":"","portfolio_categories":[35],"class_list":["post-3017","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio\/3017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media\/31283"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media?parent=3017"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/portfolio_categories?post=3017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}