{"id":18,"count":1,"description":"I nostri blog sull&#039;automazione del marketing ti terranno aggiornato su tutto, dagli strumenti pi\u00f9 recenti, alle strategie di marketing, alle novit\u00e0 del settore e alle tendenze delle agenzie.","link":"https:\/\/www.carmatec.com\/it_it\/category\/marketing-automation\/","name":"Automazione del marketing","slug":"automazione-del-marketing","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}