{"id":27219,"date":"2022-01-28T09:18:42","date_gmt":"2022-01-28T09:18:42","guid":{"rendered":"https:\/\/new.carmatec.com\/?post_type=casestudy&#038;p=27219"},"modified":"2023-09-28T08:55:22","modified_gmt":"2023-09-28T08:55:22","slug":"unapp-per-celebrare-un-importante-festival-indiano","status":"publish","type":"casestudy","link":"https:\/\/www.carmatec.com\/it_it\/casestudy\/an-app-for-celebration-of-a-major-indian-festival\/","title":{"rendered":"Applicazione mobile del festival"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"27219\" class=\"elementor elementor-27219\" data-elementor-post-type=\"casestudy\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edc9968 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc9968\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88460ed\" data-id=\"88460ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2f5178 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a2f5178\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e92733\" data-id=\"0e92733\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0b70d elementor-widget elementor-widget-lae-heading\" data-id=\"9c0b70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Paese<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6000696 elementor-widget elementor-widget-text-editor\" data-id=\"6000696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tIndia\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b856e0c\" data-id=\"b856e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee0bc6 elementor-widget elementor-widget-lae-heading\" data-id=\"1ee0bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Industria<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af1b901 elementor-widget elementor-widget-text-editor\" data-id=\"af1b901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Internet<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-441399b\" data-id=\"441399b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-333b274 elementor-widget elementor-widget-lae-heading\" data-id=\"333b274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">piattaforma<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1db07 elementor-widget elementor-widget-text-editor\" data-id=\"4c1db07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Mobile<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50bb5e8 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"50bb5e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98b7dff\" data-id=\"98b7dff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-581d578 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"581d578\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-36f6bb5\" data-id=\"36f6bb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70fef06 elementor-widget elementor-widget-text-editor\" data-id=\"70fef06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"common_para\">Il cliente si \u00e8 rivolto a Carmatec con la richiesta di sviluppare un&#039;applicazione mobile unica per Ganeshotsav, che si sarebbe posizionata come la prima destinazione unica in India per tutto ci\u00f2 che il pubblico ha bisogno di sapere sulla celebrazione di Ganesh Chaturthi ogni anno. Con questa app, un tocco consentirebbe all&#039;utente di scorrere ed esplorare il vasto mondo di Ganpati, offrendo molteplici posizioni mandap, eventi che li terranno assorti nei colori di Ganpati Bappa, una guida festiva per tutte le loro esigenze (da Ganpati Aarti, Decorazioni, Ganpati Matra, Modak Recipes to Fashion Fun), insieme a numerosi punti visarjan in giro per la citt\u00e0. Non solo questo! L&#039;allegria \u00e8 raddoppiata con alcuni concorsi in-app incredibilmente divertenti ogni giorno per celebrare il carnevale festivo lungo 11 giorni. L&#039;app Ganeshotsav consentirebbe all&#039;utente di godersi la febbre del festival in modo semplice e comodamente da casa, con un semplice tocco!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2731b195 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2731b195\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-532bbb72\" data-id=\"532bbb72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac07876 elementor-widget elementor-widget-lae-heading\" data-id=\"ac07876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-align\" >\n\n    <h3 class=\"lae-title\">Requisito di business<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0c8da61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c8da61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f081e4a elementor-invisible\" data-id=\"f081e4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfbd58d elementor-widget elementor-widget-text-editor\" data-id=\"cfbd58d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"common_para\">Considerando la domanda del mercato, il cliente ha avuto l&#039;idea di sviluppare un&#039;applicazione unica (mobile) per consentire al pubblico di accedere a tutte le informazioni (pantaloni, acquisti di idoli, eventi, vestiti, regali, ecc.) di cui avevano bisogno durante il Festival di Ganesh.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4697937 elementor-invisible\" data-id=\"4697937\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2765b92 elementor-widget elementor-widget-image\" data-id=\"2765b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"488\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg\" class=\"attachment-full size-full wp-image-28118\" alt=\"Obiettivi aziendali 2\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg 800w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-300x183.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-768x468.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c19173b elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c19173b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd4aa0\" data-id=\"0fd4aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7787a9f elementor-widget elementor-widget-lae-heading\" data-id=\"7787a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Obiettivi aziendali<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-091858f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"091858f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b6fa688\" data-id=\"b6fa688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69919a5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"69919a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>L&#039;obiettivo della creazione dell&#039;applicazione era triplice:<\/b><\/p>\n<p><b>Informazione<\/b>\u00a0- L&#039;app aveva lo scopo di fornire informazioni complete su mandap, eventi, dettagli Visarjan e dettagli sulle celebrit\u00e0 di eventi o mandap specifici ecc. In un unico posto gli utenti potevano trovare tutte le informazioni sul festival di Ganesha che si sarebbe svolto a Mumbai e Pune.<\/p>\n<p><b>Convenienza<\/b>\u00a0\u2013 Gli utenti non devono pi\u00f9 lottare per trovare eventi nelle vicinanze, mandap o dettagli visarjan ecc. Fornisce prima loro i dettagli pi\u00f9 vicini, quindi visualizzer\u00e0 tutti gli altri dettagli, quindi gli utenti finali possono semplicemente utilizzare l&#039;app per vedere i dettagli richiesti risparmiando molto tempo.<\/p>\n<p><b>Fidanzamento<\/b>\u00a0\u2013 Ci\u00f2 offre agli utenti finali la possibilit\u00e0 di partecipare a pi\u00f9 concorsi che si stanno svolgendo a Pune e Mumbai, possono scattare un selfie e caricare quelle foto nell&#039;app, alla fine del concorso gli utenti possono anche vincere i migliori premi offerti dal cliente. Gli utenti possono effettuare il &quot;check-in&quot; utilizzando l&#039;app quando visitano qualsiasi mandap.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d844f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"34d844f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf274af\" data-id=\"cf274af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9161bb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9161bb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b468eb elementor-invisible\" data-id=\"3b468eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f41f7e6 elementor-widget elementor-widget-lae-heading\" data-id=\"f41f7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Soluzione offerta<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b859aa elementor-widget elementor-widget-text-editor\" data-id=\"9b859aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Carmatec ha sviluppato un&#039;applicazione mobile nativa bilingue (inglese e marathi) fornendo allo stesso tempo diversi sistemi per cliente e amministratore. L&#039;app mobile funzioner\u00e0 in sincronia con l&#039;applicazione web per offrire agli utenti un&#039;interazione fluida. I clienti possono scaricare l&#039;app mobile dal Play Store e successivamente registrarsi\/accedere utilizzando il modulo o account di social media come Facebook e Google. Dopo aver effettuato l&#039;accesso alla pagina di destinazione, l&#039;utente pu\u00f2 visualizzare l&#039;elenco di eventi, mandap, guida festiva, visarjan e dettagli del concorso ecc. E avr\u00e0 la possibilit\u00e0 di fare clic su uno per visualizzarne i dettagli e aggiungere ulteriormente le proprie valutazioni e recensioni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b580c8c elementor-widget elementor-widget-text-editor\" data-id=\"b580c8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>Le caratteristiche principali della piattaforma e le sue capacit\u00e0 sono<\/b><\/p>\n<ul>\n<li>Localizzatori Puja Mandap<\/li>\n<li>Guida alle feste<\/li>\n<li>Informazioni sugli eventi<\/li>\n<li>Libretto Ganesh Aarti<\/li>\n<li>Concorsi<\/li>\n<\/ul>\n<p>Uno dei punti salienti del progetto \u00e8 stato che, nonostante fosse stato assegnato solo pochi giorni prima del festival, lo abbiamo implementato con successo appena prima del Festival di Ganesha. Ci \u00e8 stato chiesto di creare l&#039;app mobile inclusa l&#039;amministrazione in appena un mese. Il team di sviluppo dell&#039;app mobile ha svolto un lavoro straordinario per completare il progetto entro il mese stabilito, gestendo in modo efficiente il rigoroso programma.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79ba21a animated-slow elementor-invisible\" data-id=\"79ba21a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45fedc2 elementor-widget elementor-widget-text-editor\" data-id=\"45fedc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>Utilizzando l&#039;app utile, gli utenti possono accedere ai moduli menzionati di seguito:<\/b><\/p>\n<ul>\n<li><b>Mandaps<\/b>: Il cliente sar\u00e0 in grado di visualizzare i pandali vicini e avr\u00e0 la possibilit\u00e0 di fare clic su uno e visualizzare dettagli come nome, indirizzo, galleria di immagini, orari Pooja ecc.<\/li>\n<li><b>Concorsi<\/b>: Il cliente sar\u00e0 in grado di visualizzare l&#039;elenco dei concorsi aggiunti dall&#039;amministratore e avr\u00e0 la possibilit\u00e0 di partecipare condividendo la propria foto selfie e i contenuti ad essa correlati.<\/li>\n<li><b>Notifiche<\/b>: Il cliente potr\u00e0 visualizzare le notifiche che ha ricevuto relative ai pandali, ai tempi di Pooja, ecc.<\/li>\n<li><b>Il mio profilo<\/b>: Qui potr\u00e0 visualizzare e modificare i suoi dati personali.<\/li>\n<li><b>Altre pagine<\/b>: Qui potr\u00e0 visualizzare i contenuti relativi a Informazioni su Ganeshotsav, Informazioni sull&#039;app Ganeshotsav, Trasporti e Numeri di emergenza.<\/li>\n<li><b>Contattaci<\/b>: Qui visualizzer\u00e0 i dettagli di contatto e avr\u00e0 la possibilit\u00e0 di compilare il modulo di contatto, all&#039;invio del quale l&#039;e-mail verr\u00e0 inviata all&#039;amministratore.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-96951f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96951f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-330a533 elementor-invisible\" data-id=\"330a533\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60b07d8 elementor-widget elementor-widget-lae-heading\" data-id=\"60b07d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Risultato<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edfbcb7 elementor-widget elementor-widget-text-editor\" data-id=\"edfbcb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nell&#039;arco di 48 ore, sono avvenute oltre 10.000 installazioni dopo aver lanciato l&#039;app agli utenti finali. La valutazione media degli utenti finali \u00e8 4,5 e nessuna escalation da parte di alcun cliente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1fe7f3b animated-slow elementor-invisible\" data-id=\"1fe7f3b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d8bb3e elementor-widget elementor-widget-lae-heading\" data-id=\"4d8bb3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Pila tecnologica<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bc445c elementor-widget elementor-widget-text-editor\" data-id=\"0bc445c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>PHP<\/li><li>Torta PHP 3.6<\/li><li>MySQL 5.7<\/li><li>HTML5,CSS3<\/li><li>Javascript<\/li><li>JQuery,Ajax<\/li><li>Apache2.4<\/li><li>Va bene, SES<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":2,"featured_media":37918,"template":"","casestudy_categories":[43,44],"class_list":["post-27219","casestudy","type-casestudy","status-publish","has-post-thumbnail","hentry","casestudy_categories-mobile-app-development","casestudy_categories-startup"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/casestudy\/27219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/casestudy"}],"about":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/types\/casestudy"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/casestudy\/27219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media\/37918"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/media?parent=27219"}],"wp:term":[{"taxonomy":"casestudy_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/it_it\/wp-json\/wp\/v2\/casestudy_categories?post=27219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}