{"id":5637,"date":"2016-03-01T17:11:39","date_gmt":"2016-03-01T11:41:39","guid":{"rendered":"http:\/\/carmatec.com\/?p=5637"},"modified":"2022-09-29T11:57:15","modified_gmt":"2022-09-29T11:57:15","slug":"le-guide-du-debutant-sur-les-hashtags","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/fr_fr\/learn-technology\/the-beginners-guide-to-hashtags\/","title":{"rendered":"Le guide du d\u00e9butant sur les hashtags"},"content":{"rendered":"<h2>HASHTAGS<\/h2>\n<p>Que vous les aimiez ou les d\u00e9testiez, les hashtags sont l\u00e0 pour rester ! Apparue avec appr\u00e9hension en 2007, la tendance n&#039;a fait que prendre un essor consid\u00e9rable depuis lors et on ne peut plus passer une journ\u00e9e sur les r\u00e9seaux sociaux sans tomber sur des hashtags. Il y a des hashtags dr\u00f4les, inspirants, bizarres, s\u00e9rieux, tendance, toutes sortes de hashtags et le meilleur, c&#039;est que tout le monde peut cr\u00e9er un hashtag (#SocialMediaRocks) \u2013 Vous voyez ce que j&#039;ai fait l\u00e0-bas ? Il suffit d\u2019ajouter un signe di\u00e8se devant un mot et cela devient un hashtag !<\/p>\n<p>Une explication simple du hashtag serait qu&#039;il s&#039;agit d&#039;un mot ou d&#039;un groupe de mots pr\u00e9c\u00e9d\u00e9 d&#039;un signe di\u00e8se (#). Vous n&#039;avez besoin d&#039;aucune exp\u00e9rience en codage ou d&#039;un logiciel sp\u00e9cial pour transformer un mot en hashtag. Ajoutez simplement un signe di\u00e8se et vous \u00eates pr\u00eat \u00e0 partir. Assurez-vous qu\u2019il n\u2019y a pas d\u2019espaces, pas de ponctuation et pas de caract\u00e8res sp\u00e9ciaux entre les deux. Vous pouvez distinguer les mots en utilisant une lettre majuscule par exemple, un hashtag tr\u00e8s populaire de Nike distingue les diff\u00e9rents mots avec une lettre majuscule ##MakeItCount (quand vous lisez ceci, vous savez que c&#039;est \u00ab Make It Count \u00bb).<\/p>\n<p>Cela signifie-t-il #You #Can #Add #anything #as #hashtags\u00a0? Non. Ajouter tout et n&#039;importe quoi comme hashtags donnera non seulement une mauvaise apparence \u00e0 votre tweet\/post, mais ennuiera \u00e9galement vos abonn\u00e9s. Tout comme trop de cuisiniers g\u00e2chent le bouillon, trop de hashtags vous font para\u00eetre horrible\u00a0!<\/p>\n<p>En fait, en langage geek, les hashtags sont des balises de m\u00e9tadonn\u00e9es utilis\u00e9es pour regrouper les conversations. Par exemple, si vous souhaitez suivre un sujet de fitness, vous pouvez effectuer une recherche avec #fitness et tout tweet utilisant ce hashtag appara\u00eetra dans la recherche et vous pourrez suivre les personnes qui les ont utilis\u00e9s.<\/p>\n<p>Si vous cherchez \u00e0 vous lancer dans cette mode des m\u00e9dias sociaux, voici quelques choses \u00e0 faire et \u00e0 ne pas faire que vous devez suivre\u00a0:<\/p>\n<h2>\u00c0 faire<\/h2>\n<ul>\n<li>Recherchez ce qui flotte dans le secteur dans lequel vous \u00e9voluez. Par exemple, si vous \u00eates une petite entreprise, d\u00e9couvrez tous les hashtags li\u00e9s \u00e0 votre secteur d&#039;activit\u00e9 et utilisez les hashtags pour diffuser votre message.<\/li>\n<li>Soyez pr\u00e9cis. Trouvez des personnes et des entreprises partageant votre int\u00e9r\u00eat pour des th\u00e8mes sp\u00e9cifiques. Plus vous \u00eates pr\u00e9cis, plus il vous sera facile de trouver un public cibl\u00e9.<\/li>\n<li>Suis les r\u00e8gles. Les r\u00e8gles d&#039;utilisation des hashtags peuvent varier d&#039;une cha\u00eene \u00e0 l&#039;autre m\u00eame si les principes fondamentaux sont les m\u00eames. Par exemple, alors que pour Twitter l\u2019accent est davantage mis sur le sujet, pour Instagram, l\u2019accent est davantage mis sur la description de la photo.<\/li>\n<li>Les hashtags peuvent \u00eatre utilis\u00e9s pour tirer parti du marketing int\u00e9gr\u00e9. Proposez des hashtags pertinents pour votre entreprise afin de promouvoir vos supports marketing.<\/li>\n<li>Dernier point mais non le moindre, engagez-vous aupr\u00e8s de votre communaut\u00e9. Les r\u00e9seaux sociaux sont avant tout une question de conversations. Au lieu de publier uniquement des hashtags et de les oublier, interagissez avec vos utilisateurs.<\/li>\n<\/ul>\n<h2>\u00c0 ne pas faire<\/h2>\n<ul>\n<li>Ne surchargez pas vos publications avec des hashtags. Utiliser trop de hashtags marquera votre message comme spam et m\u00eame un bon message se noiera dans la mer de hashtags. Tenez-vous en \u00e0 seulement deux \u00e0 trois hashtags par publication. N&#039;ayez jamais de hashtags plus que des mots. C&#039;est un outil pour am\u00e9liorer votre conversation, pas la conversation elle-m\u00eame. Utiliser trop de hashtags diluera votre message.<\/li>\n<li>Tenez-vous-en \u00e0 votre genre et hashtag quelque chose qui est pertinent pour votre entreprise. Ne hashtagez pas tout.<\/li>\n<li>N&#039;utilisez pas de hashtags tr\u00e8s longs, cela ne fait que d\u00e9router le visiteur et est contre-productif. Gardez vos hashtags courts.<\/li>\n<li>N&#039;utilisez pas de hashtags pour toutes les plateformes sociales. Alors que les sites Web aiment <a href=\"https:\/\/www.facebook.com\">Facebook<\/a>, <a href=\"https:\/\/www.instagram.com\">Instagram<\/a>, <a href=\"https:\/\/plus.google.com\">Google+<\/a>, YouTube, Flickr, Tumblr et Pinterest encouragent leurs utilisateurs \u00e0 utiliser des hashtags, mais pour des sites Web comme LinkedIn, cela peut ne pas \u00eatre pertinent.<\/li>\n<li>Rester simple. \u00c9vitez les acronymes que les gens connaissent \u00e0 peine.<\/li>\n<\/ul>\n<p>Utiliser correctement les hashtags peut vous aider \u00e0 cr\u00e9er une impression favorable aupr\u00e8s de votre public cible. Faites-le bien et faites-le souvent\u00a0! Et n&#039;oubliez pas de partager vos commentaires dans la zone de commentaires ! Nous aimons avoir de vos nouvelles\u00a0!<\/p>\n<h3><\/h3>","protected":false},"excerpt":{"rendered":"<p>HASHTAGS Whether you love them or hate them, hashtags are here to stay! Coming on to the scene with trepidation in 2007, the trend has only gained huge momentum since then and now you cannot go by a day on social channels without coming across hashtags. There are funny, inspirational, weird, serious, trending, all kinds [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5639,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn-technology"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/5637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=5637"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/5637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=5637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=5637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=5637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}