{"id":35826,"date":"2023-03-30T09:53:55","date_gmt":"2023-03-30T09:53:55","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=35826"},"modified":"2026-02-02T10:11:16","modified_gmt":"2026-02-02T10:11:16","slug":"meilleures-pratiques-de-securite-magento-comment-assurer-la-securite-de-votre-magasin","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/fr_fr\/blog\/magento-security-best-practices-how-to-keep-your-store-safe\/","title":{"rendered":"Meilleures pratiques de s\u00e9curit\u00e9 Magento\u00a0: comment assurer la s\u00e9curit\u00e9 de votre boutique"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"35826\" class=\"elementor elementor-35826\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-deeec74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"deeec74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74c7887\" data-id=\"74c7887\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-699b717 elementor-widget elementor-widget-text-editor\" data-id=\"699b717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Comment s\u00e9curiser votre site Web Magento devrait \u00eatre votre principale pr\u00e9occupation lors de la cr\u00e9ation d&#039;une boutique de commerce \u00e9lectronique \u00e0 l&#039;aide de Magento. Il existe de puissantes fonctionnalit\u00e9s de s\u00e9curit\u00e9 int\u00e9gr\u00e9es dans Magento, mais vous devez faire quelque chose pour prot\u00e9ger votre site contre les attaques ou la perte de donn\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Bien qu\u2019il s\u2019agisse d\u2019une puissante plateforme de commerce \u00e9lectronique avec plus de 250\u00a0000 sites actifs, elle pr\u00e9sente \u00e9galement certains risques en mati\u00e8re de s\u00e9curit\u00e9. 87\u00a0% des magasins de commerce \u00e9lectronique bas\u00e9s sur Magento sont expos\u00e9s \u00e0 un risque plus \u00e9lev\u00e9 de cyberattaques, <a href=\"https:\/\/www.techradar.com\/news\/magento-ecommerce-sites-at-high-risk-of-cyberattack\">selon un r\u00e9cent rapport de s\u00e9curit\u00e9 TechRadar<\/a>.<\/span><\/p><p><span style=\"font-weight: 400;\">Il est possible que votre magasin en fasse partie.<\/span><\/p><h2><b>Qu&#039;est-ce que la s\u00e9curit\u00e9 Magento<\/b><\/h2><p><span style=\"font-weight: 400;\">L&#039;une des plateformes de commerce \u00e9lectronique les plus populaires, Magento dispose de fonctionnalit\u00e9s de s\u00e9curit\u00e9 int\u00e9gr\u00e9es qui r\u00e9duisent les risques de s\u00e9curit\u00e9 tels que les fuites de donn\u00e9es, le vol d&#039;informations et les transactions ill\u00e9gales. Assurez-vous d&#039;avoir appliqu\u00e9 toutes les pratiques de s\u00e9curit\u00e9 modernes de Magento, y compris les th\u00e8mes, extensions et h\u00e9bergements fiables.<\/span><\/p><p><span style=\"font-weight: 400;\">Cela montre clairement que Magento est le premier choix pour quiconque envisage de cr\u00e9er une boutique de commerce \u00e9lectronique en 2020, quelle que soit sa taille ou son historique. Magento, cependant, offre d&#039;excellentes pratiques de s\u00e9curit\u00e9 d\u00e8s le d\u00e9part \u00e0 la plupart des commer\u00e7ants en ligne.<\/span><\/p><h2><b>Liste de contr\u00f4le de s\u00e9curit\u00e9 Magento\u00a0: comment s\u00e9curiser votre boutique Magento en 2023\u00a0?<\/b><\/h2><p><span style=\"font-weight: 400;\">Vous pouvez \u00e9viter (et dans une certaine mesure, r\u00e9soudre) les probl\u00e8mes de s\u00e9curit\u00e9 de Magento en suivant la liste de contr\u00f4le ci-dessous. Voici quelques conseils de s\u00e9curit\u00e9 Magento pour vous aider \u00e0 conserver votre <a href=\"https:\/\/www.carmatec.com\/fr_fr\/commerce-electronique-en-tant-que-service\/\">boutique de commerce \u00e9lectronique<\/a> s\u00e9curis\u00e9:<\/span><\/p><h3><b>La derni\u00e8re version de Magento doit \u00eatre utilis\u00e9e<\/b><\/h3><p><span style=\"font-weight: 400;\">Il arrive parfois qu\u2019on vous dise que la version la plus r\u00e9cente de Magento n\u2019est pas la meilleure. La raison en est que la plupart des gens pensent que la derni\u00e8re version de Magento n&#039;est pas suffisamment s\u00e9curis\u00e9e. Bien que cela soit vrai, les d\u00e9veloppeurs corrigent g\u00e9n\u00e9ralement les probl\u00e8mes de correctifs de s\u00e9curit\u00e9 pr\u00e9c\u00e9dents de Magento dans les nouvelles versions. Par cons\u00e9quent, il est essentiel de rester \u00e0 jour avec les correctifs Magento les plus r\u00e9cents. Apr\u00e8s la publication d\u2019une version stable, vous devez effectuer des tests Magento avant de l\u2019impl\u00e9menter.<\/span><\/p><h3><b>Utiliser l&#039;authentification \u00e0 deux facteurs (2FA)<\/b><\/h3><p><span style=\"font-weight: 400;\">La plate-forme Magento 2 prend en charge l&#039;authentification \u00e0 deux facteurs (2FA), qui ajoute une couche de furtivit\u00e9 ou de mouvement subreptice. Quatre types diff\u00e9rents d&#039;authentificateurs sont utilis\u00e9s pour permettre aux appareils de confiance d&#039;acc\u00e9der au backend de Magento 2.<\/span><\/p><p><span style=\"font-weight: 400;\">En utilisant le code de s\u00e9curit\u00e9 de votre smartphone et le mot de passe de votre connexion administrateur Magento, l&#039;extension Magento Two Factor Authentication am\u00e9liore la s\u00e9curit\u00e9 de votre connexion administrateur Magento. Pour acc\u00e9der au panneau d&#039;administration de Magento 2, autorisez uniquement les utilisateurs autoris\u00e9s \u00e0 acc\u00e9der au code.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous n&#039;avez plus \u00e0 vous soucier des risques de s\u00e9curit\u00e9 Magento li\u00e9s aux mots de passe avec certaines extensions Magento prenant en charge l&#039;authentification \u00e0 deux facteurs (2FA).<\/span><\/p><h3><b>Personnaliser le chemin du panneau d&#039;administration<\/b><\/h3><p><span style=\"font-weight: 400;\">Le panneau d&#039;administration Magento est accessible sur my-site.com\/admin. Les pirates peuvent facilement acc\u00e9der \u00e0 votre page de connexion d&#039;administrateur Magento et mener des attaques par force brute.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous pouvez emp\u00eacher cela en utilisant \/admin avec un terme personnalis\u00e9 (par exemple, \u00ab Store Door \u00bb). Si des pirates informatiques parviennent \u00e0 mettre la main sur votre mot de passe, ils ne peuvent \u00e9galement pas acc\u00e9der \u00e0 votre page de connexion administrateur Magento. En modifiant le fichier local.xml dans Magento 1 et le fichier env.php dans Magento 2, vous pouvez modifier votre chemin d&#039;administration Magento.<\/span><\/p><h3><b>Acqu\u00e9rir une connexion crypt\u00e9e (SSL\/HTTPS)<\/b><\/h3><p><span style=\"font-weight: 400;\">Les donn\u00e9es envoy\u00e9es via une connexion non crypt\u00e9e, comme vos informations de connexion, risquent d&#039;\u00eatre intercept\u00e9es. Les assaillants pourront peut-\u00eatre consulter vos informations d\u2019identification gr\u00e2ce \u00e0 cette interception. Les connexions Magento doivent \u00eatre s\u00e9curis\u00e9es afin d&#039;\u00e9viter ces probl\u00e8mes.<\/span><\/p><p><span style=\"font-weight: 400;\">Magento vous permet d&#039;obtenir une URL HTTPS\/SSL s\u00e9curis\u00e9e en cochant l&#039;onglet \u00ab Utiliser les URL s\u00e9curis\u00e9es \u00bb dans le menu de configuration du syst\u00e8me. De plus, il s\u2019agit d\u2019un \u00e9l\u00e9ment essentiel pour rendre votre site Web Magento conforme \u00e0 la norme de s\u00e9curit\u00e9 des donn\u00e9es PCI.<\/span><\/p><p><span style=\"font-weight: 400;\">Let&#039;s Encrypt est un bon point de d\u00e9part si vous souhaitez un <a href=\"https:\/\/www.carmatec.com\/fr_fr\/meilleurs-fournisseurs-de-certificats-ssl-en-inde\/\">Certificat SSL<\/a>. De plus, cela vous aidera \u00e0 devenir conforme \u00e0 la norme PCI.<\/span><\/p><h3><b>Utiliser FTP s\u00e9curis\u00e9<\/b><\/h3><p><span style=\"font-weight: 400;\">Deviner ou intercepter facilement les mots de passe FTP est l\u2019un des moyens les plus courants de pirater un site Web.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0SFTP (Secured File Transfer Protocol) utilise un fichier de cl\u00e9 priv\u00e9e pour d\u00e9crypter et authentifier les utilisateurs, afin que vous puissiez \u00e9viter que cela ne vous arrive. Sur Carmatec, l&#039;acc\u00e8s SFTP est d\u00e9j\u00e0 disponible.<\/span><\/p><h3><b>Avoir un plan de sauvegarde actif<\/b><\/h3><p><span style=\"font-weight: 400;\">Prendre des pr\u00e9cautions pour la s\u00e9curit\u00e9 de Magento est une excellente pratique, mais un plan de sauvegarde est tout aussi vital. Les sauvegardes hors site doivent \u00eatre effectu\u00e9es toutes les heures et des sauvegardes t\u00e9l\u00e9chargeables doivent \u00e9galement \u00eatre effectu\u00e9es. Le plan de sauvegarde garantira que vous ne subirez aucune interruption de service si votre site Web est pirat\u00e9 ou tombe en panne pour quelque raison que ce soit.<\/span><\/p><p><span style=\"font-weight: 400;\">Les fichiers de sauvegarde de votre site Web peuvent \u00eatre stock\u00e9s hors site ou sauvegard\u00e9s via un service de sauvegarde en ligne pour \u00e9viter la perte de donn\u00e9es. La perte de donn\u00e9es est minime gr\u00e2ce \u00e0 la sauvegarde des donn\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous devriez toujours demander \u00e0 votre fournisseur d&#039;h\u00e9bergement s&#039;il a une strat\u00e9gie de sauvegarde. Nos sauvegardes sont opportunes et suffisantes \u00e0 <a href=\"https:\/\/www.carmatec.com\/fr_fr\/\">Carmatec<\/a>.<\/span><\/p><h3><b>L&#039;indexation des r\u00e9pertoires doit \u00eatre d\u00e9sactiv\u00e9e<\/b><\/h3><p><span style=\"font-weight: 400;\">Vous pouvez am\u00e9liorer la s\u00e9curit\u00e9 de votre boutique Magento en d\u00e9sactivant l&#039;indexation des r\u00e9pertoires. En d\u00e9sactivant l&#039;indexation des r\u00e9pertoires, vous pourrez masquer diff\u00e9rents chemins par lesquels les fichiers de votre domaine sont stock\u00e9s.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous pouvez l&#039;utiliser pour emp\u00eacher les cybercriminels d&#039;acc\u00e9der aux fichiers principaux de votre site Web aliment\u00e9 par Magento. Ils peuvent toujours vous acc\u00e9der s&#039;ils connaissent le chemin complet de vos donn\u00e9es.<\/span><\/p><h3><b>Vous devez \u00eatre prudent avec votre mot de passe Magento<\/b><\/h3><p><span style=\"font-weight: 400;\">Vous avez besoin d&#039;un mot de passe pour acc\u00e9der \u00e0 votre boutique Magento. C\u2019est pour cette raison que vous devez \u00eatre tr\u00e8s prudent lors du choix d\u2019un mot de passe. Cr\u00e9ez un mot de passe contenant des alphabets majuscules et minuscules, des chiffres et des caract\u00e8res sp\u00e9ciaux tels que ?, &gt;, etc. (De plus, vous pouvez utiliser un service de gestion de mots de passe si vous avez du mal \u00e0 vous souvenir de mots de passe complexes.)\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">De plus, n\u2019utilisez jamais vos mots de passe Magento pour vous connecter \u00e0 un autre site Web. Pour rendre plus difficile la recherche de votre mot de passe par les pirates informatiques, conservez votre mot de passe Magento s\u00e9par\u00e9 de vos autres applications.<\/span><\/p><h3><b>Combler les failles du courrier \u00e9lectronique<\/b><\/h3><p><span style=\"font-weight: 400;\">Avec Magento, les utilisateurs peuvent r\u00e9cup\u00e9rer leurs mots de passe via une adresse email pr\u00e9configur\u00e9e. Dans le cas o\u00f9 votre identifiant de messagerie est pirat\u00e9, l&#039;ensemble de votre boutique Magento devient vuln\u00e9rable. Magento n\u00e9cessite une authentification \u00e0 deux facteurs pour votre adresse e-mail et ne doit pas \u00eatre connue publiquement.<\/span><\/p><h3><b>H\u00e9bergez votre site Web avec un bon plan<\/b><\/h3><p><span style=\"font-weight: 400;\">Pour toute entreprise de commerce \u00e9lectronique, l\u2019h\u00e9bergement partag\u00e9 n\u2019est pas une bonne option.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0L&#039;h\u00e9bergement partag\u00e9 est g\u00e9n\u00e9ralement une bonne option pour les startups Magento, mais investir dans l&#039;h\u00e9bergement partag\u00e9 compromet la s\u00e9curit\u00e9 de votre boutique Magento.<\/span><\/p><p><span style=\"font-weight: 400;\">You may also consider <a href=\"https:\/\/ultahost.com\/dedicated-hosting\" target=\"_blank\" rel=\"noopener\">dedicated hosting<\/a>, but it may not be sufficient for your needs since you will be restricted to a single server. When your Magento store traffic spikes suddenly, the website will crash due to a lack of resources.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous devriez plut\u00f4t choisir un fournisseur d\u2019h\u00e9bergement cloud g\u00e9r\u00e9 qui offre une s\u00e9curit\u00e9 robuste et des correctifs de serveur fr\u00e9quents.<\/span><\/p><p><span style=\"font-weight: 400;\">Les plans d&#039;h\u00e9bergement \u00e0 la douzaine promettent des fonctionnalit\u00e9s qu&#039;ils ne peuvent pas offrir (du moins pas \u00e0 bas prix). Vous devriez rester \u00e0 l\u2019\u00e9cart de tels plans, car ils ne connaissent rien \u00e0 la s\u00e9curit\u00e9 de Magento.<\/span><\/p><h3><b>Emp\u00eacher l&#039;injection MySQL<\/b><\/h3><p><span style=\"font-weight: 400;\">Les versions et correctifs les plus r\u00e9cents de Magento offrent une excellente protection contre les attaques par injection MySQL, mais s&#039;appuyer uniquement sur eux n&#039;est pas toujours optimal. Afin de prot\u00e9ger votre site Web et vos clients, nous vous recommandons d&#039;ajouter un pare-feu d&#039;application Web, tel que NAXSI. Il est \u00e9galement possible d&#039;appliquer des correctifs de s\u00e9curit\u00e9 fournis par les d\u00e9veloppeurs officiels de Magento 2.<\/span><\/p><h3><b>Obtenez un examen de s\u00e9curit\u00e9 Magento<\/b><\/h3><p><span style=\"font-weight: 400;\">Il n\u2019est pas n\u00e9cessaire que les d\u00e9veloppeurs Magento soient des experts en s\u00e9curit\u00e9.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0De nombreuses personnes sont dou\u00e9es pour le codage, mais seules quelques-unes savent comment s\u00e9curiser les sites Magento. Pour cette raison, vous devriez faire analyser votre site Web une (ou peut-\u00eatre deux) par an pour d\u00e9tecter les failles de s\u00e9curit\u00e9.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">The Magento 2 security scan includes checking the site, plugins, and extensions installed on it.\u00a0 In case of security flaws, bugs, or loopholes, Magento 2 security patches should be obtained from a reliable security firm. It is possible for these reviews to help further harden the security of your Magento store if they are done properly.<\/span><\/p><h3><b>Entrez en contact avec la communaut\u00e9 Magento<\/b><\/h3><p><span style=\"font-weight: 400;\">Si vous avez besoin d&#039;aide, la communaut\u00e9 technique de Magento est toujours l\u00e0 pour vous aider. Si vous souhaitez publier une requ\u00eate concernant des probl\u00e8mes de s\u00e9curit\u00e9 li\u00e9s \u00e0 Magento ou \u00e0 ses fonctionnalit\u00e9s, vous pouvez la rechercher et la publier. Diff\u00e9rentes versions de Magento sont \u00e9galement publi\u00e9es par les membres de la communaut\u00e9 Magento, alors gardez \u00e9galement un \u0153il sur celles-ci.<\/span><\/p><h3><b>Ajouter une cl\u00e9 de s\u00e9curit\u00e9 au panneau d&#039;administration de Magento<\/b><\/h3><p><span style=\"font-weight: 400;\">La plateforme de commerce \u00e9lectronique Magento 2 vous permet d&#039;ajouter facilement une cl\u00e9 secr\u00e8te aux URL. De plus, la cl\u00e9 emp\u00eache les oreilles indiscr\u00e8tes\/pirates d\u2019acc\u00e9der au panneau d\u2019administration.<\/span><\/p><p><span style=\"font-weight: 400;\">Le temps d&#039;inactivit\u00e9 du clavier peut \u00e9galement \u00eatre ajout\u00e9 comme mesure pour am\u00e9liorer la s\u00e9curit\u00e9 de Magento 2. En faisant cela, la session expirera et l&#039;administrateur pourra \u00e0 nouveau acc\u00e9der au panneau d&#039;administration.\u00a0<\/span><\/p><h2><b>Conclusion<\/b><\/h2><p><span style=\"font-weight: 400;\">Nous vivons dans un monde en constante \u00e9volution en mati\u00e8re de s\u00e9curit\u00e9. Rien ne garantit que Magento sera totalement s\u00e9curis\u00e9. Cependant, si ces \u00e9tapes \u00e9taient suivies, les pirates informatiques ou les violations seraient consid\u00e9rablement moins susceptibles de se produire. <a href=\"https:\/\/www.carmatec.com\/fr_fr\/contactez-nous\/\">Entrer en contact <\/a>avec<\/span>\u00a0notre \u00e9quipe d&#039;assistance experte Magento si vous avez des questions concernant cet article. Embauchez des d\u00e9veloppeurs Magento en Inde pour <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-de-commerce-electronique\/magento\/\">Services de d\u00e9veloppement Magento<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>How to secure your Magento website should be your primary concern when setting up an eCommerce store using Magento. There are some powerful built-in security features in Magento, but you must do something to protect your site against attacks or data loss. Although it is a powerful eCommerce platform with over 250,000 active sites, it [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":35837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,65],"tags":[],"class_list":["post-35826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-magento"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/35826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=35826"}],"version-history":[{"count":3,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/35826\/revisions"}],"predecessor-version":[{"id":50058,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/35826\/revisions\/50058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/35837"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=35826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=35826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=35826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}