{"id":13175,"date":"2018-08-07T16:28:14","date_gmt":"2018-08-07T16:28:14","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=13175"},"modified":"2023-09-28T09:29:18","modified_gmt":"2023-09-28T09:29:18","slug":"comment-lintelligence-artificielle-est-la-nouvelle-electricite","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/fr_fr\/blog\/how-artificial-intelligence-is-the-new-electricity\/","title":{"rendered":"Comment l&#039;intelligence artificielle est la \u00ab nouvelle \u00e9lectricit\u00e9 \u00bb"},"content":{"rendered":"<p>Lorsque Benjamin Franklin a d\u00e9couvert l\u2019\u00e9lectricit\u00e9, personne \u00e0 l\u2019\u00e9poque n\u2019aurait pr\u00e9dit la transformation r\u00e9volutionnaire qu\u2019elle apporterait \u00e0 chacun. Cet \u00e9v\u00e9nement capital a laiss\u00e9 sa marque dans la longue histoire de l\u2019humanit\u00e9. La prochaine grande avanc\u00e9e est d\u00e9j\u00e0 en train de transformer de nombreuses industries. L\u2019IA nous fascine depuis des si\u00e8cles et s\u2019est impos\u00e9e comme un th\u00e8me r\u00e9current des films de science-fiction au cours des derni\u00e8res d\u00e9cennies. Aujourd\u2019hui, l\u2019IA r\u00e9volutionne le secteur du commerce \u00e9lectronique et a non seulement am\u00e9lior\u00e9 l\u2019exp\u00e9rience client, mais a \u00e9galement fait grimper en fl\u00e8che les b\u00e9n\u00e9fices d\u2019entreprises comme eBay et Target.<\/p>\n<h2>Comment l\u2019IA peut conduire \u00e0 des exp\u00e9riences client plus rentables<\/h2>\n<h4>1) L&#039;IA pour offrir une meilleure exp\u00e9rience utilisateur dans le commerce \u00e9lectronique<\/h4>\n<p>Sur le march\u00e9 du commerce \u00e9lectronique, les grands acteurs tels qu&#039;Amazon, Flipkart, eBay et Snapdeal adoptent l&#039;IA pour mieux r\u00e9pondre aux besoins de leurs clients. Le d\u00e9taillant Target s&#039;est associ\u00e9 \u00e0 Pinterest pour utiliser l&#039;outil de recherche visuelle de ce dernier dans son application et ses sites Web. Cela permettra aux clients de Target de cliquer sur le produit de leur choix et de trouver des produits similaires dans le magasin. Ainsi, le client, m\u00eame sans conna\u00eetre le nom du produit, pourrait le rechercher avec des images prises dans son smartphone lors d&#039;une visite dans un pays \u00e9tranger. LensKart en Inde a \u00e9galement exploit\u00e9 la puissance de l&#039;IA en permettant aux clients d&#039;essayer diff\u00e9rentes nuances dans leur magasin sans \u00eatre physiquement en magasin, les aidant ainsi \u00e0 choisir les meilleures qui accentuent leur personnalit\u00e9 tout en faisant leurs achats dans le confort de leur foyer.<\/p>\n<h4>2) L&#039;IA pour fournir de meilleurs services \u00e0 moindre co\u00fbt<\/h4>\n<p>Les co\u00fbts administratifs dans le secteur de la sant\u00e9 et dans de nombreux secteurs augmentent de fa\u00e7on exponentielle et les experts du secteur pr\u00e9disent que l\u2019intelligence artificielle peut aider \u00e0 les r\u00e9duire. Il a d\u00e9j\u00e0 fait de grands progr\u00e8s en traitant les rayons X et en d\u00e9tectant efficacement les cellules canc\u00e9reuses. Les chatbots, par exemple, peuvent aider les entreprises \u00e0 \u00e9conomiser sur les co\u00fbts du service client en\u00a0:<\/p>\n<ul>\n<li>Acc\u00e9l\u00e9rer les temps de r\u00e9ponse<\/li>\n<li>Lib\u00e9rer les agents pour qu\u2019ils puissent effectuer un travail plus exigeant<\/li>\n<li>R\u00e9pondre \u00e0 jusqu&#039;\u00e0 70% des questions de routine<\/li>\n<\/ul>\n<p>Non seulement cela pourrait conduire \u00e0 des r\u00e9ductions de co\u00fbts allant jusqu\u2019\u00e0 30%, mais cela pourrait \u00e9galement contribuer \u00e0 adopter une approche commerciale plut\u00f4t centr\u00e9e sur le client.<\/p>\n<h4>3) L&#039;IA pour optimiser les recherches et les recommandations des clients<\/h4>\n<p>Certaines strat\u00e9gies bas\u00e9es sur l&#039;IA, telles que la recherche visuelle et les recommandations, rapportent des r\u00e9compenses sans pr\u00e9c\u00e9dent aux marques et aux d\u00e9taillants, car elles les aident \u00e0 trouver les produits qu&#039;ils ont en t\u00eate et, ainsi, \u00e0 augmenter les conversions. Go Find, par exemple, invite ses utilisateurs \u00e0 t\u00e9l\u00e9charger une image, sur la base de laquelle il renvoie des r\u00e9sultats similaires, notamment les fourchettes de prix et les magasins (en ligne). Echo Look d&#039;Amazon utilise une cam\u00e9ra combin\u00e9e \u00e0 l&#039;intelligence artificielle pour devenir votre assistant personnel qui vous recommande le look qui vous convient le mieux.<\/p>\n<h4>4) L&#039;IA pour g\u00e9n\u00e9rer des ventes gr\u00e2ce \u00e0 la technologie portable<\/h4>\n<p>La technologie bas\u00e9e sur l&#039;IA a am\u00e9lior\u00e9 les capacit\u00e9s des appareils portables et, selon les statistiques, environ 115 millions d&#039;appareils portables ont \u00e9t\u00e9 exp\u00e9di\u00e9s rien qu&#039;en 2017. Les principaux acteurs du march\u00e9 comme Xiaomi, Fitbit, Garmin, Huawei et Apple ont \u00e9quip\u00e9 leurs produits d&#039;assistants personnalis\u00e9s qui aident les utilisateurs \u00e0 exceller dans des t\u00e2ches sp\u00e9cifiques.<\/p>\n<p>D\u2019une mani\u00e8re que nous n\u2019imaginons peut-\u00eatre pas, l\u2019IA fa\u00e7onne d\u00e9finitivement nos vies. Il joue \u00e9galement un r\u00f4le dans notre prise de d\u00e9cision. En particulier, sa capacit\u00e9 \u00e0 s\u2019auto-apprendre et \u00e0 am\u00e9liorer les performances d\u2019une t\u00e2che \u00e0 accomplir au fil du temps est la merveille technologique que nous attendions tous depuis toutes ces ann\u00e9es. Pour conclure, je dirais qu&#039;il est l\u00e0 pour rester et pour de bon !<\/p>\n<p>Avec plus de 16 ans d&#039;expertise dans l&#039;industrie informatique, <a href=\"https:\/\/www.carmatec.com\/fr_fr\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Carmatec<\/strong><\/a> rassemble un ensemble de comp\u00e9tences multiformes dans les domaines du design, des sciences du comportement, de l&#039;utilisabilit\u00e9, de l&#039;analyse, du marketing et de la cr\u00e9ation de marque pour fournir aux entreprises des solutions globales pour <a href=\"https:\/\/www.carmatec.com\/fr_fr\/services-dintelligence-artificielle\/\">Services d&#039;intelligence artificielle<\/a>, <a href=\"https:\/\/www.carmatec.com\/fr_fr\/services-de-conception-de-sites-web\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Cr\u00e9ation de sites web<\/strong><\/a>, La toile &amp; <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-dapplications-mobiles\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>D\u00e9veloppement mobile<\/strong><\/a>, Gestion de l&#039;infrastructure informatique \u00e0 distance, d\u00e9veloppement de logiciels, services informatiques g\u00e9r\u00e9s, conseil cloud, marketing Internet et image de marque.<\/p>\n<p><strong>Lire aussi<\/strong> :\u00a0<a href=\"https:\/\/www.carmatec.com\/fr_fr\/apprendre-la-technologie\/lentreprise-a-besoin-du-developpement-dapplications-web-personnalisees\/\">Pourquoi votre entreprise a besoin du d\u00e9veloppement d&#039;applications Web personnalis\u00e9es<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>When Benjamin Franklin discovered electricity, no one at that time would have predicted the revolutionary transformation it would bring in everyone\u2019s life. The momentous event has etched its mark in the long history of humanity. The next big thing is already transforming many industries. AI has fascinated us for centuries and has made its place [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29225,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,4,10],"tags":[],"class_list":["post-13175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artificial-intelligence","category-blog","category-learn-technology"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/13175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=13175"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/13175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/29225"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=13175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=13175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=13175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}