{"id":1284,"date":"2014-08-26T15:35:07","date_gmt":"2014-08-26T10:05:07","guid":{"rendered":"http:\/\/carmatec.com\/?p=1284"},"modified":"2022-08-18T14:03:57","modified_gmt":"2022-08-18T14:03:57","slug":"gerer-un-client-abusif","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/fr_fr\/management\/handle-abusive-customer\/","title":{"rendered":"Comment g\u00e9rer un client abusif"},"content":{"rendered":"<p style=\"text-align: justify;\">Si vous avez d\u00e9j\u00e0 travaill\u00e9 dans le service d&#039;assistance (t\u00e9l\u00e9phone, e-mail, chat, etc.), le plus souvent, vous aurez peut-\u00eatre rencontr\u00e9 un client abusif \u00e0 un moment donn\u00e9. Comment g\u00e9reriez-vous une telle situation ? Crier en retour ? Interrompre brusquement la conversation\u00a0? Laisser simplement le client continuer \u00e0 d\u00e9nigrer ? G\u00e9rer un client abusif est une comp\u00e9tence en soi.<br \/>\nEh bien, voici quelques conseils sur lesquels nous formons nos techniciens pour faire face \u00e0 de tels sc\u00e9narios\u00a0:<\/p>\n<p style=\"text-align: justify;\"><strong>* Comprendre la situation<\/strong><\/p>\n<p style=\"text-align: justify;\">N&#039;interrompez pas imm\u00e9diatement la conversation. Parlez au client et essayez de comprendre la situation. Par exemple, il pourrait \u00eatre frustr\u00e9 parce qu\u2019on lui a donn\u00e9 des coups de pied sans que le probl\u00e8me soit r\u00e9solu. Un autre sc\u00e9nario est qu\u2019il n\u2019a pas de v\u00e9ritable probl\u00e8me. Au lieu de cela, il vous harc\u00e8le juste pour le plaisir ou peut-\u00eatre est-il ivre. Pour comprendre le probl\u00e8me exact, vous devez parler.<\/p>\n<p style=\"text-align: justify;\"><strong>* N&#039;utilisez pas de scripts<\/strong><\/p>\n<p style=\"text-align: justify;\">Au lieu d&#039;utiliser des scripts qui pourraient irriter davantage le client, essayez d&#039;ajouter une touche personnelle \u00e0 la conversation. S&#039;adresser au client par son nom et lui faire savoir que vous souhaitez l&#039;aider sont quelques moyens d&#039;y parvenir.<\/p>\n<p style=\"text-align: justify;\"><strong>* Garder votre calme<\/strong><\/p>\n<p style=\"text-align: justify;\">N&#039;oubliez pas que le client n&#039;est pas en col\u00e8re contre vous mais contre la situation. Ne le prends pas personnellement. Si vous avez pass\u00e9 une mauvaise journ\u00e9e, essayez quelques techniques de gestion du stress. En comptant de 1 \u00e0 10, garder une photo de votre proche sur votre bureau est un moyen de r\u00e9duire le stress. Si rien ne fonctionne et que vous devez exprimer vos sentiments, mettez l&#039;appel en mode \u00ab\u00a0muet\u00a0\u00bb et \u00e9liminez votre frustration. Et s&#039;il s&#039;agit d&#039;un e-mail\/d&#039;un chat, vous n&#039;avez m\u00eame pas \u00e0 vous en soucier \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\"><strong>* Transmettez votre intention et vos limites<\/strong><\/p>\n<p style=\"text-align: justify;\">Faites savoir au client que votre intention est de l\u2019aider et que pour que vous y parveniez, il doit coop\u00e9rer. Vous et votre entreprise souhaitez le satisfaire. Si cela ne sert \u00e0 rien, faites-lui savoir qu&#039;il vous est difficile de poursuivre la conversation. Rappelez-lui vos limites.<\/p>\n<p style=\"text-align: justify;\"><strong>* Transf\u00e9rez-le \u00e0 une autre personne<\/strong><\/p>\n<p style=\"text-align: justify;\">Si les choses deviennent incontr\u00f4lables, faites-le-lui savoir et transf\u00e9rez l&#039;appel\/le chat \u00e0 votre superviseur ou coll\u00e8gue. Cela lui laisserait peu de temps pour se regrouper et il y a toutes les chances qu&#039;il se comporte bien lorsqu&#039;il parle \u00e0 la personne suivante. S&#039;il s&#039;agit d&#039;un e-mail, vous pouvez toujours le transf\u00e9rer.<\/p>\n<p style=\"text-align: justify;\"><strong>* Arr\u00eatez la conversation<\/strong><\/p>\n<p style=\"text-align: justify;\">S&#039;il n&#039;y a personne \u00e0 qui transf\u00e9rer ou si vous \u00eates la personne qui s&#039;occupe de la session transf\u00e9r\u00e9e, indiquez clairement une fois de plus que vous \u00eates l\u00e0 pour l&#039;aider. S&#039;il ne coop\u00e8re toujours pas, plut\u00f4t que d&#039;\u00eatre impoli, faites-lui savoir que ce genre de comportement est inacceptable. R\u00e9it\u00e9rez la politique de votre entreprise concernant les abus envers les employ\u00e9s et interrompez la session.<\/p>","protected":false},"excerpt":{"rendered":"<p>If you have ever been working in the support department (phone,email,chat etc) then more often than not, you might have come across an abusive customer at some point. How would you deal with such a situation ? Yell back ? Discontinue the conversation abruptly? Just let the customer continue bashing ? Handling an abusive customer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}