{"id":35224,"date":"2023-03-10T06:21:07","date_gmt":"2023-03-10T06:21:07","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=portfolio&#038;p=35224"},"modified":"2023-04-04T12:41:37","modified_gmt":"2023-04-04T12:41:37","slug":"1000-pharmacies","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/fr_fr\/portfolio\/1000-farmacie\/","title":{"rendered":"1000 pharmacies"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1600\" height=\"500\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie.jpg\" alt=\"\" class=\"wp-image-35225\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie.jpg 1600w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie-18x6.jpg 18w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie-400x125.jpg 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-1000-Farmacie-1536x480.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Description du projet<\/h3>\n\n\n\n<p>1000 Farmacie est un march\u00e9 pharmaceutique financ\u00e9 comme 1mg permettant aux utilisateurs d&#039;acheter des m\u00e9dicaments, de commander dans leurs magasins et de recevoir des produits directement \u00e0 leur domicile. La vision de ce projet est de concevoir et de d\u00e9velopper une application mobile pour Android\/iOS et une API ROR pour 1000 Farmacie, Italie (UE). Le projet comprendra une application mobile destin\u00e9e aux utilisateurs, qui leur permettra de payer en ligne leurs produits pharmaceutiques. Les applications mobiles auront les listes de produits et les cat\u00e9gories de produits qui seront g\u00e9r\u00e9es par l&#039;administrateur dans le backend (syst\u00e8me existant). Le <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-dapplications-mobiles\/developpement-dapplication-ios\/\">IOS <\/a>et <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-dapplications-mobiles\/developpement-dapplications-android\/\">Android<\/a> Les performances, la fiabilit\u00e9, la s\u00e9curit\u00e9 et la disponibilit\u00e9 des applications mobiles seront les \u00e9l\u00e9ments essentiels du d\u00e9veloppement. Les applications mobiles seront cr\u00e9\u00e9es \u00e0 l\u2019aide des meilleures et derni\u00e8res piles de technologies mobiles disponibles.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Caract\u00e9ristiques<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Processus d&#039;inscription facile et simple avec inscription par e-mail et sur les r\u00e9seaux sociaux.&nbsp;<\/li>\n\n\n\n<li>Des notifications push qui am\u00e9liorent l&#039;engagement du client en l&#039;informant des promotions, des offres et des remises sp\u00e9ciales.&nbsp;<\/li>\n\n\n\n<li>Les clients pourront consulter, acheter et effectuer des paiements pour les produits pharmaceutiques sur les deux plateformes mobiles.&nbsp;<\/li>\n\n\n\n<li>Les utilisateurs pourront donner leur avis sur les produits.<\/li>\n\n\n\n<li>Il disposera d\u2019une option de passerelle de paiement en ligne et d\u2019une fonctionnalit\u00e9 de notification par SMS pour les commandes et les transactions.&nbsp;<\/li>\n\n\n\n<li>Des banni\u00e8res et des fonctionnalit\u00e9s de r\u00e9duction sur les produits seront disponibles pour les clients \u00e0 des fins marketing et saisonni\u00e8res.<\/li>\n\n\n\n<li>Deux langues diff\u00e9rentes, anglais et italien, pour l&#039;application mobile au profit des clients et selon les exigences du march\u00e9.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"905\" height=\"721\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/m1000-Farmacie.png\" alt=\"\" class=\"wp-image-35349\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/m1000-Farmacie.png 905w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/m1000-Farmacie-300x239.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/m1000-Farmacie-768x612.png 768w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"833\" height=\"476\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-1000-Farmacie.png\" alt=\"\" class=\"wp-image-35747\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-1000-Farmacie.png 833w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-1000-Farmacie-300x171.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-1000-Farmacie-768x439.png 768w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Solution propos\u00e9e<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Arriver \u00e0 un niveau de compr\u00e9hension de la vision propos\u00e9e, <a href=\"https:\/\/www.carmatec.com\/fr_fr\/\">Carmatec<\/a> a analys\u00e9 la faisabilit\u00e9 et les r\u00e9sultats attendus en proposant ainsi de d\u00e9velopper une plateforme exclusive qui touchera le march\u00e9 en proposant une application mobile intuitive sous Android\/iOS et une API ROR pour 1000 pharmacies en Italie. L&#039;application permettra aux utilisateurs finaux d&#039;acheter des produits pharmaceutiques et d&#039;effectuer des paiements en ligne. Un administrateur g\u00e9rera les listes de produits et les cat\u00e9gories dans le backend du syst\u00e8me existant. Le d\u00e9veloppement se concentrera sur les performances, la fiabilit\u00e9, la s\u00e9curit\u00e9 et la disponibilit\u00e9 des <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-dapplications-mobiles\/\">Applications mobiles<\/a>, en utilisant les derni\u00e8res piles de technologies mobiles.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Technologie<\/h3>\n\n\n\n<p>Application mobile dans <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-dapplications-natives-react\/\">R\u00e9agir natif<\/a>, API backend et site Web sur Ruby on Rails, AWS ElasticSearch, int\u00e9grations avec Clark.io, Zendesk et de nombreux autres services tiers<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>1000 Farmacie est un march\u00e9 pharmaceutique financ\u00e9 comme 1mg permettant aux utilisateurs d&#039;acheter des m\u00e9dicaments, de commander dans leurs magasins et de recevoir des produits directement \u00e0 leur domicile. <\/p>","protected":false},"author":2,"featured_media":35225,"template":"","portfolio_categories":[26,28,33],"class_list":["post-35224","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce","portfolio_categories-health-care","portfolio_categories-mobile"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio\/35224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/35225"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=35224"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio_categories?post=35224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}