{"id":35167,"date":"2023-03-15T10:02:30","date_gmt":"2023-03-15T10:02:30","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=portfolio&#038;p=35167"},"modified":"2023-04-04T12:42:04","modified_gmt":"2023-04-04T12:42:04","slug":"point-de-chai","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/fr_fr\/portfolio\/chaipoint\/","title":{"rendered":"Point Chai"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1600\" height=\"500\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint.jpg\" alt=\"\" class=\"wp-image-35171\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint.jpg 1600w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint-18x6.jpg 18w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint-400x125.jpg 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/02\/desk-screen-chaipoint-1536x480.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Description du projet<\/strong><\/h3>\n\n\n\n<p>Chai Point est une soci\u00e9t\u00e9 indienne de th\u00e9 et une cha\u00eene de caf\u00e9s qui se concentre sur les boissons \u00e0 base de th\u00e9 o\u00f9 les utilisateurs peuvent voir et commander les produits Chai Point et effectuer un achat en ligne dans le magasin le plus proche. La vision de ce projet est de repenser et de d\u00e9velopper un site Web Front-End de commerce \u00e9lectronique ReactJS (commande et boutique) pour la marque Chai Point. Le projet comprend une refonte du site Web de la marque, une consolidation des marques Chai Point \u00e0 long terme pour les utilisateurs finaux, et avec l&#039;aide du site Web, les utilisateurs peuvent visualiser et commander les produits Chai Point et faire un achat en ligne dans le magasin le plus proche.<\/p>\n\n\n\n<p>L&#039;objectif principal de ce projet est de fournir une exp\u00e9rience en ligne transparente aux clients de Chai Point, en pr\u00e9sentant l&#039;histoire de leur marque et leurs produits dans une interface facile \u00e0 utiliser. Le site Web proposera \u00e0 la fois des fonctionnalit\u00e9s de commande sur le Web et sur WhatsApp, offrant ainsi aux clients un moyen pratique et efficace de commander leurs produits pr\u00e9f\u00e9r\u00e9s chez Chai Point.<\/p>\n\n\n\n<p>Le site Web comprendra \u00e9galement un panneau d&#039;administration pour g\u00e9rer les pages CMS et d&#039;autres services dans le backend, offrant un acc\u00e8s facile et s\u00e9curis\u00e9 aux administrateurs pour g\u00e9rer le site Web et les commandes des clients.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h3 class=\"wp-block-heading\"><strong>Caract\u00e9ristiques<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Processus d&#039;inscription rationalis\u00e9, convivial et facile \u00e0 compl\u00e9ter<\/li>\n\n\n\n<li>Interface belle et conviviale avec un flux de travail clair et logique<\/li>\n\n\n\n<li>Possibilit\u00e9 d&#039;appliquer des coupons et des offres promotionnelles pour un engagement client accru<\/li>\n\n\n\n<li>Titres de r\u00e9f\u00e9rencement dynamique pour am\u00e9liorer le classement et la visibilit\u00e9 dans les moteurs de recherche<\/li>\n\n\n\n<li>Ic\u00f4ne WhatsApp flottante pour une commande en ligne et un support client pratiques<\/li>\n\n\n\n<li>Int\u00e9gration avec Google Analytics pour un suivi et une analyse d\u00e9taill\u00e9s du comportement des utilisateurs<\/li>\n\n\n\n<li>Int\u00e9gration transparente avec les passerelles de paiement, les services de localisation GPS, les passerelles SMS et les notifications push<\/li>\n\n\n\n<li>Possibilit\u00e9 de reth\u00e8me et d&#039;int\u00e9gration avec les blogs WordPress pour une gestion facile du contenu<\/li>\n\n\n\n<li>Int\u00e9gration avec les plateformes de m\u00e9dias sociaux pour un engagement et une notori\u00e9t\u00e9 accrus de la marque<\/li>\n\n\n\n<li>Int\u00e9gration avec les sites Web de commerce \u00e9lectronique VAAS et DTDC pour un traitement et une ex\u00e9cution transparents des commandes<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"905\" height=\"721\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mchaipoint.png\" alt=\"\" class=\"wp-image-35343\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mchaipoint.png 905w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mchaipoint-300x239.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mchaipoint-768x612.png 768w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Solution propos\u00e9e<\/strong><\/h3>\n\n\n\n<p>Arriver \u00e0 un niveau de compr\u00e9hension de la vision propos\u00e9e, <a href=\"https:\/\/www.carmatec.com\/fr_fr\/\">Carmatec<\/a> a analys\u00e9 la faisabilit\u00e9 et les r\u00e9sultats anticip\u00e9s en proposant ainsi de d\u00e9velopper une plateforme exclusive qui permettra de toucher le march\u00e9 en offrant une interface intuitive. <a href=\"https:\/\/www.carmatec.com\/fr_fr\/societe-de-developpement-de-commerce-electronique\/\">Site Web de commerce \u00e9lectronique<\/a> Administrateur Front-End et CMS.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"833\" height=\"476\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-chaipoint.png\" alt=\"\" class=\"wp-image-35737\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-chaipoint.png 833w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-chaipoint-300x171.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-chaipoint-768x439.png 768w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>ARCHITECTURE<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pile de services distribu\u00e9s sur AWS<\/li>\n\n\n\n<li>\u00c9volutif, \u00e9quilibr\u00e9 en charge et flexible pour l&#039;\u00e9volutivit\u00e9<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>PLATEFORMES PRISES EN CHARGE<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tous les syst\u00e8mes d&#039;exploitation standards<\/li>\n\n\n\n<li>Front-end du site Web React JS (COMMANDE ET ACHETER)<\/li>\n\n\n\n<li>ADMINISTRATEUR DU CMS CakePHP<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Les parties prenantes du Site Internet sont :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Clients<\/li>\n\n\n\n<li>Administrateur<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>ADMINISTRATEUR<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>G\u00e9rer les pages CMS<\/li>\n\n\n\n<li>Liste d&#039;abonnement \u00e0 la newsletter<\/li>\n\n\n\n<li>G\u00e9rer les FAQ<\/li>\n\n\n\n<li>G\u00e9rer l&#039;offre d&#039;emploi<\/li>\n\n\n\n<li>G\u00e9rer les blogs<\/li>\n\n\n\n<li>G\u00e9rer les marques et les URL<\/li>\n\n\n\n<li>G\u00e9rer les utilisateurs et les r\u00f4les<\/li>\n\n\n\n<li>G\u00e9rer les clients<\/li>\n\n\n\n<li>G\u00e9rer les param\u00e8tres frontaux du site<\/li>\n\n\n\n<li>G\u00e9rer les avis et les notes<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Technologie<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/www.carmatec.com\/fr_fr\/developpement-de-reaction\/\">R\u00e9agirJS<\/a>, Cake PHP, base de donn\u00e9es Mysql, UI\/UX et HTML\/CSS<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Chai Point est une soci\u00e9t\u00e9 indienne de th\u00e9 et une cha\u00eene de caf\u00e9s qui se concentre sur les boissons \u00e0 base de th\u00e9 o\u00f9 les utilisateurs peuvent voir et commander les produits Chai Point et effectuer un achat en ligne dans le magasin le plus proche. <\/p>","protected":false},"author":2,"featured_media":35171,"template":"","portfolio_categories":[26,36],"class_list":["post-35167","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce","portfolio_categories-web-design"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio\/35167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/35171"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=35167"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio_categories?post=35167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}