{"id":2568,"date":"2015-03-07T06:48:24","date_gmt":"2015-03-07T01:18:24","guid":{"rendered":"http:\/\/\/?post_type=project&#038;p=2568"},"modified":"2022-09-27T16:28:21","modified_gmt":"2022-09-27T16:28:21","slug":"groupofis","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/fr_fr\/portfolio\/groupofis\/","title":{"rendered":"GroupeOfis"},"content":{"rendered":"<p><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/grp-office.png\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8920\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/grp-office.png\" alt=\"grp-bureau\" width=\"1600\" height=\"500\"><\/a><\/p>\n<h3 class=\"common_sub_head\">Description du projet<\/h3>\n<p class=\"projectdesccommon\" style=\"text-align: justify;\">Le projet Workflow est le premier du genre \u00e0 attribuer des t\u00e2ches aux utilisateurs par administrateur. Un flux de travail se compose d&#039;un nombre variable de n\u0153uds interconnect\u00e9s les uns aux autres. L&#039;administrateur cr\u00e9e l&#039;arborescence du flux de travail en choisissant diff\u00e9rents types de n\u0153uds. Cr\u00e9ation de t\u00e2ches hi\u00e9rarchiques et affectation \u00e0 l&#039;utilisateur. Les modules couverts par l&#039;application sont les modules de gestion des utilisateurs, de gestion des r\u00f4les et de gestion des vacances et des vacances.<\/p>\n<h3 class=\"common_sub_head\">Caract\u00e9ristiques<\/h3>\n<p class=\"projectdesccommon\">1. Configuration de la base de donn\u00e9es.<br \/>\n2. Interactions avec plusieurs bases de donn\u00e9es.<br \/>\n3. \u00c9diteur JavaScript et AJAX.<br \/>\n4. Traduction linguistique pour les donn\u00e9es dynamiques.<\/p>\n<h3 class=\"iconimage\">&nbsp;D\u00e9ploiement<\/h3>\n<p>Ceci est d\u00e9ploy\u00e9 sur des serveurs cloud haute disponibilit\u00e9 et s\u00e9curis\u00e9s.<\/p>\n<h3>Dur\u00e9e du projet<\/h3>\n<p>4 mois<\/p>","protected":false},"excerpt":{"rendered":"<p>Project Description Workflow project is first of its kind, to allot tasks to users by admin. A workflow consists of various number of nodes inter-connected to each other. The admin creates the work flow tree by choosing different types of nodes. Hierarchical tasks creation and assignment to user. Modules covered in the application are User [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28453,"template":"","portfolio_categories":[35],"class_list":["post-2568","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/28453"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=2568"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio_categories?post=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}