{"id":17853,"date":"2020-05-01T01:05:42","date_gmt":"2020-04-30T19:35:42","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=project&#038;p=17853"},"modified":"2023-04-04T12:52:04","modified_gmt":"2023-04-04T12:52:04","slug":"agregateur-dassurance-amana","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/fr_fr\/portfolio\/amana-insurance-aggregator\/","title":{"rendered":"Agr\u00e9gateur d\u2019assurance Amana"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"320\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/amana-banner-1024x320.jpg\" alt=\"\" class=\"wp-image-28350\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/amana-banner-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/amana-banner-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/amana-banner-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/amana-banner-1536x480.jpg 1536w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/amana-banner.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h3><strong>Description du projet<\/strong><\/h3>\n<p>Amana Qatar est l&#039;un des principaux courtiers d&#039;assurance au Qatar, proposant une gamme de solutions d&#039;assurance aux particuliers et aux entreprises. La vision de ce projet \u00e9tait de cr\u00e9er un site Web d&#039;agr\u00e9gateur d&#039;assurance et une application mobile pour Amana Insurance Broker Qatar avec un support en 2 langues, dont l&#039;arabe. L&#039;application permettrait aux utilisateurs finaux de rechercher et de souscrire des assurances pour un large \u00e9ventail de cat\u00e9gories en quelques minutes.<\/p>\n<h3><strong>Caract\u00e9ristiques<\/strong><\/h3>\n<ul>\n<li>Connexion et authentification<\/li>\n<li>Dans une page de destination, l&#039;utilisateur dispose de tous les types de polices de v\u00e9hicules assur\u00e9s.<\/li>\n<li>Les prestataires d&#039;assurance \u00e9taient li\u00e9s au syst\u00e8me et, par cons\u00e9quent, les politiques telles que les d\u00e9tails actifs et renouvel\u00e9s \u00e9taient disponibles pour que les utilisateurs puissent les v\u00e9rifier.<\/li>\n<\/ul>\n<h3><strong>Technologie<\/strong><\/h3>\n<p>Android, iOS, base de donn\u00e9es SQLite, backend \u2013 Ruby On Rails<\/p>","protected":false},"excerpt":{"rendered":"<p>Amana Qatar est l&#039;un des principaux courtiers d&#039;assurance au Qatar, proposant une gamme de solutions d&#039;assurance aux particuliers et aux entreprises.<\/p>","protected":false},"author":2,"featured_media":28338,"template":"","portfolio_categories":[30,33],"class_list":["post-17853","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-insurance","portfolio_categories-mobile"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio\/17853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/28338"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=17853"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/portfolio_categories?post=17853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}