{"id":26828,"date":"2022-02-18T06:19:38","date_gmt":"2022-02-18T06:19:38","guid":{"rendered":"https:\/\/new.carmatec.com\/?post_type=casestudy&#038;p=26828"},"modified":"2023-09-28T08:57:02","modified_gmt":"2023-09-28T08:57:02","slug":"application-mobile-de-commerce-electronique-native-avec-lapi-word-press-rest","status":"publish","type":"casestudy","link":"https:\/\/www.carmatec.com\/fr_fr\/casestudy\/native-ecommerce-mobile-app-withword-press-rest-api\/","title":{"rendered":"Application mobile de commerce \u00e9lectronique native avec l&#039;API WordPress Rest"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26828\" class=\"elementor elementor-26828\" data-elementor-post-type=\"casestudy\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edc9968 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc9968\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88460ed\" data-id=\"88460ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2f5178 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a2f5178\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e92733\" data-id=\"0e92733\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0b70d elementor-widget elementor-widget-lae-heading\" data-id=\"9c0b70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Pays<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6000696 elementor-widget elementor-widget-text-editor\" data-id=\"6000696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tInde\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b856e0c\" data-id=\"b856e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee0bc6 elementor-widget elementor-widget-lae-heading\" data-id=\"1ee0bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Industrie<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af1b901 elementor-widget elementor-widget-text-editor\" data-id=\"af1b901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>commerce \u00e9lectronique<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-441399b\" data-id=\"441399b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-333b274 elementor-widget elementor-widget-lae-heading\" data-id=\"333b274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Plate-forme<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1db07 elementor-widget elementor-widget-text-editor\" data-id=\"4c1db07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Mobile<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2731b195 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2731b195\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-532bbb72\" data-id=\"532bbb72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac07876 elementor-widget elementor-widget-lae-heading\" data-id=\"ac07876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-align\" >\n\n    <h3 class=\"lae-title\">Exigence commerciale<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0c8da61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c8da61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f081e4a elementor-invisible\" data-id=\"f081e4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70fef06 elementor-widget elementor-widget-text-editor\" data-id=\"70fef06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le client a contact\u00e9 Carmatec pour lui demander de d\u00e9velopper une application mobile unique pour son site Web WordPress woocommerce existant. Cette application est principalement d\u00e9velopp\u00e9e exclusivement pour une ville en Inde. Elle peut \u00eatre utilis\u00e9e partout dans le monde en configurant les pays et les devises. Vous pouvez r\u00e9pondre \u00e0 tous vos besoins domestiques en un seul clic. Vous pouvez choisir parmi des centaines de produits. L&#039;utilisateur peut choisir l&#039;option de paiement selon sa convenance \u2013 morue ou en ligne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4697937 elementor-invisible\" data-id=\"4697937\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2765b92 elementor-widget elementor-widget-image\" data-id=\"2765b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"488\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg\" class=\"attachment-full size-full wp-image-28118\" alt=\"Objectifs commerciaux 2\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg 800w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-300x183.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-768x468.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c19173b elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c19173b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd4aa0\" data-id=\"0fd4aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7787a9f elementor-widget elementor-widget-lae-heading\" data-id=\"7787a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Objectifs d&#039;affaires<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-091858f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"091858f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b6fa688\" data-id=\"b6fa688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69919a5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"69919a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Commodit\u00e9 \u2013 Les utilisateurs n&#039;ont plus besoin de lutter pour trouver les points de vente et les visiter pour acheter les produits requis. Le monde des applications mobiles est vaste car il offre un acc\u00e8s plus rapide au contenu et des interactions fluides avec les clients. Un client peut commander toutes les courses n\u00e9cessaires \u00e0 l&#039;aide de cette application.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c574a0a elementor-widget elementor-widget-lae-heading\" data-id=\"c574a0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Solution propos\u00e9e<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34ac20e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34ac20e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-685f5df\" data-id=\"685f5df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a93e78 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9a93e78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Carmatec a d\u00e9velopp\u00e9 une application mobile native tout en fournissant diff\u00e9rents syst\u00e8mes pour le client et l&#039;administrateur. L&#039;application mobile fonctionnera en synchronisation avec l&#039;application Web pour offrir une interaction transparente aux utilisateurs. Les clients peuvent t\u00e9l\u00e9charger l&#039;application mobile depuis le Play Store et s&#039;inscrire\/se connecter \u00e0 l&#039;aide du formulaire. Apr\u00e8s s&#039;\u00eatre connect\u00e9 sur la page de destination, l&#039;utilisateur peut consulter la liste des combos, des offres, des offres de produits tendance, etc. Nous avons d\u00e9velopp\u00e9 l&#039;application sur Android et iOS.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d844f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"34d844f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf274af\" data-id=\"cf274af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9161bb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9161bb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b468eb elementor-invisible\" data-id=\"3b468eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f41f7e6 elementor-widget elementor-widget-lae-heading\" data-id=\"f41f7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Caract\u00e9ristiques<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fedc2 elementor-widget elementor-widget-text-editor\" data-id=\"45fedc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Les principales caract\u00e9ristiques de la plateforme et ses capacit\u00e9s sont<\/strong><\/p>\n<ul>\n<li>Combinaisons<\/li>\n<li>Des offres<\/li>\n<li>Produits tendance<\/li>\n<li>Offres<\/li>\n<li>Recherche globale<\/li>\n<li>Chariot<\/li>\n<li>V\u00e9rifier<\/li>\n<li>Passerelle de paiement CCAvenue<\/li>\n<li>Annuler la commande<\/li>\n<li>Commande de retour<\/li>\n<\/ul>\n<p><br \/>L\u2019un des points forts du projet a \u00e9t\u00e9 l\u2019incapacit\u00e9 d\u2019un autre fournisseur \u00e0 cr\u00e9er l\u2019application mobile \u00e0 l\u2019aide de l\u2019API WordPress. On nous a demand\u00e9 de cr\u00e9er l&#039;application mobile en 1 mois. L&#039;\u00e9quipe de d\u00e9veloppement d&#039;applications mobiles termine le projet dans le d\u00e9lai d&#039;un mois stipul\u00e9 tout en g\u00e9rant efficacement le calendrier rigoureux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79ba21a animated-slow elementor-invisible\" data-id=\"79ba21a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0428bb5 elementor-widget elementor-widget-lae-heading\" data-id=\"0428bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Pile technologique<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8290b50 elementor-widget elementor-widget-text-editor\" data-id=\"8290b50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Pile technologique (iOS)<br \/><\/strong><\/p>\n<ul>\n<li>IOS<\/li>\n<li>Objectif c<\/li>\n<li>SDK iOS<\/li>\n<li>Touche Cacao<br \/><br \/><\/li>\n<\/ul>\n<p><strong>Pile technologique (Android)<\/strong><\/p>\n<ul>\n<li>Java<\/li>\n<li>SDK Android<\/li>\n<li>XML<br \/><br \/><\/li>\n<\/ul>\n<p><strong>WordPress\u00a0:<\/strong><\/p>\n<ul>\n<li>API de repos<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":3,"featured_media":37923,"template":"","casestudy_categories":[38,43],"class_list":["post-26828","casestudy","type-casestudy","status-publish","has-post-thumbnail","hentry","casestudy_categories-e-commerce","casestudy_categories-mobile-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/casestudy\/26828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/casestudy"}],"about":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/types\/casestudy"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/casestudy\/26828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media\/37923"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=26828"}],"wp:term":[{"taxonomy":"casestudy_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/fr_fr\/wp-json\/wp\/v2\/casestudy_categories?post=26828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}