{"id":5637,"date":"2016-03-01T17:11:39","date_gmt":"2016-03-01T11:41:39","guid":{"rendered":"http:\/\/carmatec.com\/?p=5637"},"modified":"2022-09-29T11:57:15","modified_gmt":"2022-09-29T11:57:15","slug":"la-guia-para-principiantes-sobre-hashtags","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/es_mx\/learn-technology\/the-beginners-guide-to-hashtags\/","title":{"rendered":"La gu\u00eda para principiantes sobre hashtags"},"content":{"rendered":"<h2>ETIQUETAS<\/h2>\n<p>Ya sea que los ames o los odies, \u00a1los hashtags llegaron para quedarse! Esta tendencia, que apareci\u00f3 en escena con temor en 2007, no ha hecho m\u00e1s que ganar un gran impulso desde entonces y ahora no puedes pasar un d\u00eda en las redes sociales sin encontrarte con hashtags. Hay hashtags divertidos, inspiradores, extra\u00f1os, serios, de tendencia, todo tipo de hashtags y la mejor parte es que cualquiera puede crear un hashtag (#SocialMediaRocks). \u00bfVes lo que hice all\u00ed? \u00a1Todo lo que necesitas es agregar un signo de almohadilla delante de una palabra y se convierte en un hashtag!<\/p>\n<p>Una explicaci\u00f3n simple del hashtag ser\u00eda que es una palabra o grupo de palabras precedidas por un signo de almohadilla (#). No necesitas experiencia en codificaci\u00f3n ni software especial para convertir una palabra en un hashtag. Simplemente agregue un signo de almohadilla y listo. Aseg\u00farese de que no haya espacios, puntuaci\u00f3n ni caracteres especiales en el medio. Puedes distinguir palabras usando una letra may\u00fascula, por ejemplo, un hashtag muy popular de Nike distingue las diferentes palabras con una letra may\u00fascula ##MakeItCount (cuando leas esto, sabr\u00e1s que es &quot;Make It Count&quot;)<\/p>\n<p>\u00bfSignifica #You #Can #Add #anything #as #hashtags? No. Agregar cualquier cosa como hashtags no solo har\u00e1 que tu tweet\/publicaci\u00f3n se vea mal, sino que tambi\u00e9n molestar\u00e1 a tus seguidores. As\u00ed como demasiados cocineros estropean el caldo, \u00a1demasiados hashtags te hacen lucir horrible!<\/p>\n<p>En realidad, en el lenguaje geek, los hashtags son etiquetas de metadatos que se utilizan para agrupar conversaciones. Por ejemplo, si est\u00e1 interesado en seguir un tema de fitness, puede buscar con #fitness y cualquier tweet que use ese hashtag aparecer\u00e1 en la b\u00fasqueda y podr\u00e1 seguir a las personas que lo hayan usado.<\/p>\n<p>Si est\u00e1 buscando sumergirse en esta moda de las redes sociales, aqu\u00ed hay algunos pros y contras que debe seguir:<\/p>\n<h2>Qu\u00e9 hacer<\/h2>\n<ul>\n<li>Investigue qu\u00e9 flota en la industria en la que se encuentra. Por ejemplo, si es una peque\u00f1a empresa, descubra todos los hashtags relacionados con su l\u00ednea de negocio y util\u00edcelos para difundir su mensaje.<\/li>\n<li>Sea espec\u00edfico. Encuentre personas y empresas que compartan su inter\u00e9s en temas espec\u00edficos. Cuanto m\u00e1s espec\u00edfico sea, m\u00e1s f\u00e1cil ser\u00e1 encontrar un p\u00fablico objetivo.<\/li>\n<li>Sigue las reglas. Las reglas de uso de hashtags pueden variar de un canal a otro, aunque los principios fundamentales son los mismos. Por ejemplo, mientras que en Twitter la atenci\u00f3n se centra m\u00e1s en el tema, en Instagram, la atenci\u00f3n se centra m\u00e1s en la descripci\u00f3n de la foto.<\/li>\n<li>Los hashtags se pueden utilizar para aprovechar el marketing integrado. Cree hashtags relevantes para su empresa para promocionar sus materiales de marketing.<\/li>\n<li>Por \u00faltimo, pero no menos importante, interact\u00fae con su comunidad. Las redes sociales se tratan de conversaciones. En lugar de publicar solo hashtags y olvidarse de ellos, interact\u00fae con sus usuarios.<\/li>\n<\/ul>\n<h2>No hacer<\/h2>\n<ul>\n<li>No sobrecargues tus publicaciones con hashtags. Usar demasiados hashtags marcar\u00e1 tu mensaje como spam e incluso los buenos mensajes se ahogar\u00e1n en el mar de hashtags. C\u00ed\u00f1ete a solo dos o tres hashtags por publicaci\u00f3n. Nunca uses hashtags m\u00e1s que palabras. Es una herramienta para mejorar su conversaci\u00f3n, no la conversaci\u00f3n en s\u00ed. Usar demasiados hashtags diluir\u00e1 tu mensaje.<\/li>\n<li>C\u00ed\u00f1ete a tu g\u00e9nero y hashtag algo que sea relevante para tu negocio. No pongas hashtags en todo.<\/li>\n<li>No utilices hashtags muy largos, s\u00f3lo confunde al visitante y es contraproducente. Mantenga sus hashtags breves.<\/li>\n<li>No utilices hashtags para todas las plataformas sociales. Mientras que los sitios web como <a href=\"https:\/\/www.facebook.com\">Facebook<\/a>, <a href=\"https:\/\/www.instagram.com\">Instagram<\/a>, <a href=\"https:\/\/plus.google.com\">Google+<\/a>, YouTube, Flickr, Tumblr y Pinterest animan a sus usuarios a utilizar hashtags; para sitios web como LinkedIn, puede que no sea relevante.<\/li>\n<li>Mantenlo simple. Evite acr\u00f3nimos que la gente apenas conozca.<\/li>\n<\/ul>\n<p>Usar hashtags de la manera correcta puede ayudarlo a generar una impresi\u00f3n favorable en su p\u00fablico objetivo. \u00a1Hazlo bien y hazlo con frecuencia! \u00a1Y no olvides compartir tus comentarios en el cuadro de comentarios! \u00a1Nos encanta saber de usted!<\/p>\n<h3><\/h3>","protected":false},"excerpt":{"rendered":"<p>HASHTAGS Whether you love them or hate them, hashtags are here to stay! Coming on to the scene with trepidation in 2007, the trend has only gained huge momentum since then and now you cannot go by a day on social channels without coming across hashtags. There are funny, inspirational, weird, serious, trending, all kinds [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5639,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn-technology"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/posts\/5637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/comments?post=5637"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/posts\/5637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=5637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/categories?post=5637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/tags?post=5637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}