{"id":11597,"date":"2018-03-12T13:45:54","date_gmt":"2018-03-12T08:15:54","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=11597"},"modified":"2022-03-23T16:35:24","modified_gmt":"2022-03-23T16:35:24","slug":"carmatec-firma-un-acuerdo-con-efatoora-para-una-asociacion-tecnologica","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/es_mx\/press-and-events\/carmatec-signs-agreement-with-efatoora-for-tech-partnership\/","title":{"rendered":"Carmatec firma una asociaci\u00f3n tecnol\u00f3gica con la nueva y din\u00e1mica empresa emergente de Dubai, eFatoora; Listo para abrir nuevos caminos en la tecnolog\u00eda digital"},"content":{"rendered":"<p>BANGALORE, India, 9 de marzo de 2018, Carmatec - En otro movimiento estrat\u00e9gico para expandir el negocio en el suelo digitalmente &quot;f\u00e9rtil&quot; de Medio Oriente, la multinacional de transformaci\u00f3n digital <a href=\"http:\/\/carmatec.ae\/\">Carmatec<\/a> ha anunciado que ha firmado un acuerdo de asociaci\u00f3n con Tech Startup con sede en Dubai,<a href=\"http:\/\/www.efatoora.ae\/\"> eFatoora<\/a>. La colaboraci\u00f3n se centra en aprovechar tecnolog\u00edas emergentes como Blockchain en proyectos de alto impacto para lograr avances dram\u00e1ticos e impulsar la visi\u00f3n de Su Alteza el Jeque Hamdan Bin Mohammed Bin Rashid Al Maktoum de un Dubai sin papel en 2021. En t\u00e9rminos de avances tecnol\u00f3gicos, BlockChain promete una apertura sustancial oportunidades, especialmente para el sector comercial y log\u00edstico, mercados de capitales, seguros, propiedad intelectual, atenci\u00f3n m\u00e9dica y gobierno en Dubai.<\/p>\n<h3><\/h3>\n<h3><strong>Acerca de Carmatec<\/strong><\/h3>\n<p>Con esta asociaci\u00f3n, <a href=\"https:\/\/www.carmatec.com\/es_mx\/\">Carmatec<\/a>\u2013que es l\u00edder mundial en transformaciones digitales y soluciones de TI\u2013 fortalecer\u00e1 sus v\u00ednculos con los pa\u00edses del Golfo y explorar\u00e1 oportunidades en nuevos sectores del mercado. Hasta febrero de 2018, Carmatec ha realizado importantes contribuciones t\u00e9cnicas a los sectores de comercio electr\u00f3nico, BFSI, medios, impresi\u00f3n, publicidad, atenci\u00f3n m\u00e9dica, construcci\u00f3n, autom\u00f3vil y suministros de TI en Medio Oriente. La empresa galardonada se especializa en ofrecer soluciones de habilitaci\u00f3n digital, empresariales, de nube y de TI para empresas emergentes y organizaciones peque\u00f1as y grandes y tiene una extensa lista de clientes en 20 pa\u00edses.<\/p>\n<h3><\/h3>\n<h3><strong>Acerca de eFatoora<\/strong><\/h3>\n<p>Clasificada entre las 10 mejores startups a tener en cuenta seg\u00fan el <a href=\"https:\/\/www.gitexfuturestars.com\/\">GITEX Futuras Estrellas 2017<\/a>, <a href=\"http:\/\/www.efatoora.ae\/\">eFatoora<\/a> ha estado causando sensaci\u00f3n en el sector tecnol\u00f3gico de Dubai por su \u00faltima plataforma basada en Blockchain. Esta nueva plataforma ofrece un programa de &#039;contrato inteligente&#039; para el sector BFSI (Banca, Servicios Financieros y Seguros) que eliminar\u00e1 la necesidad de intermediarios y reducir\u00e1 el costo de operaci\u00f3n para los proveedores de servicios financieros. Adem\u00e1s, la plataforma promete eliminar las molestias relacionadas con el cambio de moneda y las transacciones relacionadas con propiedades y acciones e introduce un valor de transparencia en todo el proceso. El proyecto est\u00e1 alineado con la misi\u00f3n de eFatoora de hacer de Dubai la ciudad m\u00e1s inteligente y feliz al permitir tecnolog\u00eda sostenible en toda la ciudad.<\/p>","protected":false},"excerpt":{"rendered":"<p>BANGALORE, India, March 9, 2018, Carmatec &#8212; In another strategic move to expand business in the digitally \u2018fertile\u2019 Middle Eastern soil, the multinational digital transformation business Carmatec has announced that it has signed a partnership agreement with the Dubai-based Tech Startup, eFatoora. The collaboration is focused around leveraging emerging technologies such as Blockchain on high-impact [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-11597","post","type-post","status-publish","format-standard","hentry","category-blog","category-press-and-events"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/posts\/11597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/comments?post=11597"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/posts\/11597\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=11597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/categories?post=11597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/tags?post=11597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}