{"id":8917,"date":"2017-03-21T17:03:14","date_gmt":"2017-03-21T11:33:14","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=project&#038;p=8917"},"modified":"2023-09-29T13:31:34","modified_gmt":"2023-09-29T13:31:34","slug":"omoma","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/omoma\/","title":{"rendered":"OMOMA"},"content":{"rendered":"<p><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/OMOMA_1.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8920\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/OMOMA_1.jpg\" alt=\"OMOMA\" width=\"1600\" height=\"500\" \/><\/a><\/p>\n<h3 class=\"common_sub_head\">Descripci\u00f3n del Proyecto<\/h3>\n<p class=\"projectdesccommon\">El cliente requer\u00eda tener un sitio web de comercio electr\u00f3nico que ofreciera ropa de maternidad. El prop\u00f3sito del sistema era que los usuarios pudieran ver productos de todas las marcas y categor\u00edas y ordenarlos en tama\u00f1os y colores espec\u00edficos. El cliente requer\u00eda que la aplicaci\u00f3n fuera biling\u00fce, es decir, que la informaci\u00f3n se mostrara en ingl\u00e9s o \u00e1rabe seg\u00fan las preferencias del usuario. En la primera fase de desarrollo, el cliente exigi\u00f3 que el sitio atendiera \u00fanicamente a clientes de habla inglesa, pero que, m\u00e1s adelante, tuviera la capacidad de atender tambi\u00e9n a clientes de habla \u00e1rabe.<\/p>\n<h3 class=\"common_sub_head\">Soluci\u00f3n ofrecida<\/h3>\n<p class=\"projectdesccommon\">El equipo PHP de Carmatec estudi\u00f3 los requisitos detallados especificados por el cliente y, en base a eso, construyeron la plataforma OMOMA en Magento para satisfacer sus necesidades comerciales espec\u00edficas. El administrador ten\u00eda la funci\u00f3n de actualizar todas las categor\u00edas, precios de productos e informaci\u00f3n relacionada con el inventario en el panel de administraci\u00f3n de Magento. El equipo de desarrollo identific\u00f3 un tema de Magento adecuado seg\u00fan las necesidades del negocio y personaliz\u00f3 la configuraci\u00f3n junto con la apariencia del tema adquirido de acuerdo con las preferencias del cliente para que el sitio web pudiera aparecer al usuario final tal como lo deseaba el cliente.<\/p>\n<h3>Despliegue<\/h3>\n<p>Esto se implementa en servidores en la nube seguros y de alta disponibilidad y es tecnol\u00f3gicamente m\u00e1s avanzado que sus competidores en el mercado.<\/p>\n<h3>Duraci\u00f3n del proyecto<\/h3>\n<p>2 meses<\/p>\n<h3>Tecnolog\u00eda utilizada<\/h3>\n<p>Magento Versi\u00f3n 1.9.2.x<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\"><\/h2>","protected":false},"excerpt":{"rendered":"<p>Project Description The client required to have an ecommerce website that caters to maternity wear. The purpose of the system was for users to be able to view products across brands and categories and order them in specific sizes and colors. The client required for the app to be bilingual i.e the information to be [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38121,"template":"","portfolio_categories":[26],"class_list":["post-8917","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/8917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/38121"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=8917"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=8917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}