{"id":8811,"date":"2016-03-08T14:22:27","date_gmt":"2016-03-08T08:52:27","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=project&#038;p=8811"},"modified":"2023-03-26T02:57:46","modified_gmt":"2023-03-26T02:57:46","slug":"laboratorios-qol","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/qol-labs\/","title":{"rendered":"Laboratorios de calidad de vida"},"content":{"rendered":"<p><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/QolLabs.png\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8920\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/QolLabs.png\" alt=\"laboratorios qol\" width=\"1600\" height=\"500\"><\/a><\/p>\n<h3 class=\"common_sub_head\">Acerca de los laboratorios de calidad de vida<\/h3>\n<p align=\"justify\">QOL Labs es una l\u00ednea de <a href=\"https:\/\/www.carmatec.com\/es_mx\/healthcare-software-app-development\/\">cuidado de la salud<\/a> Suplementos para profesionales, productos seguros, \u00fanicos y eficaces de m\u00faltiples categor\u00edas para m\u00e9dicos y sus pacientes. QOL Labs promete ofrecer productos con ingredientes cl\u00ednicamente respaldados, en dosis efectivas para el cuerpo humano.<\/p>\n<h3 class=\"common_sub_head\">Requisito de negocio<\/h3>\n<p align=\"justify\">QOL Labs se puso en contacto con Carmatec para el proyecto de renovaci\u00f3n de su sitio web existente. El alcance del proyecto tambi\u00e9n inclu\u00eda la implementaci\u00f3n de una interfaz minorista para el sitio web. El cliente necesitaba que el sitio web tuviera una apariencia contempor\u00e1nea, adem\u00e1s de ser totalmente responsivo, compatible con SEO, altamente interactivo y f\u00e1cil de usar con una navegaci\u00f3n intuitiva que le diera una ventaja sobre la competencia. Adem\u00e1s de esto, el proyecto tambi\u00e9n requer\u00eda desarrollar una aplicaci\u00f3n m\u00f3vil para el usuario administrador y todos los dem\u00e1s usuarios.<\/p>\n<h3 class=\"common_sub_head\">Soluci\u00f3n propuesta<\/h3>\n<p>La soluci\u00f3n propuesta inclu\u00eda una renovaci\u00f3n de su sitio web actual junto con la habilitaci\u00f3n de CMS para las p\u00e1ginas requeridas junto con un desarrollo back-end personalizado basado en Rails para su portal de comercio electr\u00f3nico.<\/p>\n<p align=\"justify\">Carmatec propuso implementar este proyecto en dos fases, donde la fase 1 comprend\u00eda la renovaci\u00f3n del sitio web actual, haci\u00e9ndolo m\u00e1s interactivo, optimizado para motores de b\u00fasqueda, f\u00e1cil de usar y receptivo. Esta fase tambi\u00e9n incluy\u00f3 la implementaci\u00f3n de capacidades de comercio electr\u00f3nico para que QOL Labs venda productos en l\u00ednea. Sus productos ahora se presentaban en el sitio web de una manera ordenada y hermosa para que fueran accesibles a los pacientes y m\u00e9dicos\/cl\u00ednicas y se compraran en l\u00ednea. El sitio web ten\u00eda un sistema de gesti\u00f3n de inventario para que el administrador pudiera agregar o actualizar los productos. Adem\u00e1s, el sistema CMS permitir\u00eda al administrador publicar consejos de salud o cualquier contenido informativo en el sitio web para que los visitantes del sitio lo vean, les guste y publiquen en los blogs. El sitio web tendr\u00eda 3 usuarios, incluido el usuario administrador, los profesionales\/pacientes y los usuarios invitados. Si bien los usuarios administradores pueden monitorear el sitio web, asignar roles y garantizar el buen funcionamiento del sistema, los usuarios profesionales o pacientes no tendr\u00edan ning\u00fan permiso en esta etapa.<\/p>\n<p align=\"justify\">En la fase 2 del desarrollo del sitio web, se realiz\u00f3 la implementaci\u00f3n de sistemas de m\u00faltiples tiendas para los profesionales o cl\u00ednicas. Aqu\u00ed se retomaron los portales de clientes con integraci\u00f3n ERP en el back-end. Ahora, los profesionales pudieron comenzar a vender sus productos en el sitio web y permitir que sus pacientes se registraran. La integraci\u00f3n de ERP permiti\u00f3 al usuario administrador almacenar los detalles de sus pacientes y el sistema de gesti\u00f3n hospitalaria de una manera sencilla. De manera similar, las cl\u00ednicas o profesionales tendr\u00edan una base de datos para actualizar los detalles de sus pacientes en el sistema.<\/p>\n<p align=\"justify\">En la segunda fase tambi\u00e9n se desarroll\u00f3 la aplicaci\u00f3n m\u00f3vil para el usuario administrador y todos los dem\u00e1s usuarios. La aplicaci\u00f3n se cre\u00f3 teniendo en cuenta la facilidad de uso y la escalabilidad futura. Por lo tanto, hizo posible integrar nuevas caracter\u00edsticas considerando las fases posteriores del desarrollo futuro de manera fluida.<\/p>\n<h3 class=\"common_sub_head\">Tecnolog\u00eda utilizada<\/h3>\n<p>WordPress(CMS), php, mysql, javascript, jQuery, Bootstrap, CSS3 y HTML5.<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\"><\/h2>","protected":false},"excerpt":{"rendered":"<p>About QOL Labs QOL Labs is a line of healthcare practitioner supplements, catering safe, unique, and efficacious products of multiple categories to doctors and their patients. QOL Labs promises to deliver products with clinically backed ingredients, in dosages effective for human body. Business requirement QOL Labs contacted Carmatec for the revamp project of their existing [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31233,"template":"","portfolio_categories":[26,28],"class_list":["post-8811","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce","portfolio_categories-health-care"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/8811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/31233"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=8811"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=8811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}