{"id":6768,"date":"2016-09-15T15:49:24","date_gmt":"2016-09-15T10:19:24","guid":{"rendered":"http:\/\/www.carmatec.com\/?post_type=project&#038;p=6768"},"modified":"2023-03-26T02:57:40","modified_gmt":"2023-03-26T02:57:40","slug":"inclinado-alto","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/leaningtall\/","title":{"rendered":"inclinado alto"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/5_LeaningTall-1.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8683\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/5_LeaningTall-1.jpg\" alt=\"InclinadoAlto\" width=\"1600\" height=\"500\"><\/a><\/div>\n<h3 class=\"common_sub_head\">Descripci\u00f3n del Proyecto<\/h3>\n<p class=\"projectdesccommon\" style=\"text-align: justify;\">Al cliente le gusta la decoraci\u00f3n del hogar. El requisito del cliente era crear un portal online donde se pudieran mostrar todos los servicios personalizados de carpinter\u00eda que ofrec\u00edan. El objetivo clave del sitio web era demostrar su creatividad en la creaci\u00f3n de armarios, cocinas modulares, decoraci\u00f3n de interiores, unidades de pared y muebles personalizados.<\/p>\n<h3 class=\"common_sub_head\">Soluciones ofrecidas<\/h3>\n<p>Carmatec cre\u00f3 un sitio web de WordPress donde todos los productos creativos se mostraban por categor\u00edas con distintas categor\u00edas para armarios, cocinas modulares, decoraci\u00f3n de interiores, etc. Una presentaci\u00f3n exquisita de los productos junto con una f\u00e1cil navegaci\u00f3n fue el resultado final del proyecto.<\/p>\n<h3>Tecnolog\u00eda utilizada<\/h3>\n<p>WordPress, php y mysql.<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\">&nbsp;<\/h2>","protected":false},"excerpt":{"rendered":"<p>Project Description The client is into home d\u00e9cor. The client requirement was to create an online portal where all the customized woodwork services offered by them could be showcased. The key objective of the website was to demonstrate their creativity in crafting customized wardrobes, modular kitchens, interior decoration, wall units &amp; furniture. Solutions Offered Carmatec [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31200,"template":"","portfolio_categories":[36],"class_list":["post-6768","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-design"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/6768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/31200"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=6768"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=6768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}