{"id":35228,"date":"2023-03-01T10:04:56","date_gmt":"2023-03-01T10:04:56","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=portfolio&#038;p=35228"},"modified":"2023-04-04T12:44:37","modified_gmt":"2023-04-04T12:44:37","slug":"corrisoft","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/corrisoft\/","title":{"rendered":"corrisoft"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1600\" height=\"500\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft.jpg\" alt=\"\" class=\"wp-image-35229\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft.jpg 1600w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft-18x6.jpg 18w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft-400x125.jpg 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-saga4Corrisoft-1536x480.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Descripci\u00f3n del Proyecto<\/h2>\n\n\n\n<p>La aplicaci\u00f3n Sage 4 Child Support Solutions es una ubicaci\u00f3n \u00fanica para encontrar recursos de manutenci\u00f3n infantil en un \u00e1rea. La visi\u00f3n de este proyecto es dise\u00f1ar y desarrollar aplicaciones m\u00f3viles Ionic con backend PHP Laravel. El proyecto incluir\u00eda aplicaciones m\u00f3viles para los usuarios finales con un panel de administraci\u00f3n para la empresa. Con la ayuda de las aplicaciones m\u00f3viles, los Estados\/Jurisdicciones podr\u00e1n crear las p\u00e1ginas de informaci\u00f3n. Los usuarios podr\u00e1n seleccionar la jurisdicci\u00f3n y mostrar\u00e1 la informaci\u00f3n si est\u00e1 disponible. El administrador tendr\u00e1 la funcionalidad de gestionar la informaci\u00f3n de la agencia\/caso, las p\u00e1ginas CMS, etc. en el backend. Las plataformas brindar\u00e1n el mejor servicio en seguridad y protecci\u00f3n de los datos a la empresa.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Caracter\u00edsticas<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seg\u00fan la ciudad y la jurisdicci\u00f3n, busque recursos de manutenci\u00f3n infantil<\/li>\n\n\n\n<li>Presentar casos espec\u00edficos de un problema de manutenci\u00f3n infantil<\/li>\n\n\n\n<li>Todo el contenido, las im\u00e1genes y las secciones son din\u00e1micos seg\u00fan la ciudad y la jurisdicci\u00f3n desde el backend.<\/li>\n\n\n\n<li>Actualizaciones de noticias relacionadas con el cuidado infantil y el abuso infantil.<\/li>\n\n\n\n<li>Tablero de mensajes: Mensajes del personal de la agencia a todos los NCP y CP<\/li>\n\n\n\n<li>P\u00e1gina de descripci\u00f3n del Departamento de Servicios Infantiles, Oficina de Cumplimiento de la Manutenci\u00f3n Infantil<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"795\" height=\"513\" data-id=\"35612\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft.png\" alt=\"\" class=\"wp-image-35612\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft.png 795w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft-300x194.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft-768x496.png 768w\" sizes=\"(max-width: 795px) 100vw, 795px\" \/><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<h3 class=\"wp-block-heading\">Soluci\u00f3n ofrecida<\/h3>\n\n\n\n<p>Llegar a un nivel de comprensi\u00f3n de la visi\u00f3n propuesta, <a href=\"https:\/\/www.carmatec.com\/es_mx\/\">Carmatec<\/a> ha analizado las viabilidades y los resultados previstos, proponiendo as\u00ed desarrollar una plataforma exclusiva que llegar\u00e1 al mercado ofreciendo una soluci\u00f3n intuitiva. <a href=\"https:\/\/www.carmatec.com\/es_mx\/empresa-de-desarrollo-de-aplicaciones-moviles\/\">Aplicaci\u00f3n movil<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"833\" height=\"476\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft-1.png\" alt=\"\" class=\"wp-image-35733\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft-1.png 833w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft-1-300x171.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-saga4Corrisoft-1-768x439.png 768w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>ARQUITECTURA<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pila de servicios distribuidos en AWS<\/li>\n\n\n\n<li>Escalable, con carga equilibrada y flexible para escalar<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>PLATAFORMAS SOPORTADAS<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Todos los sistemas operativos est\u00e1ndar<\/li>\n\n\n\n<li>Ionic con aplicaciones m\u00f3viles PHP Laravel y panel de administraci\u00f3n<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>M\u00d3DULO DE ADMINISTRACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Administrar roles y acceso de usuarios<\/li>\n\n\n\n<li>Informes con desglose, clasificaci\u00f3n y filtrado<\/li>\n\n\n\n<li>El administrador de la empresa puede gestionar el acceso y las funciones de los usuarios, as\u00ed como otros servicios en la plataforma en el backend.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>APLICACIONES M\u00d3VILES<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Interfaz de usuario est\u00e9tica y flujo de trabajo coherente<\/li>\n\n\n\n<li>La aplicaci\u00f3n funcionar\u00e1 sin Internet.<\/li>\n\n\n\n<li>Puerta de enlace SMS y notificaci\u00f3n push<\/li>\n\n\n\n<li>Noticias, enlaces de pago, detalles de recursos comunitarios, informaci\u00f3n de agencia\/caso<\/li>\n\n\n\n<li>Los usuarios pueden crear p\u00e1ginas de informaci\u00f3n dentro de la aplicaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>PARTES INTERESADAS<\/strong><\/p>\n\n\n\n<p>Los interesados en las aplicaciones M\u00f3viles son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los usuarios finales&nbsp;<\/li>\n\n\n\n<li>Administraci\u00f3n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Tecnolog\u00eda<\/h3>\n\n\n\n<p>Aplicaciones m\u00f3viles Ionic Hybrid para Android e iOS, con backend PHP, base de datos Mysql alojada en GCP<\/p>","protected":false},"excerpt":{"rendered":"<p>La aplicaci\u00f3n Sage 4 Child Support Solutions es una ubicaci\u00f3n \u00fanica para encontrar recursos de manutenci\u00f3n infantil en un \u00e1rea. La visi\u00f3n de este proyecto es dise\u00f1ar y desarrollar aplicaciones m\u00f3viles Ionic con backend PHP Laravel. <\/p>","protected":false},"author":2,"featured_media":35229,"template":"","portfolio_categories":[27,33],"class_list":["post-35228","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-education","portfolio_categories-mobile"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/35228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/35229"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=35228"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=35228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}