{"id":3240,"date":"2015-03-12T10:40:37","date_gmt":"2015-03-12T05:10:37","guid":{"rendered":"http:\/\/qatar.carmatec.com\/?post_type=project&#038;p=3240"},"modified":"2023-03-13T14:43:59","modified_gmt":"2023-03-13T14:43:59","slug":"ciro","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/cyrus\/","title":{"rendered":"Ciro"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/23_Cyrus.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8845\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/23_Cyrus.jpg\" alt=\"Ciro\" width=\"1600\" height=\"500\"><\/a><\/div>\n<h3 class=\"common_sub_head\">Descripci\u00f3n del Proyecto<\/h3>\n<p style=\"text-align: justify;\">Cyrus es una aplicaci\u00f3n que sirve a la industria de mudanzas y empacadores. Cyrus tambi\u00e9n se llama Mystoragebox. Los usuarios pueden realizar pedidos de cajas de diferentes tama\u00f1os seg\u00fan sus necesidades y pueden almacenar sus pertenencias en esas cajas y luego enviarlas de vuelta a Mystorage, donde se almacenan. Al cliente se le cobrar\u00e1 inicialmente por la entrega y recogida de la caja y posteriormente se le cobrar\u00e1 cada mes hasta que recupere las pertenencias. Se habilita un sistema automatizado para los pagos mensuales.<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\">&nbsp;<\/h2>","protected":false},"excerpt":{"rendered":"<p>Project Description Cyrus is an application that serves movers and packers industry. Cyrus is also named as Mystoragebox. Users can place the order for boxes of different sizes as per their requirement and can store their belongings in those boxes and then send back those boxes to Mystorage where the boxes are stored. The customer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31228,"template":"","portfolio_categories":[35],"class_list":["post-3240","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/3240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/31228"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=3240"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=3240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}