{"id":29326,"date":"2023-03-03T05:53:49","date_gmt":"2023-03-03T05:53:49","guid":{"rendered":"https:\/\/new.carmatec.com\/?post_type=portfolio&#038;p=29326"},"modified":"2024-07-19T12:28:38","modified_gmt":"2024-07-19T12:28:38","slug":"camas-abiertas","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/openbeds\/","title":{"rendered":"Camas Abiertas"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" class=\"wp-image-29327\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/06\/desk-screen-treatconnection.jpg\" alt=\"\" \/><\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Descripci\u00f3n del Proyecto<\/h2>\r\n\r\n\r\n\r\n<p>OpenBeds es una soluci\u00f3n de salud conductual orientada a proveedores para sistemas de salud, planes de salud y gobiernos estatales. OpenBeds crea redes de tratamiento de atenci\u00f3n coordinadas y confiables, lo que mejora el apoyo de los proveedores y la prestaci\u00f3n de atenci\u00f3n a los pacientes que la necesitan.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis: 66.66%;\">\r\n<h3 class=\"wp-block-heading\">Caracter\u00edsticas<\/h3>\r\n\r\n\r\n\r\n<p><strong>Una aplicaci\u00f3n para recomendar, compartir y comunicarse<\/strong><\/p>\r\n\r\n\r\n\r\n<p>Con OpenBeds, los proveedores de atenci\u00f3n primaria, el departamento de emergencias y otras partes interesadas en el proceso de gesti\u00f3n de crisis pueden saber d\u00f3nde hay camas disponibles en todo el estado y a qui\u00e9n pueden acomodar esas camas. Y pueden derivar personas f\u00e1cilmente y ayudar a coordinar la atenci\u00f3n en los centros receptores.<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Inventario de camas en tiempo real<\/li>\r\n\r\n\r\n\r\n<li>Proceso de recomendaci\u00f3n sencillo<\/li>\r\n\r\n\r\n\r\n<li>Informes sobre patrones de uso y referencias<\/li>\r\n\r\n\r\n\r\n<li>Integraci\u00f3n con datos PDMP<\/li>\r\n<\/ul>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis: 33.33%;\">\r\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"515\" height=\"291\" class=\"wp-image-35753\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/openbeds.png\" alt=\"\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/openbeds.png 515w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/openbeds-300x170.png 300w\" sizes=\"(max-width: 515px) 100vw, 515px\" \/><\/figure>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Soluci\u00f3n ofrecida<\/h3>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<p><strong>Sistema de proveedor a proveedor<\/strong><br \/>Este sistema ser\u00e1 utilizado por dos tipos de organizaciones: organizaciones remitentes y organizaciones receptoras.<br \/>Las organizaciones receptoras brindar\u00e1n servicios, las organizaciones remitentes har\u00e1n derivaciones para los pacientes.<br \/>Las funcionalidades son:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Servicio de b\u00fasqueda para buscar los servicios ofrecidos por las organizaciones receptoras y tambi\u00e9n su disponibilidad de camas.<\/li>\r\n\r\n\r\n\r\n<li>Hacer una solicitud de referencia<\/li>\r\n\r\n\r\n\r\n<li>Mensajes de solicitud de referencia<\/li>\r\n\r\n\r\n\r\n<li>Anal\u00edtica<\/li>\r\n\r\n\r\n\r\n<li>Apoyo a la decisi\u00f3n de tratamiento<\/li>\r\n<\/ul>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<p><strong>Sistema orientado al p\u00fablico<\/strong><br \/>Este sistema ser\u00e1 utilizado por proveedores p\u00fablicos y fuera de la red. El p\u00fablico en general puede buscar servicios seg\u00fan muchos criterios como c\u00f3digo postal, pago aceptado, etc.<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>El p\u00fablico puede hacer una solicitud de paciente o una solicitud de contacto conmigo.<\/li>\r\n\r\n\r\n\r\n<li>Los proveedores pueden enviar mensajes al usuario p\u00fablico.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p><strong>Rastreador de recursos cr\u00edticos<\/strong><\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Este sistema se puede utilizar para buscar hospitales.<\/li>\r\n\r\n\r\n\r\n<li>Puede ver los detalles de cualquier hospital haciendo clic en el nombre en la lista de b\u00fasqueda.<\/li>\r\n<\/ul>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped has-white-background-color has-background wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1365\" height=\"700\" data-id=\"35754\" class=\"wp-image-35754\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-16-36-1.png\" alt=\"\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-16-36-1.png 1365w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-16-36-1-300x154.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-16-36-1-1024x525.png 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-16-36-1-768x394.png 768w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1365\" height=\"701\" data-id=\"35756\" class=\"wp-image-35756\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-15-02-1.png\" alt=\"\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-15-02-1.png 1365w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-15-02-1-300x154.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-15-02-1-1024x526.png 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-15-02-1-768x394.png 768w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"525\" data-id=\"35757\" class=\"wp-image-35757\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-14-11-1-1024x525.png\" alt=\"\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-14-11-1-1024x525.png 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-14-11-1-300x154.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-14-11-1-768x394.png 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/Screenshot-from-2023-02-23-18-14-11-1.png 1365w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<\/figure>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Tecnolog\u00eda<\/h3>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>PHP<\/li>\r\n\r\n\r\n\r\n<li>mysql<\/li>\r\n\r\n\r\n\r\n<li>Pit\u00f3n<\/li>\r\n\r\n\r\n\r\n<li>reaccionarjs<\/li>\r\n\r\n\r\n\r\n<li>marco laravel<\/li>\r\n\r\n\r\n\r\n<li>Marco CodeIgniter<\/li>\r\n\r\n\r\n\r\n<li>HTML<\/li>\r\n\r\n\r\n\r\n<li>CSS<\/li>\r\n\r\n\r\n\r\n<li>javascript<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 100px;\" aria-hidden=\"true\">\u00a0<\/div>","protected":false},"excerpt":{"rendered":"<p>OpenBeds es una soluci\u00f3n de salud conductual orientada a proveedores para sistemas de salud, planes de salud y gobiernos estatales. OpenBeds crea redes de tratamiento de atenci\u00f3n coordinada y confiable<\/p>","protected":false},"author":2,"featured_media":29327,"template":"","portfolio_categories":[28,35],"class_list":["post-29326","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-health-care","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/29326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/29327"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=29326"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=29326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}