{"id":2840,"date":"2015-03-10T06:55:32","date_gmt":"2015-03-10T06:55:32","guid":{"rendered":"http:\/\/\/?post_type=project&#038;p=2840"},"modified":"2023-03-13T14:37:31","modified_gmt":"2023-03-13T14:37:31","slug":"administrador-de-esalud","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es_mx\/portfolio\/ehealth-admin\/","title":{"rendered":"Administrador de salud electr\u00f3nica"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/ehealth_admin_banner.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8731\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/ehealth_admin_banner.jpg\" alt=\"ehealth_admin_banner\" width=\"1600\" height=\"500\"><\/a><\/div>\n<h3 class=\"common_sub_head\">Descripci\u00f3n del Proyecto<\/h3>\n<p class=\"projectdesccommon\" style=\"text-align: justify;\">Para gestionar una aplicaci\u00f3n SAAS enorme como esta no podemos saltarnos la idea de tener un panel de administraci\u00f3n dedicado para controlar y automatizar la aplicaci\u00f3n. As\u00ed que integramos un panel de administraci\u00f3n completo en el <a href=\"https:\/\/www.carmatec.com\/es_mx\/healthcare-software-app-development\/\">aplicaci\u00f3n sanitaria<\/a>.<\/p>\n<h3 class=\"common_sub_head\">Caracter\u00edsticas<\/h3>\n<p class=\"projectdesccommon\">1. Gesti\u00f3n de Usuarios (Cl\u00ednicas).<br \/>\n2. Gesti\u00f3n de consultas.<br \/>\n3. Gesti\u00f3n de Producto.<br \/>\n4. Gesti\u00f3n administrativa.<br \/>\n5. Gesti\u00f3n de correo electr\u00f3nico y notificaciones.<br \/>\n6. Google Analytics, etc.<\/p>\n<h3>Despliegue<\/h3>\n<p>Esto se implementa en servidores en la nube seguros y de alta disponibilidad y es tecnol\u00f3gicamente m\u00e1s avanzado que sus competidores en el mercado.<\/p>\n<h3>Duraci\u00f3n del proyecto<\/h3>\n<p>3 meses<\/p>","protected":false},"excerpt":{"rendered":"<p>Project Description To manage a huge SAAS application like this we cannot skip the idea of having a dedicated admin panel to control and automate the application. So we integrated full-fledged admin panel into the healthcare application. Features 1. User(Clinics) Management. 2. Query Management. 3. Product Management. 4. Admin Management. 5. Email and Notifications Management. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31262,"template":"","portfolio_categories":[28],"class_list":["post-2840","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-health-care"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio\/2840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/31262"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=2840"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/portfolio_categories?post=2840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}