{"id":26982,"date":"2022-01-22T10:43:35","date_gmt":"2022-01-22T10:43:35","guid":{"rendered":"https:\/\/new.carmatec.com\/?post_type=casestudy&#038;p=26982"},"modified":"2023-09-27T11:11:07","modified_gmt":"2023-09-27T11:11:07","slug":"aprovechar-el-poder-de-iot-para-la-educacion-rural","status":"publish","type":"casestudy","link":"https:\/\/www.carmatec.com\/es_mx\/casestudy\/harnessing-the-power-of-iot-for-rural-education\/","title":{"rendered":"Aprovechar el poder de la IoT para la educaci\u00f3n rural"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26982\" class=\"elementor elementor-26982\" data-elementor-post-type=\"casestudy\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edc9968 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc9968\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88460ed\" data-id=\"88460ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2f5178 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a2f5178\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e92733\" data-id=\"0e92733\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0b70d elementor-widget elementor-widget-lae-heading\" data-id=\"9c0b70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Pa\u00eds<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6000696 elementor-widget elementor-widget-text-editor\" data-id=\"6000696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAustralia\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b856e0c\" data-id=\"b856e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee0bc6 elementor-widget elementor-widget-lae-heading\" data-id=\"1ee0bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Industria<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af1b901 elementor-widget elementor-widget-text-editor\" data-id=\"af1b901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Educaci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-441399b\" data-id=\"441399b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-333b274 elementor-widget elementor-widget-lae-heading\" data-id=\"333b274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Plataforma<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1db07 elementor-widget elementor-widget-text-editor\" data-id=\"4c1db07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Web y m\u00f3vil<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2731b195 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2731b195\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-532bbb72\" data-id=\"532bbb72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac07876 elementor-widget elementor-widget-lae-heading\" data-id=\"ac07876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-align\" >\n\n    <h3 class=\"lae-title\">Requisito de negocio<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0c8da61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c8da61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f081e4a elementor-invisible\" data-id=\"f081e4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70fef06 elementor-widget elementor-widget-text-editor\" data-id=\"70fef06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"common_para\">El cliente necesitaba una soluci\u00f3n educativa donde se pudiera impartir contenido educativo a las escuelas en una plataforma tecnol\u00f3gica en \u00e1reas que tienen acceso limitado a la tecnolog\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b22863f elementor-widget elementor-widget-text-editor\" data-id=\"b22863f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p class=\"common_para\">Necesitaban realizar una gesti\u00f3n de contenidos educativos aprovechando las capacidades de IoT, en lugares donde, si bien un equipo dedicado podr\u00eda acceder a la tecnolog\u00eda e Internet, la audiencia final ser\u00edan los estudiantes de \u00e1reas rurales donde tendr\u00edan acceso limitado o nulo a la tecnolog\u00eda e Internet.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4697937 elementor-invisible\" data-id=\"4697937\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2765b92 elementor-widget elementor-widget-image\" data-id=\"2765b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"488\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg\" class=\"attachment-full size-full wp-image-28118\" alt=\"Objetivos comerciales 2\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg 800w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-300x183.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-768x468.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c19173b elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c19173b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd4aa0\" data-id=\"0fd4aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7787a9f elementor-widget elementor-widget-lae-heading\" data-id=\"7787a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Aplicaci\u00f3n web<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-091858f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"091858f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b6fa688\" data-id=\"b6fa688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69919a5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"69919a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En la estructura que se muestra arriba, los niveles de organizaci\u00f3n y divisi\u00f3n son manejados por la aplicaci\u00f3n en la nube.<br \/>Carmatec propuso desarrollar la aplicaci\u00f3n web back-end utilizando el marco LAMP. El marco LAMP est\u00e1 construido con Linux, Apache, MySQL y PHP. Plataforma PHP personalizada con HTML como front-end y MySQL como back-end. PHP se utiliza para dise\u00f1ar cualquier tipo de aplicaci\u00f3n y es escalable. Se puede ejecutar en todos los principales sistemas operativos, incluidos Linux, UNIX, Mac OS y Windows, siempre que el servidor backend est\u00e9 en una LAMP.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b28fe5a elementor-widget elementor-widget-image\" data-id=\"b28fe5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"735\" height=\"550\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/02\/Case-Study-on-Android-IoT-Application-for-Education.jpg\" class=\"attachment-full size-full wp-image-26985\" alt=\"Estudio de caso sobre la aplicaci\u00f3n IoT de Android para la educaci\u00f3n\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/02\/Case-Study-on-Android-IoT-Application-for-Education.jpg 735w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/02\/Case-Study-on-Android-IoT-Application-for-Education-300x224.jpg 300w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d8d319 elementor-widget elementor-widget-lae-heading\" data-id=\"7d8d319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Aplicaci\u00f3n maestra de Android<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-204998d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"204998d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-742451f\" data-id=\"742451f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-833b17a elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"833b17a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Carmatec propuso desarrollar una &quot;aplicaci\u00f3n maestra de Android&quot; que ser\u00eda utilizada por un grupo de organizaciones. Master App sincroniza solo el contenido necesario para el plan de estudios de ese grupo y el idioma local. Una vez que la aplicaci\u00f3n maestra ha recopilado informaci\u00f3n del m\u00f3dulo de la escuela, tambi\u00e9n integra todos los datos de las transacciones en la nube.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-19951d3 elementor-widget elementor-widget-lae-heading\" data-id=\"19951d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Aplicaci\u00f3n Frambuesa Pi<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cfc8fdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfc8fdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f215a23\" data-id=\"f215a23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bff4ca elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6bff4ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Carmatec propuso desarrollar una \u201cAplicaci\u00f3n Raspberry Pi\u201d que ser\u00eda utilizada por el m\u00f3dulo de una escuela. La Raspberry Pi actuar\u00eda como servidor en las redes de intranet de la escuela. Las escuelas normalmente estar\u00edan en ubicaciones remotas con poca o ninguna conectividad a Internet. La Master App se sincronizar\u00eda con Raspberry Pi para impulsar todas las actualizaciones de contenido educativo y extraer toda la informaci\u00f3n de las escuelas y estudiantes locales.<br \/>Carmatec propuso desarrollar la aplicaci\u00f3n web back-end utilizando el marco LAMP\/XAMPP. Este marco LAMP\/XAMPP utiliza Linux, Apache, MySQL y corePHP. Plataforma PHP personalizada con HTML como front-end y MySQL como back-end. PHP se utiliza para dise\u00f1ar cualquier tipo de aplicaci\u00f3n y es escalable. Se puede ejecutar en todos los principales sistemas operativos como Linux, UNIX, Mac OS y Windows siempre que el servidor backend est\u00e9 en una LAMP.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a69d519 elementor-widget elementor-widget-lae-heading\" data-id=\"a69d519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Aplicaci\u00f3n Android para estudiantes<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a92dee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a92dee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6a9d4e3\" data-id=\"6a9d4e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f11259 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2f11259\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Carmatec propuso desarrollar una &quot;Aplicaci\u00f3n de Android para estudiantes&quot; que los estudiantes utilizar\u00edan para aprender lecciones y evaluarse a s\u00ed mismos mediante cuestionarios. Los estudiantes podr\u00edan iniciar sesi\u00f3n a trav\u00e9s de la credencial proporcionada. Cuando los estudiantes inicien sesi\u00f3n por primera vez, podr\u00e1n ver y aprender la lecci\u00f3n 1 del nivel 1 del programa 1, que est\u00e1 desbloqueada de forma predeterminada. Al final de la lecci\u00f3n 1, habr\u00e1 una prueba que los estudiantes deber\u00e1n realizar y aprobar para pasar a la lecci\u00f3n 2. Y al final de todas las lecciones, habr\u00e1 una prueba que el estudiante deber\u00e1 aprobar para pasar a la lecci\u00f3n 2. al siguiente nivel. Adem\u00e1s, seguido de estos cuestionarios, habr\u00eda retroalimentaci\u00f3n y lecciones de recuperaci\u00f3n. Al final de cada prueba de este tipo, el maestro tendr\u00e1 la opci\u00f3n de ingresar un c\u00f3digo de acceso que se le enviar\u00e1 por correo electr\u00f3nico mientras lo agrega a la aplicaci\u00f3n. Entonces, cada vez que un estudiante inicia y cierra sesi\u00f3n, la aplicaci\u00f3n sincroniza todos los datos del estudiante desde la aplicaci\u00f3n de Android con Raspberry Pi. Esta aplicaci\u00f3n tambi\u00e9n tendr\u00eda una opci\u00f3n de \u201cSincronizaci\u00f3n\u201d; lo que ayudar\u00eda al usuario a sincronizar los datos (de las escuelas y cursos recientemente actualizados) desde Raspberry Pi con la aplicaci\u00f3n de Android del estudiante.<\/p>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d844f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"34d844f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf274af\" data-id=\"cf274af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9161bb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9161bb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b468eb elementor-invisible\" data-id=\"3b468eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f41f7e6 elementor-widget elementor-widget-lae-heading\" data-id=\"f41f7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Soluci\u00f3n ofrecida<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fedc2 elementor-widget elementor-widget-text-editor\" data-id=\"45fedc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La soluci\u00f3n propuesta consisti\u00f3 en las siguientes aplicaciones:<\/p>\n<ul>\n<li>Aplicaci\u00f3n web<\/li>\n<li>Aplicaci\u00f3n maestra de Android<\/li>\n<li>Frambuesa Pi<\/li>\n<li>Aplicaci\u00f3n Android para estudiantes<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79ba21a animated-slow elementor-invisible\" data-id=\"79ba21a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0428bb5 elementor-widget elementor-widget-lae-heading\" data-id=\"0428bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Pila de tecnolog\u00eda<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8290b50 elementor-widget elementor-widget-text-editor\" data-id=\"8290b50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>L\u00c1MPARA, marco CakePHP, CorePHP<\/li>\n<li>HTML\/CSS\/JS<\/li>\n<li>android-java<\/li>\n<li>Analizador JSON y XML<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7083da9 elementor-widget elementor-widget-text-editor\" data-id=\"7083da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Los datos del cliente est\u00e1n protegidos bajo estricta NDA y, por lo tanto, no revelamos dicha informaci\u00f3n. Sin embargo, podemos proporcionarle referencias una vez que realice una consulta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":3,"featured_media":37890,"template":"","casestudy_categories":[39,45],"class_list":["post-26982","casestudy","type-casestudy","status-publish","has-post-thumbnail","hentry","casestudy_categories-education","casestudy_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/casestudy\/26982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/casestudy"}],"about":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/types\/casestudy"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/casestudy\/26982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media\/37890"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/media?parent=26982"}],"wp:term":[{"taxonomy":"casestudy_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es_mx\/wp-json\/wp\/v2\/casestudy_categories?post=26982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}