{"id":17708,"date":"2020-03-18T16:44:02","date_gmt":"2020-03-18T11:14:02","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=17708"},"modified":"2022-08-19T15:52:46","modified_gmt":"2022-08-19T15:52:46","slug":"reaccionar-desarrollador-nativo","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/es\/jobs\/react-native-developer\/","title":{"rendered":"Reaccionar desarrollador nativo"},"content":{"rendered":"<p>Carmatec busca un desarrollador nativo de React apasionado para formar parte de un equipo de profesionales joven y emprendedor. No solo tendr\u00e1 la oportunidad de dejar su huella como desarrollador nativo de React establecido, sino que tambi\u00e9n podr\u00e1 trabajar e interactuar con profesionales experimentados que est\u00e1n profundamente comprometidos.<\/p>\n<h3>Descripci\u00f3n del trabajo:<\/h3>\n<ul>\n<li>Cree interfaces de usuario fluidas y con p\u00edxeles perfectos en ambas plataformas m\u00f3viles.<\/li>\n<li>Aproveche las API nativas para lograr integraciones profundas con ambas plataformas.<\/li>\n<li>Diagnostica y corrige errores y cuellos de botella en el rendimiento para lograr un rendimiento que parezca nativo.<\/li>\n<li>Comun\u00edquese con la comunidad de c\u00f3digo abierto para alentar y ayudar a implementar correcciones de software de misi\u00f3n cr\u00edtica: React Native se mueve r\u00e1pido y, a menudo, estropea cosas.<\/li>\n<li>Mantenga el c\u00f3digo y escriba pruebas automatizadas para garantizar que el producto sea de la m\u00e1s alta calidad.<\/li>\n<li>Realice la transici\u00f3n de las aplicaciones web React existentes a React Native.<\/li>\n<\/ul>\n<h3>Habilidades requeridas<\/h3>\n<ul>\n<li>Conocimiento firme del lenguaje JavaScript {{y TypeScript o ClojureScript}} y sus matices, incluida la sintaxis de ES6+.<\/li>\n<li>Conocimiento de programaci\u00f3n {{funcional u orientada a objetos}}<\/li>\n<li>Capacidad para escribir c\u00f3digo Javascript limpio y bien documentado.<\/li>\n<li>S\u00f3lido como una roca para trabajar con dependencias de terceros y depurar conflictos de dependencias.<\/li>\n<li>Familiaridad con herramientas de compilaci\u00f3n nativas, como XCode, Gradle {{Android Studio, IntelliJ}}<\/li>\n<li>Comprensi\u00f3n de las API REST, el modelo de solicitud de documentos y el almacenamiento fuera de l\u00ednea<\/li>\n<li>Fuerte conocimiento en el concepto Redux.<\/li>\n<\/ul>\n<p><b>Experiencia: 2+ a\u00f1os<\/b><br \/>\n<b>Ubicaci\u00f3n: Bangalore<\/b><\/p>\n<p>Si la descripci\u00f3n anterior es de su inter\u00e9s, comun\u00edquese con nosotros con su curr\u00edculum actualizado para <a href=\"mailto:teamhr@carmatec.com\">teamhr@carmatec.com <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Carmatec is looking for passionate React Native Developer to be a part of a young and entrepreneurial team of professionals. Not only will you have the chance to make your mark as an established React Native Developer, but you will also get to work and interact with seasoned professionals who are deeply committed. Job Description: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-17708","post","type-post","status-publish","format-standard","hentry","category-jobs"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/posts\/17708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/comments?post=17708"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/posts\/17708\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media?parent=17708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/categories?post=17708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/tags?post=17708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}