{"id":35761,"date":"2023-03-05T09:20:03","date_gmt":"2023-03-05T09:20:03","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=portfolio&#038;p=35761"},"modified":"2023-04-04T12:46:08","modified_gmt":"2023-04-04T12:46:08","slug":"quana","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es\/portfolio\/quana\/","title":{"rendered":"quana"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1600\" height=\"500\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana.jpg\" alt=\"quana\" class=\"wp-image-35790\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana.jpg 1600w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana-18x6.jpg 18w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana-400x125.jpg 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/mobile-screen-quana-1536x480.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Descripci\u00f3n del Proyecto<\/strong><\/h3>\n\n\n\n<p>La visi\u00f3n de este proyecto es desarrollar aplicaciones m\u00f3viles ReactNative (Android e iOS) para el cliente ThePost. Con la ayuda de las aplicaciones m\u00f3viles, los usuarios pueden ver la lista de art\u00edculos\/publicaciones y leer la descripci\u00f3n presionando los botones de flechas siguientes. Los art\u00edculos tambi\u00e9n tendr\u00e1n el v\u00eddeo que habla sobre el art\u00edculo y se mostrar\u00e1 en la ventana modal. Por lo tanto, las aplicaciones m\u00f3viles brindar\u00e1n el mejor servicio en materia de seguridad de los datos a la empresa.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h3 class=\"wp-block-heading\"><strong>Caracter\u00edsticas<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Configuraci\u00f3n de proyecto y navegaci\u00f3n para ReactNative<\/li>\n\n\n\n<li>Compatibilidad con la plataforma iOS<\/li>\n\n\n\n<li>Almacenamiento en cach\u00e9 sin conexi\u00f3n y carga desde cach\u00e9 para una experiencia de usuario perfecta<\/li>\n\n\n\n<li>Integraci\u00f3n de notificaciones push con Firebase para mantener a los usuarios interesados<\/li>\n\n\n\n<li>P\u00e1gina de inicio con selecci\u00f3n de pesta\u00f1as para permitir un acceso r\u00e1pido a diferentes secciones<\/li>\n\n\n\n<li>Pantalla de presentaci\u00f3n personalizada para que la aplicaci\u00f3n parezca m\u00e1s profesional<\/li>\n\n\n\n<li>Proceso de registro sencillo para permitir que m\u00e1s usuarios creen cuentas<\/li>\n\n\n\n<li>Sistema eficiente de inicio de sesi\u00f3n y gesti\u00f3n de sesiones para mejorar la seguridad y la experiencia del usuario.<\/li>\n\n\n\n<li>P\u00e1gina detallada de noticias o post con informaci\u00f3n relevante para los usuarios<\/li>\n\n\n\n<li>Men\u00fas de hamburguesas intuitivos para proporcionar una mejor interfaz y experiencia de usuario<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"550\" height=\"439\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/quana.png\" alt=\"\" class=\"wp-image-35762\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/quana.png 550w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/quana-300x239.png 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Soluci\u00f3n ofrecida<\/strong><\/h3>\n\n\n\n<p>Al llegar a un nivel de comprensi\u00f3n de la visi\u00f3n propuesta, Carmatec ha analizado las viabilidades y los resultados anticipados propuestos para desarrollar una plataforma exclusiva que llegar\u00e1 al mercado ofreciendo una aplicaci\u00f3n m\u00f3vil intuitiva.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"833\" height=\"476\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-quana.png\" alt=\"ms-quana\" class=\"wp-image-35791\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-quana.png 833w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-quana-300x171.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2023\/03\/ms-quana-768x439.png 768w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Tecnolog\u00eda<\/strong><\/h3>\n\n\n\n<p>Android, iOS, ReactNative, base de datos MySQL<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La visi\u00f3n de este proyecto es desarrollar aplicaciones m\u00f3viles ReactNative (Android e iOS) para el cliente ThePost. <\/p>","protected":false},"author":2,"featured_media":35790,"template":"","portfolio_categories":[32,33],"class_list":["post-35761","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-media","portfolio_categories-mobile"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio\/35761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media\/35790"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media?parent=35761"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio_categories?post=35761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}