{"id":2593,"date":"2015-03-07T07:10:26","date_gmt":"2015-03-07T01:40:26","guid":{"rendered":"http:\/\/\/?post_type=project&#038;p=2593"},"modified":"2022-08-11T07:51:52","modified_gmt":"2022-08-11T07:51:52","slug":"diseno-bcs","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es\/portfolio\/bcs-design\/","title":{"rendered":"Dise\u00f1o BCS"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"320\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/10_BCS_Black_Cate_-1024x320.jpg\" alt=\"\" class=\"wp-image-28442\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/10_BCS_Black_Cate_-1024x320.jpg 1024w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/10_BCS_Black_Cate_-300x94.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/10_BCS_Black_Cate_-768x240.jpg 768w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/10_BCS_Black_Cate_-1536x480.jpg 1536w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/03\/10_BCS_Black_Cate_.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h3 class=\"common_sub_head\">Descripci\u00f3n del Proyecto&nbsp;<\/h3>\n<p style=\"text-align: justify;\">B\u00e1sicamente, esta aplicaci\u00f3n se utiliza para anunciar cualquier tipo de productos y se divide principalmente en dos m\u00f3dulos: 1. Sitio web y 2. Administrador del sitio.<br>Esta aplicaci\u00f3n se ha desarrollado exclusivamente en Ruby on Rails con base de datos Mongoid y se ha utilizado ajax y jquery de alta calidad. Algunos de los m\u00f3dulos importantes de esta aplicaci\u00f3n son agregar listados con tipos de folletos m\u00faltiples y multiformes, administraci\u00f3n de directorios, administraci\u00f3n de galer\u00edas y im\u00e1genes de galer\u00edas, b\u00fasqueda difusa de categor\u00edas y categor\u00edas, administraci\u00f3n de usuarios y roles, etc.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Project Description&nbsp; Basically this application used for advertising any kind of products and mainly divided into two modules \u2013 1. Website and 2. Site Manager.This application has developed purely on Ruby on Rails with Mongoid database and high quality ajax, jquery have been used. Some of the important modules of this application are add listing [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28441,"template":"","portfolio_categories":[35],"class_list":["post-2593","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio\/2593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media\/28441"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media?parent=2593"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio_categories?post=2593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}