{"id":2576,"date":"2015-03-07T07:00:09","date_gmt":"2015-03-07T07:00:09","guid":{"rendered":"http:\/\/\/?post_type=project&#038;p=2576"},"modified":"2023-03-26T02:53:06","modified_gmt":"2023-03-26T02:53:06","slug":"ucliq-2","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/es\/portfolio\/ucliq-2\/","title":{"rendered":"ucl\u00edq"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/22_ucliq.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8842\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/22_ucliq.jpg\" alt=\"22_ucliq\" width=\"1600\" height=\"500\" \/><\/a><\/div>\n<h3 class=\"common_sub_head\">Descripci\u00f3n del Proyecto<\/h3>\n<p style=\"text-align: justify;\">Una aplicaci\u00f3n de red social que permite al usuario final registrarse, iniciar sesi\u00f3n y explorar la aplicaci\u00f3n. Tambi\u00e9n se facilita al usuario final buscar, compartir y agregar a la lista de favoritos. UcliQ es la forma f\u00e1cil y divertida de encontrar, revisar y hablar sobre lo bueno (y lo no tan bueno) en su \u00e1rea local. Se trata de personas reales que dan sus opiniones honestas y personales sobre todo, desde restaurantes y spas hasta cafeter\u00edas y bares. Nuestro prop\u00f3sito es conectar a las personas con las empresas locales. Adem\u00e1s de las rese\u00f1as, puedes usar UcliQ para buscar eventos, listas y hablar con otros Ucliqers<\/p>\n<h3>Despliegue<\/h3>\n<p>Esto se implementa en servidores en la nube seguros y de alta disponibilidad y es tecnol\u00f3gicamente m\u00e1s avanzado que sus competidores en el mercado.<\/p>\n<h3>Duraci\u00f3n del proyecto<\/h3>\n<p>2 meses<\/p>","protected":false},"excerpt":{"rendered":"<p>Project Description A social networking application that allows an end-user to sign up, login and explore the app. End user is also facilitated to search, share and add to the list of favourites. UcliQ is the fun and easy way to find, review and talk about what&#8217;s great &#8211; and not so great &#8211; in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28451,"template":"","portfolio_categories":[35],"class_list":["post-2576","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio\/2576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media\/28451"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media?parent=2576"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/portfolio_categories?post=2576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}