{"id":33383,"date":"2022-11-30T16:50:10","date_gmt":"2022-11-30T16:50:10","guid":{"rendered":"https:\/\/www.carmatec.com\/?page_id=33383"},"modified":"2026-02-17T04:46:56","modified_gmt":"2026-02-17T04:46:56","slug":"servicios-de-pensamiento-de-diseno-2","status":"publish","type":"page","link":"https:\/\/www.carmatec.com\/es\/design-thinking-services\/","title":{"rendered":"Servicios de pensamiento de dise\u00f1o"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"33383\" class=\"elementor elementor-33383\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eb8bbc0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5eb8bbc0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-193a2ac5\" data-id=\"193a2ac5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99f1e53 elementor-widget elementor-widget-heading\" data-id=\"99f1e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Servicios de pensamiento de dise\u00f1o<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13f5cfed elementor-widget elementor-widget-heading\" data-id=\"13f5cfed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nuestros servicios personalizados de Design Thinking sientan las bases para un proyecto de aplicaci\u00f3n m\u00f3vil exitoso al definir los objetivos del producto y los resultados comerciales y priorizar las caracter\u00edsticas correctas.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfd0e7d elementor-align-left elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"dfd0e7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.carmatec.com\/es\/contactenos-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Ponerse en contacto!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ca0e52b elementor-hidden-mobile\" data-id=\"2ca0e52b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa2d253 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa2d253\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e22eeaa\" data-id=\"e22eeaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c78789 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1c78789\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo abordamos el pensamiento de dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-72e3856 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72e3856\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57374b9\" data-id=\"57374b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3451cc1 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"3451cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-strategy.png\" class=\"attachment-full size-full wp-image-33611\" alt=\"estrategia de producto\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-strategy.png 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-strategy-300x300.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-strategy-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Estrategia de producto<\/h3><p class=\"elementor-image-box-description\">Establece criterios de \u00e9xito, identifica tu segmento de audiencia y desarrolla una propuesta de valor \u00fanica para tu producto digital.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e11f8c\" data-id=\"2e11f8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8063b2f elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8063b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/user.png\" class=\"attachment-full size-full wp-image-33613\" alt=\"usuario\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/user.png 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/user-300x300.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/user-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Investigaci\u00f3n de usuarios<\/h3><p class=\"elementor-image-box-description\">Tome decisiones de productos basadas en datos demogr\u00e1ficos, intereses, comportamientos digitales, objetivos, desaf\u00edos y motivadores de su p\u00fablico objetivo.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cfb317f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfb317f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-77916f5\" data-id=\"77916f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f082629 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"f082629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/mapping.png\" class=\"attachment-full size-full wp-image-33609\" alt=\"cartograf\u00eda\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/mapping.png 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/mapping-300x300.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/mapping-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mapeo del recorrido del usuario<\/h3><p class=\"elementor-image-box-description\">Desarrolle una experiencia de aplicaci\u00f3n m\u00f3vil o web de extremo a extremo que cumpla con sus criterios de \u00e9xito, reduzca la fricci\u00f3n y logre los objetivos de los usuarios.\u00a0<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8b8a8e1\" data-id=\"8b8a8e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbbc0d0 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"fbbc0d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/prioritizing.png\" class=\"attachment-full size-full wp-image-33610\" alt=\"priorizando\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/prioritizing.png 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/prioritizing-300x300.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/prioritizing-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Priorizar caracter\u00edsticas<\/h3><p class=\"elementor-image-box-description\">Puede ahorrar dinero y acelerar su tiempo de comercializaci\u00f3n al priorizar caracter\u00edsticas y funcionalidades que equilibren el valor para el usuario y el impacto comercial.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19700c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19700c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1ea9de1\" data-id=\"1ea9de1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8eab191 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8eab191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/roadmap.png\" class=\"attachment-full size-full wp-image-33612\" alt=\"mapa vial\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/roadmap.png 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/roadmap-300x300.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/roadmap-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hoja de ruta del producto<\/h3><p class=\"elementor-image-box-description\">Establezca una visi\u00f3n clara de crecimiento a largo plazo para mantener una ventaja competitiva y respaldar la retenci\u00f3n de usuarios.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d20a908\" data-id=\"d20a908\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e3f1e6 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6e3f1e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/developing.png\" class=\"attachment-full size-full wp-image-33608\" alt=\"desarrollando\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/developing.png 400w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/developing-300x300.png 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/developing-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Desarrollar prototipos r\u00e1pidamente<\/h3><p class=\"elementor-image-box-description\">Desarrolle un prototipo en el que se pueda hacer clic para capturar comentarios y aclarar la experiencia del usuario. Contamos con la confianza de marcas de renombre mundial.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-350ff7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"350ff7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-74884b7\" data-id=\"74884b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-242b10a0 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"242b10a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Resultados del pensamiento de dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5afd4e5c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5afd4e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nuestro servicio de pensamiento de dise\u00f1o personalizado ayuda a las empresas a:\u00a0<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Evaluar el prop\u00f3sito del producto y alinearlo con los objetivos comerciales.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Realizar investigaciones competitivas para determinar la viabilidad del mercado.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Realizar una extensa investigaci\u00f3n de usuarios para crear personas de usuario.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los viajes de usuario, los wireframes y las maquetas son esenciales para comunicar y justificar el concepto de un producto.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los prototipos en los que se puede hacer clic le permiten interactuar con una versi\u00f3n preliminar del producto.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Desarrollar una hoja de ruta para productos escalables<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Identifique resultados comerciales con priorizaci\u00f3n de funciones<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Con las funciones m\u00e1s valiosas e impactantes, ingrese al mercado r\u00e1pidamente<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6b8efdb\" data-id=\"6b8efdb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-984a085 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"984a085\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/outcomes.png\" class=\"attachment-full size-full wp-image-33500\" alt=\"servicios de pensamiento de dise\u00f1o\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/outcomes.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/outcomes-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89a196a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89a196a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3848f4a\" data-id=\"3848f4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7668ddc elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7668ddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/process-Design.png\" class=\"attachment-full size-full wp-image-33603\" alt=\"dise\u00f1o de procesos\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/process-Design.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/process-Design-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-830f975\" data-id=\"830f975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c521539 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c521539\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Proceso de pensamiento de dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa6a93d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"aa6a93d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>Abrazar la empat\u00eda:\u00a0<\/b><\/p><p><span style=\"font-weight: 400;\">Conozca a sus usuarios y empatice con ellos tanto como pueda.<\/span><\/p><p><b>Definiendo:\u00a0<\/b><\/p><p><span style=\"font-weight: 400;\">Plantee una variedad de posibles soluciones al problema que necesita resolverse.<\/span><\/p><p><b>Apuntar:<\/b><\/p><p><span style=\"font-weight: 400;\">En lugar de centrarse en las limitaciones actuales, conc\u00e9ntrese en los resultados finales.<\/span><\/p><p><b>Creaci\u00f3n de prototipos:<\/b><\/p><p><span style=\"font-weight: 400;\">Se pueden utilizar prototipos para explorar posibles soluciones.<\/span><\/p><p><b>Pruebas:<\/b><\/p><p><span style=\"font-weight: 400;\">Repita el proceso de probar soluciones, reflexionar sobre los resultados e improvisar.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dca43a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dca43a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d66d7b5\" data-id=\"d66d7b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf7a59b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bf7a59b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Fundaci\u00f3n del Dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc77256 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dc77256\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Brindamos a las empresas los siguientes beneficios a trav\u00e9s de nuestra Design Foundation:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los canales y los ciclos de vida del dise\u00f1o pueden coexistir y guiar los elementos de dise\u00f1o.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Impide el dise\u00f1o aislado fomentando una mentalidad colaborativa\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Para garantizar el valor de la marca, aplique coherencia y gobernanza<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Garantiza que la organizaci\u00f3n pueda aprovechar un lenguaje de dise\u00f1o com\u00fan.<br \/><br \/><\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">El pensamiento de dise\u00f1o dirigi\u00f3 a los profesionales de la digitalizaci\u00f3n.<\/span><\/p><p><span style=\"font-weight: 400;\">Durante los \u00faltimos ocho a\u00f1os, nuestro equipo de consultores l\u00edderes y profesionales de la transformaci\u00f3n digital \u00e1giles liderados por el pensamiento de dise\u00f1o han ayudado a m\u00e1s de 500 empresas en m\u00e1s de 24 pa\u00edses con consultor\u00eda de estrategia digital, innovaci\u00f3n de dise\u00f1o y desarrollo de tecnolog\u00eda.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cbad3c2\" data-id=\"cbad3c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b659c74 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"b659c74\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/foundation.png\" class=\"attachment-full size-full wp-image-33502\" alt=\"Fundaci\u00f3n de dise\u00f1o\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/foundation.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/foundation-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e63383 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e63383\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce62674\" data-id=\"ce62674\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba34c47 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ba34c47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a1Descr\u00edbanos su proyecto!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a90357b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a90357b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Puede construir mejores relaciones m\u00f3viles con sus clientes aprovechando el dise\u00f1o de productos de Carmatec<br \/>y servicios de desarrollo de aplicaciones. Empecemos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6544fae elementor-align-center elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6544fae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.carmatec.com\/es\/contactenos-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reserve una consulta GRATUITA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb38733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb38733\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-148b7d5\" data-id=\"148b7d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37d4499 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"37d4499\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Beneficios de los servicios de pensamiento de dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1499286 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1499286\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Adem\u00e1s de identificar las necesidades latentes de los usuarios finales, una empresa puede desarrollar prototipos funcionales de bajo costo para esas necesidades y probarlos en tiempo real utilizando <a href=\"https:\/\/www.carmatec.com\/es\/aprender-tecnologia\/pensamiento-de-diseno-forma-de-exito-empresarial\/\">Principios del pensamiento de dise\u00f1o<\/a>. Una empresa tambi\u00e9n puede cambiar su cultura para volverse m\u00e1s innovadora, gestionando as\u00ed sus ingresos y sus resultados. Los beneficios potenciales incluyen los siguientes:<\/span><\/p><ul><li><span style=\"font-weight: 400;\">La detecci\u00f3n temprana de errores es m\u00e1s barata<\/span><\/li><li><span style=\"font-weight: 400;\">Rompiendo silos a trav\u00e9s del dise\u00f1o de servicios<\/span><\/li><li><span style=\"font-weight: 400;\">El dise\u00f1o del servicio conduce a una mejor experiencia del cliente<\/span><\/li><li><span style=\"font-weight: 400;\">Mejora su negocio y sus clientes ofreciendo valor<\/span><\/li><li><span style=\"font-weight: 400;\">Las empresas que utilizan el dise\u00f1o de servicios brindan experiencias positivas a los clientes.<\/span><\/li><li><span style=\"font-weight: 400;\">Mejora los flujos de trabajo de pensamiento \u00e1gil actuales con un mayor valor potencial.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\"><br \/>Otros beneficios son:<\/span><\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los clientes y usuarios son el p\u00fablico objetivo de los productos y servicios.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Se debe fortalecer la cooperaci\u00f3n departamental<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Proporcionar a los clientes una experiencia positiva.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ofrecer valor a los clientes mientras se implementan las cosas con sensatez<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mejorar la orientaci\u00f3n al cliente<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e657613 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e657613\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-466986e\" data-id=\"466986e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8046360 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8046360\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 ofrecemos como empresa l\u00edder en Design Thinking?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b457a1 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1b457a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Carmatec, como la principal empresa de servicios de pensamiento de dise\u00f1o en EE. UU., INDIA, ofrece una variedad de capacidades de dise\u00f1o, desarrollo, implementaci\u00f3n y servicios de adopci\u00f3n en todo el mundo. Entre nuestras ofertas se encuentran las siguientes:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c122f72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c122f72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c861fc0\" data-id=\"c861fc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5945dea elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5945dea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/enabling.png\" class=\"attachment-full size-full wp-image-33503\" alt=\"el pensamiento de dise\u00f1o\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/enabling.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/enabling-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dfe45e9\" data-id=\"dfe45e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44337b8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"44337b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Habilitando el pensamiento de dise\u00f1o:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20c6b37 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"20c6b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"font-weight: 400;\">\u00bfEst\u00e1 buscando soluciones a los desaf\u00edos de su negocio?<\/span><\/li><li><span style=\"font-weight: 400;\">\u00bfQuiere transformar la mentalidad, los procesos y la cultura de su organizaci\u00f3n?<\/span><\/li><li><span style=\"font-weight: 400;\">\u00bfEst\u00e1s luchando por dise\u00f1ar una estrategia de innovaci\u00f3n para el futuro?<br \/><br \/><\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Brindamos intervenciones estructuradas de asesoramiento, cocreaci\u00f3n y habilitaci\u00f3n como parte de los servicios de habilitaci\u00f3n de Design Thinking de Carmatec. Las capacidades de pensamiento de dise\u00f1o se desarrollan e implementan a trav\u00e9s de intervenciones guiadas adaptadas a industrias, funciones y roles.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Talleres de pensamiento de dise\u00f1o personalizados para clientes.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Soluciones que permiten el pensamiento de dise\u00f1o en industrias\/dominios espec\u00edficos<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2ba9c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2ba9c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38b2326\" data-id=\"38b2326\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa7715d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fa7715d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1o de Experiencias Digitales (UI\/UX):<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89bb3a9 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"89bb3a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00bfQuieres que tus clientes tengan una mejor experiencia digital?<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00bfNecesita ayuda para evaluar\/dise\u00f1ar sus activos digitales?<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Los principios de dise\u00f1o centrados en el ser humano se incorporan a nuestros servicios de dise\u00f1o de experiencias digitales, que se centran en mejorar la experiencia del usuario.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25fb3d7\" data-id=\"25fb3d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e5dd1d elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2e5dd1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/uiux-design-thinking.png\" class=\"attachment-full size-full wp-image-33594\" alt=\"pensamiento de dise\u00f1o uiux\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/uiux-design-thinking.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/uiux-design-thinking-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb58144 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb58144\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ccc9b07\" data-id=\"ccc9b07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1352c3 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"c1352c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-service-1.png\" class=\"attachment-full size-full wp-image-33597\" alt=\"servicio de dise\u00f1o de producto\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-service-1.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/product-service-1-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cb48abc\" data-id=\"cb48abc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-454e4a8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"454e4a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1o de productos y servicios:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2f0927 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b2f0927\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"font-weight: 400;\">\u00bfTiene una idea para un producto o servicio que le gustar\u00eda dise\u00f1ar?<\/span><\/li><li><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00bfQuieres crear experiencias que a tus clientes les encantar\u00e1n?<br \/><br \/><\/span><\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Como empresa de dise\u00f1o de productos y servicios, Carmatec ayuda a las organizaciones a identificar desaf\u00edos, dise\u00f1ar\/cocrear soluciones (productos, servicios, experiencias) y colaborar en proyectos de dise\u00f1o\/innovaci\u00f3n. Entre nuestros servicios se encuentran los siguientes:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dise\u00f1ar un producto nuevo o redise\u00f1ado.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dise\u00f1o de embalaje<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Desarrollo de conceptos<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Servicios de dise\u00f1o<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd1e4be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd1e4be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f071e3\" data-id=\"2f071e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-555d095 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"555d095\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Investigaci\u00f3n para el dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab587ba elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ab587ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00bfQuieres saber qu\u00e9 compran y venden los usuarios?<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00bfC\u00f3mo maneja las demandas fluctuantes de los usuarios?<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 se puede hacer para satisfacer las necesidades de los clientes en r\u00e1pida evoluci\u00f3n?<br \/><br \/><\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Un ejemplo de investigaci\u00f3n sobre la experiencia del cliente es la investigaci\u00f3n de dise\u00f1o, que se utiliza para desarrollar productos, servicios y experiencias que respondan a las necesidades humanas. Para descubrir los patrones subyacentes de comportamiento y experiencias del usuario que impulsan las decisiones de elecci\u00f3n de productos o servicios, se deben analizar los datos del usuario. Las empresas pueden diferenciarse e innovar a trav\u00e9s de este enfoque en lugar de modificar los dise\u00f1os actuales bas\u00e1ndose en an\u00e1lisis. Ofrecemos los siguientes servicios:<\/span><\/p><ul><li><span style=\"font-weight: 400;\">An\u00e1lisis de datos etnogr\u00e1ficos.<\/span><\/li><li><span style=\"font-weight: 400;\">Una visi\u00f3n de la empat\u00eda<\/span><\/li><li><span style=\"font-weight: 400;\">Comportamiento de los consumidores<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e41c4a8\" data-id=\"e41c4a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3c605d elementor-invisible elementor-widget elementor-widget-image\" data-id=\"d3c605d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/research-1.png\" class=\"attachment-full size-full wp-image-33598\" alt=\"Investigaci\u00f3n del pensamiento de dise\u00f1o\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/research-1.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/research-1-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a83b718 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a83b718\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62ed4b0\" data-id=\"62ed4b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fd31a7 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2fd31a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/office-1.png\" class=\"attachment-full size-full wp-image-33596\" alt=\"Oficina de dise\u00f1o\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/office-1.png 525w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/12\/office-1-300x200.png 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3898238\" data-id=\"3898238\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-947e980 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"947e980\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oficina de dise\u00f1o:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-757425b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"757425b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"font-weight: 400;\">\u00bfQuiere que su organizaci\u00f3n adopte una cultura de innovaci\u00f3n centrada en el cliente?<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Una oficina de dise\u00f1o integrada es el secreto para integrar el dise\u00f1o y la innovaci\u00f3n en el ADN de una organizaci\u00f3n mediante la democratizaci\u00f3n de la innovaci\u00f3n centrada en el ser humano y la promoci\u00f3n de la colaboraci\u00f3n entre silos. Entre nuestros servicios se encuentran los siguientes:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hoja de ruta para la innovaci\u00f3n<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lienzos para propuestas de valor al cliente<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dise\u00f1ando un modelo de negocio<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fceac49 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fceac49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-562735cb\" data-id=\"562735cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97c51be elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"97c51be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Preguntas m\u00e1s frecuentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43dfe2fd elementor-widget elementor-widget-accordion\" data-id=\"43dfe2fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1131\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1131\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 significa el dise\u00f1o de servicios en el pensamiento de dise\u00f1o?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1131\"><p><span style=\"font-weight: 400;\">Tomar un servicio y adaptarlo para satisfacer las necesidades de los usuarios y clientes es de lo que se trata el dise\u00f1o del servicio. Adem\u00e1s de mejorar los servicios existentes, se puede utilizar para crear otros nuevos.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1132\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1132\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfCu\u00e1l es el prop\u00f3sito del dise\u00f1o de servicios?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1132\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1132\"><p><span style=\"font-weight: 400;\">El dise\u00f1o del servicio garantiza que el producto y servicio se desarrolle para los usuarios y el grupo de clientes que compran el producto. Proporcionar valor a los clientes y a sus clientes es el prop\u00f3sito del dise\u00f1o de servicios. En el dise\u00f1o de servicios, el cliente tambi\u00e9n se tiene en cuenta a la hora de desarrollar los servicios.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1133\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1133\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfC\u00f3mo cumple el servicio su prop\u00f3sito?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1133\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1133\"><p><span style=\"font-weight: 400;\">El prop\u00f3sito del servicio es ofrecer valor a los clientes facilit\u00e1ndoles los resultados deseados sin asumir riesgos o costos particulares\u201d.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1134\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1134\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 tipo de habilidad es el pensamiento de dise\u00f1o?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1134\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1134\"><p><span style=\"font-weight: 400;\">El pensamiento de dise\u00f1o implica comprender al usuario final de un producto o servicio potencial, incluidos sus objetivos, desaf\u00edos y aspiraciones, para poder resolver problemas. Como resultado, proponen soluciones basadas en sus conocimientos. La iteraci\u00f3n est\u00e1 en el coraz\u00f3n del pensamiento de dise\u00f1o como metodolog\u00eda.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Design Thinking Services Our custom Design Thinking services sets the foundation for a successful mobile app project by defining product goals and business outcomes and prioritizing the right features. Get in touch! How We Approach Design Thinking Product Strategy Establish success criteria, identify your audience segment, and develop a unique value proposition for your digital [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-33383","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/pages\/33383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/comments?post=33383"}],"version-history":[{"count":3,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/pages\/33383\/revisions"}],"predecessor-version":[{"id":50638,"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/pages\/33383\/revisions\/50638"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/es\/wp-json\/wp\/v2\/media?parent=33383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}