{"id":9135,"date":"2017-04-11T15:58:02","date_gmt":"2017-04-11T10:28:02","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=9135"},"modified":"2022-08-19T15:20:19","modified_gmt":"2022-08-19T15:20:19","slug":"carmatec-geht-technische-e-commerce-partnerschaft-mit-der-doha-bank-ein","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/de\/press-and-events\/carmatec-enters-ecommerce-technical-partnership-with-doha-bank\/","title":{"rendered":"Carmatec geht technische E-Commerce-Partnerschaft mit der Doha Bank ein"},"content":{"rendered":"<p>Carmatec ist erfolgreich eine technische Partnerschaft mit eingegangen <a href=\"http:\/\/dohabank.qa\/\" rel=\"nofollow\">Doha-Bank<\/a> f\u00fcr ihr E-Commerce-Portal dohasooq.com. Die E-Commerce-Plattform der Doha Bank, einer der f\u00fchrenden Marken im Bank- und Finanzdienstleistungssektor auf dem katarischen Markt, wird mit modernster Technologie aufger\u00fcstet <a href=\"https:\/\/www.carmatec.com\/de\/\"><strong>Carmatec<\/strong><\/a>, eine erfahrene Organisation der IT-Branche.<\/p>\n<p>Herr Aromal Rajagopal, Gr\u00fcnder und CEO von Carmatec, der k\u00fcrzlich als einer der Hauptredner an einer von der Doha Bank organisierten KMU-Veranstaltung teilnahm, stellte den neuen Vertrag zwischen Carmatec und der Doha Bank vor. Gem\u00e4\u00df diesem Vertrag wird Carmatec als technischer Partner der Doha Bank deren E-Commerce-Plattform aktualisieren und verwalten <a href=\"https:\/\/www.dohasooq.com\/\"><strong>dohasooq.com<\/strong><\/a>. In seiner Erkl\u00e4rung erw\u00e4hnte Herr Aromal: \u201eDies ist in der Tat eine gro\u00dfartige Chance f\u00fcr Carmatec und wird erheblich dazu beitragen, auf beispiellose Weise neue profitable Wege f\u00fcr den E-Commerce-Markt in Katar und der MENA-Region zu er\u00f6ffnen.\u201c F\u00fcr dieses Projekt werden wir bald mit einem engagierten Team zusammenarbeiten, das zwischen Indien und Katar operiert. Herzlichen Gl\u00fcckwunsch an das Carmatec-Team f\u00fcr seine Bem\u00fchungen, die Verbindung zwischen Carmatec und der Doha Bank zu verwirklichen.\u201c W\u00e4hrend Carmatec mit dieser synergetischen Verbindung zwischen Carmatec und der Doha Bank eine solide Partnerschaft in der digitalen Gesch\u00e4ftslandschaft Katars erwartet, m\u00f6chte die Doha Bank ihre starke Pr\u00e4senz auf dem E-Commerce-Markt mit einer technisch leistungsf\u00e4higen E-Commerce-Plattform etablieren.<\/p>\n<p>Da die Doha Bank damit rechnet, die Art und Weise, wie die Menschen in Katar einkaufen und wie sie Online-Transaktionen wahrnehmen, zu revolutionieren, m\u00f6chte Carmatec als Wegbereiter f\u00fcr ein unvorhergesehenes Wachstum der Wirtschaft Katars dienen. Den Marktspekulationen und j\u00fcngsten E-Commerce-Markttrends zufolge kann sich der Eintritt einer starken und technisch leistungsstarken Marke wie der Doha Bank in den katarischen E-Commerce-Markt als Wendepunkt f\u00fcr die Ver\u00e4nderung des Erscheinungsbilds der katarischen Wirtschaft erweisen.<\/p>\n<p><b>\u00dcber Carmatec<\/b> Carmatec begann im Jahr 2003 mit dem ersten Angebot technischer Supportdienste f\u00fcr Rechenzentren und Hosting-Unternehmen in den USA und Europa und bietet nun seinem globalen Publikum umfassende Technologie-Business-L\u00f6sungen an. Carmatec konzentriert sich auf die Bereitstellung \u201edigitaler Transformationsl\u00f6sungen f\u00fcr KMU\u201c und entwickelt ein umfassendes, flexibles Spektrum an IT-Diensten und intelligenten Gesch\u00e4ftsl\u00f6sungen unter Verwendung bahnbrechender Informationstechnologie, die eine verbesserte End-to-End-Transparenz erm\u00f6glicht. Das Unternehmen hat eine Vielzahl von Mehrwertprodukten und umfassenden Dienstleistungen auf den Markt gebracht, die den Kunden durch die Entwicklung innovativer L\u00f6sungen, einschlie\u00dflich solcher in der Softwareentwicklung, einen erstklassigen Mehrwert bieten. <a href=\"https:\/\/www.carmatec.com\/de\/verwaltete-it-dienste-rund-um-die-uhr\/\">Verwaltete IT<\/a>, <a href=\"https:\/\/www.carmatec.com\/de\/cloud-beratungsdienste\/\">Cloud-Beratung<\/a>, <a href=\"https:\/\/www.carmatec.com\/de\/internet-marketing-dienstleistungen\/\">Internet Marketing<\/a> und Unternehmensl\u00f6sungen.<\/p>\n<p><b>\u00dcber die Doha Bank<\/b> Die 1979 er\u00f6ffnete Doha Bank ist eine der gr\u00f6\u00dften Gesch\u00e4ftsbanken im Bundesstaat Katar. Die Doha Bank bietet inl\u00e4ndische und internationale Bankdienstleistungen f\u00fcr Privat-, Gesch\u00e4fts-, Firmen- und institutionelle Kunden \u00fcber vier Gesch\u00e4ftsgruppen an: Wholesale Banking, Retail Banking, International Banking und Treasury &amp; Investments. Die Doha Bank hat Auslandsfilialen in Kuwait, Dubai (VAE), Abu Dhabi (VAE), Mumbai und Kochi (Indien) sowie Repr\u00e4sentanzen in Japan, China, Singapur, Hongkong, S\u00fcdafrika, S\u00fcdkorea, Australien und der T\u00fcrkei gegr\u00fcndet , das Vereinigte K\u00f6nigreich, Kanada, Deutschland, Bangladesch und Sharjah (VAE). Die Doha Bank erhielt zahlreiche renommierte Auszeichnungen wie \u201eBest Regional Commercial Bank\u201c \u2013 The Banker Middle East vier Jahre in Folge und \u201eBank of the Year \u2013 Qatar Domestic Trade Finance\u201c von Asian Banking &amp; Finance. Sie wurde von Fitch mit A+ bewertet. A2 von Moody&#039;s und A- von Standard &amp; Poor&#039;s f\u00fcr seine langfristige lokale und ausl\u00e4ndische W\u00e4hrung.<\/p>\n<div id=\"s3gt_translate_tooltip_mini\" class=\"s3gt_translate_tooltip_mini_box\" style=\"background: initial ! important; border: initial ! important; border-radius: initial ! important; border-spacing: initial ! important; border-collapse: initial ! important; direction: ltr ! important; flex-direction: initial ! important; font-weight: initial ! important; height: initial ! important; letter-spacing: initial ! important; min-width: initial ! important; max-width: initial ! important; min-height: initial ! important; max-height: initial ! important; margin: auto ! important; outline: initial ! important; padding: initial ! important; position: absolute; table-layout: initial ! important; text-align: initial ! important; text-shadow: initial ! important; width: initial ! important; word-break: initial ! important; word-spacing: initial ! important; overflow-wrap: initial ! important; box-sizing: initial ! important; display: initial ! important; color: inherit ! important; font-size: 13px ! important; font-family: X-LocaleSpecific,sans-serif,Tahoma,Helvetica ! important; line-height: 13px ! important; vertical-align: top ! important; white-space: inherit ! important; left: 437px; top: 40px; opacity: 0;\">\n<div id=\"s3gt_translate_tooltip_mini_logo\" class=\"s3gt_translate_tooltip_mini\" title=\"Ausgew\u00e4hlten Text \u00fcbersetzen\"><\/div>\n<div id=\"s3gt_translate_tooltip_mini_sound\" class=\"s3gt_translate_tooltip_mini\" title=\"Spielen\"><\/div>\n<div id=\"s3gt_translate_tooltip_mini_copy\" class=\"s3gt_translate_tooltip_mini\" title=\"Text in die Zwischenablage kopieren\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Carmatec has successfully entered a technical partnership with Doha Bank for their e-commerce portal dohasooq.com. The e-commerce platform of Doha Bank, one of the topmost brands in Banking &amp; Financial Services sector in the Qatar market, is going to be upgraded with cutting-edge technology to be powered by Carmatec, an IT industry veteran organization. Mr. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9136,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-and-events"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/9135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/comments?post=9135"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/9135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=9135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/categories?post=9135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/tags?post=9135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}