{"id":6042,"date":"2016-05-09T16:38:58","date_gmt":"2016-05-09T11:08:58","guid":{"rendered":"http:\/\/www.carmatec.com\/?p=6042"},"modified":"2022-08-19T08:23:57","modified_gmt":"2022-08-19T08:23:57","slug":"jeder-muss-die-terminologien-von-google-adwords-kennen","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/de\/management\/must-know-google-adwords-terminologies-everyone\/","title":{"rendered":"Jeder muss die Google AdWords-Terminologien kennen"},"content":{"rendered":"<p>Wenn es um Suchmaschinenmarketing geht, ist die Welt dunkel und voller Schrecken. Nach der letzten Folge von \u201eGame of Thrones\u201c sind wir vielleicht immer noch verkatert, aber das l\u00e4sst sich nicht leugnen <strong>Google AdWords-Terminologien<\/strong> kann voller Fachjargon und unbekanntem Gebiet sein. Tats\u00e4chlich kann das Gespr\u00e4ch mit Ihrem SEM-Spezialisten wie ein Gespr\u00e4ch in v\u00f6llig anderen Sprachen erscheinen. Aber SEM ist nat\u00fcrlich ein notwendiges Gut, schlie\u00dflich ist es der Weg zur Sichtbarkeit im Online-Dschungel. Und genau wie Wissen die Macht ist, wenn es um unbekanntes Terrain geht, wird Ihnen auch hier die Kenntnis der Terminologien von Nutzen sein.<\/p>\n<p>Google ist wahrscheinlich das Mekka der Suchmaschinen. Es bietet auch die Plattform zum Schalten von Anzeigen, die als Google AdWords bezeichnet wird. Das Schalten von Anzeigen bei Google AdWords kann Ihnen bei richtiger Planung jede Menge Leads bescheren. Aber es ist auch eine sehr t\u00fcckische Spur, da ein Fehler oder die Verwendung einer falschen Schl\u00fcsselwortauswahl zu einem gro\u00dfen Geldverlust f\u00fchren kann.<\/p>\n<p>Ganz gleich, ob Sie eine Agentur sind, Anzeigen f\u00fcr Ihre Kunden schalten oder eine Agentur mit der Durchf\u00fchrung von AdWords-Kampagnen f\u00fcr Sie beauftragen m\u00f6chten: Es gibt einige Begriffe, die jeder kennen muss, um das Beste aus AdWords herauszuholen.<\/p>\n<p>Sehen Sie sich unten die gebr\u00e4uchlichsten Google AdWords-Terminologien an:<\/p>\n<p><strong>Anzeigenerweiterungen<\/strong>: Es handelt sich um eine Art Anzeigenformat, das zusammen mit der Anzeige zus\u00e4tzliche Informationen \u00fcber das Unternehmen anzeigt. Es tr\u00e4gt zu einer besseren Sichtbarkeit und einem besseren ROI (Return on Investment) bei.<\/p>\n<p><strong>Arten von Anzeigenerweiterungen:<\/strong><\/p>\n<p><strong>1. Manuelle Erweiterung<\/strong> \u2013 Nun, die manuelle Erweiterung ist eine M\u00f6glichkeit, zus\u00e4tzliche Informationen manuell bereitzustellen. Hier sind einige manuelle Anzeigenerweiterungen:<\/p>\n<ul>\n<li>App-Erweiterungen<\/li>\n<li>Anruferweiterungen<\/li>\n<li>Standorterweiterungen<\/li>\n<li>\u00dcberpr\u00fcfen Sie Erweiterungen<\/li>\n<li>Sitelink-Erweiterungen<\/li>\n<li>Callout-Erweiterungen<\/li>\n<\/ul>\n<p><strong>2. Automatisierte Erweiterung<\/strong> \u2013 Diese Anzeigenerweiterungen werden automatisch abgerufen und daher als automatisierte Erweiterung bezeichnet. Hier sind einige der automatisierten Anzeigenerweiterungen:<\/p>\n<ul>\n<li>Verbraucherbewertungen<\/li>\n<li>Fr\u00fchere Besuche<\/li>\n<li>Dynamische strukturierte Snippets<\/li>\n<li>Verk\u00e4uferbewertungen<\/li>\n<\/ul>\n<p><strong>Anzeigengruppe:<\/strong>\u00a0Eine Anzeigengruppe besteht aus einer oder mehreren Anzeigen, die auf einen gemeinsamen Satz von Schl\u00fcsselw\u00f6rtern ausgerichtet sind. Kampagnen bestehen aus einer oder mehreren Anzeigengruppen.<\/p>\n<p><strong>Anzeigenplatzierung:<\/strong> Wir k\u00f6nnen einige Websites definieren, auf denen die Anzeigen im Google Display-Netzwerk erscheinen sollen.<\/p>\n<p><strong>Anzeigenposition:<\/strong> Die Position, an der unsere Anzeige auf der Suchseite erscheint, wird als Anzeigenposition bezeichnet.<\/p>\n<p><strong>Weitgehend passend:<\/strong> Dieser Modifikator erm\u00f6glicht, dass unsere Anzeige f\u00fcr dieselben Keywords geschaltet wird.<\/p>\n<p><strong>Budget:<\/strong> Der Gesamtbetrag, den wir f\u00fcr unsere Werbung ausgeben m\u00f6chten.<\/p>\n<p><strong>Kampagne:<\/strong> Eine Kampagne besteht aus verschiedenen Anzeigengruppen.<\/p>\n<p><strong>Klickrate (CTR):<\/strong> Dabei handelt es sich um das Verh\u00e4ltnis der Anzahl der Personen, die auf Ihre Anzeige geklickt haben, zur Anzahl der Personen, die Ihre Anzeige gesehen haben (Impression). Es wird verwendet, um zu ermitteln, wie gut Ihre Anzeigen funktionieren.<\/p>\n<p><strong>Wechselkurs:<\/strong> Es ist das Verh\u00e4ltnis der Gesamtzahl der Conversions (erreichte Ziele) zur Gesamtzahl der Klicks, die Sie erhalten.<\/p>\n<p><strong>Konvertierungen:<\/strong> Wenn die Ziele erreicht sind, die wir beschlossen haben, dann finden Konvertierungen statt.<\/p>\n<p><strong>Konvertierte Klicks:<\/strong> Es ist die Anzahl der Klicks, die zur Verwirklichung unserer Ziele gef\u00fchrt haben.<\/p>\n<p><strong>Kosten\/Umrechnung:<\/strong> Dabei handelt es sich um den Gesamtbetrag, der f\u00fcr die gew\u00fcnschte Umwandlung erforderlich ist.<\/p>\n<p><strong>Kosten pro Aktion (CPA):<\/strong> Es handelt sich um ein Zahlungsmodell f\u00fcr Online-Werbung, bei dem der Werbetreibende f\u00fcr die ausgew\u00e4hlte Aktion, wie etwa eine Impression, einen Klick oder das Absenden eines Formulars usw., bezahlen muss.<\/p>\n<p><strong>Kosten pro Klick (CPC):<\/strong> Dabei handelt es sich um den Geldbetrag, den der Werbetreibende zahlen muss, sobald auf die Anzeige geklickt wird.<\/p>\n<p><strong>Kosten pro tausend Impressionen (CPM):<\/strong> Dabei handelt es sich um den Geldbetrag, den der Werbetreibende zahlen muss, wenn die Anzeige tausend Impressionen erh\u00e4lt.<\/p>\n<p><strong>T\u00e4gliches Budget:<\/strong> Dabei handelt es sich um den Gesamtbetrag, den der Werbetreibende t\u00e4glich f\u00fcr eine Kampagne ausgeben m\u00f6chte.<\/p>\n<p><strong>Ziel-URL:<\/strong> Dabei handelt es sich um die URL, zu der der Besucher gelangt, sobald er auf die Anzeige geklickt hat.<\/p>\n<p><strong>Display-Anzeige:<\/strong> Display-Anzeigen sind Anzeigen, die im Google Display-Netzwerk erscheinen. Dabei kann es sich sowohl um Text- als auch um Image-Anzeigen handeln.<\/p>\n<p><strong>Angezeigte URL:<\/strong> \u00a0Es handelt sich um die URL, die in der Anzeige erscheint. Google zeigt bis zu 35 Zeichen in der Anzeige-URL und 20 Zeichen f\u00fcr WAP-Handy-Anzeigen an.<\/p>\n<p><strong>Genaue \u00dcbereinstimmung:<\/strong> Es handelt sich um eine Art Keyword-Match. Unsere Anzeige erscheint nur, wenn die Suchanfrage und das Schl\u00fcsselwort, das wir f\u00fcr die Anzeige festgelegt haben, genau identisch sind.<\/p>\n<p><strong>Google Display-Netzwerk:<\/strong> Das Google Display-Netzwerk erm\u00f6glicht die Anzeige von Anzeigen auf verschiedenen Google-bezogenen Websites und Blogs.<\/p>\n<p><strong>Google-Suchnetzwerk:<\/strong> Es besteht aus Textanzeigen, die auf der Google-Suchseite und anderen relevanten Websites erscheinen, die diesem Schl\u00fcsselwort entsprechen.<\/p>\n<p><strong>Image-Anzeigen:<\/strong> Anzeigen mit Bildern werden als Image-Anzeigen bezeichnet.<\/p>\n<p><strong>Eindruck:<\/strong> Die Gesamth\u00e4ufigkeit unserer Anzeige wird als Impression bezeichnet.<\/p>\n<p><strong>Stichwort:<\/strong> Satz von W\u00f6rtern, f\u00fcr die unsere Anzeige geschaltet werden soll.<\/p>\n<p><strong>Keyword-Matching-Optionen:<\/strong> Dies hilft uns, die Kontrolle \u00fcber unsere Anzeigen zu behalten, d. h. es gibt uns die Flexibilit\u00e4t zu entscheiden, bei welchen Suchanfragen unsere Anzeigen geschaltet werden.<\/p>\n<p>Es handelt sich um folgende Typen:<\/p>\n<ul>\n<li>Weitgehend passend<\/li>\n<li>Modifizierer f\u00fcr weitgehend passende Keywords<\/li>\n<li>Phrasen\u00fcbereinstimmung<\/li>\n<li>Genaue \u00dcbereinstimmung<\/li>\n<li>Negatives Spiel<\/li>\n<\/ul>\n<p><strong>Landingpage:<\/strong> Die n\u00e4chste Seite, die nach dem Klick auf die Anzeige erscheint, wird als Landingpage bezeichnet.<\/p>\n<p><strong>Verwaltete Platzierungen:<\/strong>\u00a0Im Grunde handelt es sich dabei um das Website-Targeting. Der Werbetreibende hat die volle Kontrolle dar\u00fcber, auf welchen Websites er seine Display-Anzeigen schalten m\u00f6chte.<\/p>\n<p><strong>Qualit\u00e4tsfaktor:<\/strong> Es wird verwendet, um die Kosten pro Klick zu ermitteln. Es gibt eine Reihe von Faktoren, auf denen der Qualit\u00e4tsfaktor basiert.<\/p>\n<p><strong>Remarketing:<\/strong> Dabei handelt es sich um eine Funktion in AdWords, die es Werbetreibenden erm\u00f6glicht, erneut mit Personen in Kontakt zu treten, die ihre Website bereits einmal besucht haben, indem ihnen relevante Anzeigen angezeigt werden, w\u00e4hrend sie andere Websites durchsuchen oder bei Google suchen. Das Ziel des Remarketings besteht darin, Besucher, die Ihre Website verlassen haben, dazu zu ermutigen, auf Ihre Website zur\u00fcckzukehren und eine gew\u00fcnschte Aktion auszuf\u00fchren.<\/p>\n<p><strong>Targeting-Methode:<\/strong> Dies ist die Methode, mit der wir unsere Anzeigen den Orten zuordnen, an denen unsere Anzeige geschaltet werden soll.<\/p>\n<p><strong>Textanzeige:<\/strong> Es ist das Standardformat f\u00fcr Anzeigen. Es besteht aus Titel, Beschreibung und einem Link.<\/p>\n<p>Dies sind nur einige AdWords-Begriffe, die Sie als Online-Vermarkter kennen sollten, unabh\u00e4ngig davon, ob Sie Google Advertising nutzen oder nicht! <a href=\"http:\/\/www.carmatec.com\/de\/blog\/\">Halten Sie die Augen offen in unserem Blog-Bereich<\/a> f\u00fcr weitere spannende SEO-Blogs.<\/p>\n<p>Wir bieten <a href=\"http:\/\/www.carmatec.com\/de\/internet-marketing-dienstleistungen\/\">Internet-Marketing-Dienstleistungen<\/a> zusammen mit einer Reihe von Dienstleistungen. <a href=\"http:\/\/www.carmatec.com\/de\/kontaktiere-uns\/\">Kontaktieren Sie uns<\/a>s um mehr zu wissen!<\/p>","protected":false},"excerpt":{"rendered":"<p>When it comes to search engine marketing, the world is dark and full of terrors. We may still be hungover after the last night episode of \u201cGame of Throne\u201d but there is no denying the fact that Google AdWords\u00a0terminologies can be full of jargons and unfamiliar territory. In fact, conversing with your SEM specialist may [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8],"tags":[],"class_list":["post-6042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn-technology","category-management"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/6042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/comments?post=6042"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/6042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=6042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/categories?post=6042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/tags?post=6042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}