{"id":17739,"date":"2020-03-20T12:37:37","date_gmt":"2020-03-20T07:07:37","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=17739"},"modified":"2022-10-10T06:07:03","modified_gmt":"2022-10-10T06:07:03","slug":"ui-ux-designer","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/de\/jobs\/ui-ux-designer\/","title":{"rendered":"UI\/UX-Designer \u2013 Junior"},"content":{"rendered":"<p>Carmatec sucht einen leidenschaftlichen UI\/UX-Designer als Teil eines jungen und unternehmerischen Teams von Fachleuten. Sie haben nicht nur die Chance, sich als etablierter UI\/UX-Entwickler einen Namen zu machen, sondern k\u00f6nnen auch mit erfahrenen, engagierten Profis zusammenarbeiten und interagieren.<\/p>\n<h3>Arbeitsbeschreibung:<\/h3>\n<ul>\n<li style=\"list-style-type: none;\"><\/li>\n<li>Entwickeln Sie Web-Frontend-Seiten f\u00fcr Websites und Webanwendungen mit Photoshop und<br \/>\nIllustrator als Designtool.<\/li>\n<li>Nutzen Sie JavaScript-Bibliotheken wie JQuery, Dojo, GUI und Prototype, um eine umfassende Benutzeroberfl\u00e4che bereitzustellen<br \/>\nErfahrung<\/li>\n<li>Arbeiten Sie mit Webentwicklern und Gesch\u00e4ftsanalysten zusammen, um Wireframes in umzuwandeln<br \/>\nHTML\/JavaScript-Vorlagen<\/li>\n<li>Wird unabh\u00e4ngig arbeiten, um die Kundenanforderungen bei UI-bezogenen Aufgaben zu erf\u00fcllen.<\/li>\n<\/ul>\n<h3>Ben\u00f6tigte F\u00e4higkeiten<\/h3>\n<ul>\n<li style=\"list-style-type: none;\"><\/li>\n<li>Muss \u00fcber Erfahrung im Web-\/App-Design verf\u00fcgen<\/li>\n<li>Sicherer Umgang mit Photoshop, Illustrator\/CorelDraw<\/li>\n<li>Gute Kenntnisse in HTML, CSS, Javascript, PHP (dies ist nicht unbedingt erforderlich).<br \/>\nCode, muss aber \u00fcber ein ausgepr\u00e4gtes Verst\u00e4ndnis verf\u00fcgen, um zu wissen, was praktisch ist und was nicht)<\/li>\n<li>Ausgezeichnetes Verst\u00e4ndnis von Typografie, Farbtheorie und Layouts<\/li>\n<li>Branding \u2013 ein ausgepr\u00e4gtes Verst\u00e4ndnis daf\u00fcr, wie Text und Design Hand in Hand gehen<\/li>\n<li>Festlegung der Designrichtlinien f\u00fcr verschiedene Medien wie Website, Print, Banner usw.<\/li>\n<li>F\u00e4higkeit zu improvisieren und in einer Umgebung mit begrenzten Zeit- und Ressourcenbeschr\u00e4nkungen produktiv zu sein<\/li>\n<\/ul>\n<p><b>Erfahrung: 2+ Jahre<\/b><br \/>\n<b>Standort: Bangalore<\/b><\/p>\n<p>Wenn die obige Beschreibung f\u00fcr Sie von Interesse ist, wenden Sie sich bitte mit Ihrem aktualisierten Lebenslauf an uns zur\u00fcck <a href=\"mailto:teamhr@carmatec.com\">teamhr@carmatec.com <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Carmatec is looking for a passionate UI\/UX designer to be a part of a young and entrepreneurial team of professionals. Not only will you have the chance to make your mark as an established UI\/UX developer, but you will also get to work and interact with seasoned professionals who are deeply committed. Job Description: Develop [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-17739","post","type-post","status-publish","format-standard","hentry","category-jobs"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/17739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/comments?post=17739"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/17739\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=17739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/categories?post=17739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/tags?post=17739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}