{"id":12810,"date":"2020-03-18T12:17:16","date_gmt":"2020-03-18T06:47:16","guid":{"rendered":"https:\/\/www.carmatec.com\/?p=12810"},"modified":"2022-03-16T17:03:41","modified_gmt":"2022-03-16T17:03:41","slug":"ror-tech-leiter","status":"publish","type":"post","link":"https:\/\/www.carmatec.com\/de\/jobs\/ror-tech-lead\/","title":{"rendered":"Technischer Leiter von Ruby On Rails"},"content":{"rendered":"<p>Carmatec ist auf der Suche nach einem leidenschaftlichen technischen Leiter f\u00fcr Ruby on Rails, der unser dynamisches Team leitet. Sie haben nicht nur die Chance, sich als etablierter Ruby on Rails-Leiter einen Namen zu machen, sondern k\u00f6nnen auch mit erfahrenen Fachleuten zusammenarbeiten und mit ihnen interagieren, die sich mit gro\u00dfem Engagement f\u00fcr die Revolutionierung von Ruby on Rails einsetzen <a href=\"https:\/\/www.carmatec.com\/de\/ror-entwicklungsunternehmen\/\" target=\"_blank\" rel=\"noopener noreferrer\">RoR-Entwicklung<\/a> Szenario.<\/p>\n<h3>Arbeitsbeschreibung<\/h3>\n<ul>\n<li>Ist f\u00fcr die direkte Kommunikation\/Koordination mit dem Kunden \u00fcber Skype, Web-Meeting und E-Mail verantwortlich<\/li>\n<li>Analysieren Sie die Anforderungen des Kunden und bereiten Sie technische Spezifikationen f\u00fcr die Implementierung vor.<\/li>\n<li>Erledigen Sie Aufgaben auf der Grundlage des vom Manager genehmigten Plans, der Anforderungen und des Zeitplans.<\/li>\n<li>Du bist f\u00fcr die technische Umsetzung in Projekten verantwortlich<\/li>\n<li>Sollte das Team technisch leiten<\/li>\n<li>Entwickeln Sie das Produkt und seine Elemente gem\u00e4\u00df den vom Kunden erhaltenen Spezifikationen<\/li>\n<li>\u00dcberwachen und beheben Sie gemeldete Probleme und Fehler auf Projektebene<\/li>\n<li>Legen Sie Leistungskennzahlen auf Teamebene fest und halten Sie diese ein<\/li>\n<li>Arbeiten Sie mit QA-Leitern und Testern zusammen, um die Codequalit\u00e4t und die Einhaltung von Projektzeitpl\u00e4nen zu verbessern<\/li>\n<li>Bieten Sie anderen Rollen technische Beratung zur Komponentenarchitektur<\/li>\n<li>Erwerb der erforderlichen technischen und dom\u00e4nenbezogenen Kenntnisse \u00fcber das Produkt und seine Elemente<\/li>\n<li>Sch\u00e4tzen Sie Aufgaben, definieren Sie detaillierte Zeitpl\u00e4ne, bewerten Sie Technologien, entwickeln Sie Prototypen und tragen Sie zu Designproblemen bei<\/li>\n<li>Unterst\u00fctzen Sie bei und\/oder erstellen Sie Projektpl\u00e4ne und die Verwaltung von Ressourcen<\/li>\n<li>Weisen Sie Teammitgliedern gro\u00dfe und\/oder komplexe technische Projekte zu<\/li>\n<li>Interagieren Sie regelm\u00e4\u00dfig mit dem Offshore-Teamleiter und den Onshore-Leitern, um komplexe Probleme zu l\u00f6sen und technische und nichttechnische L\u00f6sungen und Empfehlungen bereitzustellen<\/li>\n<li>Unterst\u00fctzen Sie das Management bei der technischen Planung, dem Design, der Entwicklung, dem Testen und der Bereitstellung von Projekten<\/li>\n<li>Stellen Sie sicher, dass Projekte mit hoher Qualit\u00e4t, p\u00fcnktlich und innerhalb des Budgets abgeschlossen werden<\/li>\n<li>Aufrechterhaltung einer guten Dokumentation des Aufgabenstatus<\/li>\n<li>Planen und priorisieren Sie die Aufgaben eines kleinen Teams, um eine effiziente Zeitnutzung zu f\u00f6rdern und die Produktivit\u00e4t zu maximieren.<\/li>\n<li>\u00dcberwachen Sie den Fortschritt anhand des Zeitplans. Ermitteln Sie, wann zus\u00e4tzliche Initiative erforderlich ist, um geplante Arbeiten einzuhalten, und f\u00fchren Sie diese proaktiv durch.<\/li>\n<\/ul>\n<h3>Ben\u00f6tigte F\u00e4higkeiten<\/h3>\n<ul>\n<li>\u00dcber 5 Jahre Erfahrung in der Entwicklung von Ruby-Anwendungen.<\/li>\n<li>F\u00e4higkeit, ein Entwicklerteam zu leiten.<\/li>\n<li>Analysieren, entwerfen, entwickeln und unterst\u00fctzen Sie komplexe Anwendungen.<\/li>\n<li>Entwerfen und Entwickeln komplexer Module in Ruby on Rails.<\/li>\n<li>Technisches Team-Mentoring \u2013 F\u00fchren Sie Code\u00fcberpr\u00fcfungen durch, bieten Sie technisches Mentoring an, stellen Sie eine ordnungsgem\u00e4\u00dfe Architekturaufsicht sicher und definieren Sie die Kriterien zum Erreichen von \u201eQualit\u00e4tscode\u201c.<\/li>\n<li>Sollte \u00fcber umfassende Kenntnisse in der Restful-Architektur bei der Implementierung von APIs und der Verwendung von APIs von Drittanbietern in Rails-Anwendungen verf\u00fcgen.<\/li>\n<li>Sauberes relationales Datenbankdesign zusammen mit sehr guten SQL-Kenntnissen.<\/li>\n<li>Klares Verst\u00e4ndnis von JQuery, Prototype, Ajax und Bibliotheken.<\/li>\n<li>SVN- oder Git-Versionskontrolle und Rake\/Capistrano Experience.<\/li>\n<li>Erfahrung in agiler Entwicklung, TDD\/TFD und Testtools<\/li>\n<\/ul>\n<p><b>Erfahrung: 3+ Jahre<\/b><br \/>\n<b>Standort: Bangalore<\/b><\/p>\n<p>Wenn die obige Beschreibung f\u00fcr Sie von Interesse ist, wenden Sie sich bitte mit Ihrem aktualisierten Lebenslauf an uns zur\u00fcck <a href=\"mailto:teamhr@carmatec.com\">teamhr@carmatec.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Carmatec is looking for a passionate Ruby on Rails Technical Lead to manage our dynamic team. Not only will you have the chance to make your mark as an established Ruby on Rails lead, but you will also get to work and interact with seasoned professionals deeply committed to revolutionize the RoR development scenario. Job [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-12810","post","type-post","status-publish","format-standard","hentry","category-jobs"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/12810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/comments?post=12810"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/posts\/12810\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=12810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/categories?post=12810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/tags?post=12810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}