{"id":8917,"date":"2017-03-21T17:03:14","date_gmt":"2017-03-21T11:33:14","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=project&#038;p=8917"},"modified":"2023-09-29T13:31:34","modified_gmt":"2023-09-29T13:31:34","slug":"oma","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/de\/portfolio\/omoma\/","title":{"rendered":"OMOMA"},"content":{"rendered":"<p><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/OMOMA_1.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8920\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/OMOMA_1.jpg\" alt=\"OMOMA\" width=\"1600\" height=\"500\" \/><\/a><\/p>\n<h3 class=\"common_sub_head\">Projektbeschreibung<\/h3>\n<p class=\"projectdesccommon\">Der Kunde ben\u00f6tigte eine E-Commerce-Website f\u00fcr Umstandsmode. Der Zweck des Systems bestand darin, dass Benutzer Produkte marken- und kategorien\u00fcbergreifend anzeigen und in bestimmten Gr\u00f6\u00dfen und Farben bestellen k\u00f6nnen. Der Kunde verlangte, dass die App zweisprachig ist, d. h. die Informationen sollten je nach Benutzerwunsch auf Englisch oder Arabisch angezeigt werden. In der ersten Entwicklungsphase verlangte der Kunde von der Website, dass sie nur englischsprachige Kunden bedient, sp\u00e4ter aber auch arabischsprachige Kunden bedienen kann.<\/p>\n<h3 class=\"common_sub_head\">Angebotene L\u00f6sung<\/h3>\n<p class=\"projectdesccommon\">Das PHP-Team von Carmatec untersuchte die detaillierten Anforderungen des Kunden und baute darauf basierend die OMOMA-Plattform in Magento auf, um seinen spezifischen Gesch\u00e4ftsanforderungen gerecht zu werden. Der Administrator hatte die M\u00f6glichkeit, alle Kategorien, Produktpreise und Inventarinformationen im Magento-Admin-Panel zu aktualisieren. Das Entwicklungsteam identifizierte ein geeignetes Magento-Theme basierend auf den Gesch\u00e4ftsanforderungen und passte die Konfiguration sowie das Erscheinungsbild des beschafften Themes an die Kundenpr\u00e4ferenzen an, sodass die Website dem Endbenutzer genau so angezeigt werden konnte, wie es vom Kunden beabsichtigt war<\/p>\n<h3>Einsatz<\/h3>\n<p>Dies wird auf hochverf\u00fcgbaren und gesicherten Cloud-Servern bereitgestellt und ist technologisch fortschrittlicher als seine Konkurrenten auf dem Markt.<\/p>\n<h3>Dauer des Projekts<\/h3>\n<p>2 Monate<\/p>\n<h3>Verwendete Technologie<\/h3>\n<p>Magento Version 1.9.2.x-Version<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\"><\/h2>","protected":false},"excerpt":{"rendered":"<p>Project Description The client required to have an ecommerce website that caters to maternity wear. The purpose of the system was for users to be able to view products across brands and categories and order them in specific sizes and colors. The client required for the app to be bilingual i.e the information to be [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38121,"template":"","portfolio_categories":[26],"class_list":["post-8917","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio\/8917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media\/38121"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=8917"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio_categories?post=8917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}