{"id":8811,"date":"2016-03-08T14:22:27","date_gmt":"2016-03-08T08:52:27","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=project&#038;p=8811"},"modified":"2023-03-26T02:57:46","modified_gmt":"2023-03-26T02:57:46","slug":"qol-labs","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/de\/portfolio\/qol-labs\/","title":{"rendered":"QOL Labs"},"content":{"rendered":"<p><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/QolLabs.png\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8920\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/QolLabs.png\" alt=\"qol-labs\" width=\"1600\" height=\"500\"><\/a><\/p>\n<h3 class=\"common_sub_head\">\u00dcber QOL Labs<\/h3>\n<p align=\"justify\">QOL Labs ist eine Linie von <a href=\"https:\/\/www.carmatec.com\/de\/healthcare-software-app-development\/\">Gesundheitspflege<\/a> Nahrungserg\u00e4nzungsmittel f\u00fcr \u00c4rzte, die \u00c4rzten und ihren Patienten sichere, einzigartige und wirksame Produkte verschiedener Kategorien anbieten. QOL Labs verspricht, Produkte mit klinisch best\u00e4tigten Inhaltsstoffen in f\u00fcr den menschlichen K\u00f6rper wirksamen Dosierungen zu liefern.<\/p>\n<h3 class=\"common_sub_head\">Gesch\u00e4ftsanforderung<\/h3>\n<p align=\"justify\">QOL Labs kontaktierte Carmatec f\u00fcr das \u00dcberarbeitungsprojekt ihrer bestehenden Website. Der Umfang des Projekts umfasste auch die Implementierung eines Einzelhandels-Frontends f\u00fcr die Website. Der Kunde verlangte von der Website ein zeitgem\u00e4\u00dfes Erscheinungsbild, eine vollst\u00e4ndige Reaktionsf\u00e4higkeit, SEO-F\u00e4higkeit, hohe Interaktivit\u00e4t und Benutzerfreundlichkeit sowie eine intuitive Navigation, die ihm einen Wettbewerbsvorteil verschaffen w\u00fcrde. Dar\u00fcber hinaus war im Rahmen des Projekts auch die Entwicklung einer mobilen Anwendung f\u00fcr den Admin-Benutzer und alle anderen Benutzer erforderlich.<\/p>\n<h3 class=\"common_sub_head\">Vorgeschlagene L\u00f6sung<\/h3>\n<p>Die vorgeschlagene L\u00f6sung umfasste eine \u00dcberarbeitung ihrer aktuellen Website sowie die CMS-Aktivierung f\u00fcr die erforderlichen Seiten sowie eine benutzerdefinierte Rails-basierte Backend-Entwicklung f\u00fcr ihr E-Commerce-Portal.<\/p>\n<p align=\"justify\">Carmatec schlug vor, dieses Projekt in zwei Phasen umzusetzen, wobei Phase 1 die \u00dcberarbeitung der aktuellen Website umfasste, um sie interaktiver, suchmaschinenoptimierter, benutzerfreundlicher und reaktionsf\u00e4higer zu machen. Diese Phase umfasste auch die Implementierung der E-Commerce-Funktionen f\u00fcr QOL Labs zum Online-Verkauf von Produkten. Ihre Produkte wurden nun auf der Website in einer \u00fcbersichtlichen und sch\u00f6nen Art und Weise pr\u00e4sentiert, um f\u00fcr Patienten und \u00c4rzte\/Kliniken zug\u00e4nglich zu sein und online gekauft zu werden. Die Website verf\u00fcgte \u00fcber ein Bestandsverwaltungssystem, mit dem der Administrator Produkte hinzuf\u00fcgen oder aktualisieren konnte. Dar\u00fcber hinaus w\u00fcrde das CMS-System es dem Administrator erm\u00f6glichen, Gesundheitstipps oder andere Informationsinhalte auf der Website zu ver\u00f6ffentlichen, damit die Website-Besucher sie ansehen, mit \u201eGef\u00e4llt mir\u201c markieren und in den Blogs posten k\u00f6nnen. Die Website h\u00e4tte drei Benutzer, darunter den Admin-Benutzer, \u00c4rzte\/Patienten und die Gastbenutzer. W\u00e4hrend die Admin-Benutzer die Website \u00fcberwachen, Rollen zuweisen und den reibungslosen Betrieb des Systems sicherstellen k\u00f6nnen, verf\u00fcgen die Benutzer f\u00fcr \u00c4rzte oder Patienten zu diesem Zeitpunkt \u00fcber keine Berechtigungen.<\/p>\n<p align=\"justify\">In Phase 2 der Website-Entwicklung wurde die Implementierung von Multi-Store-Systemen f\u00fcr die Praxen oder Kliniken durchgef\u00fchrt. Hierbei wurden die Kundenportale mit ERP-Integration im Backend aufgegriffen. Jetzt konnten die \u00c4rzte mit dem Verkauf ihrer Produkte auf der Website beginnen und ihren Patienten die Registrierung erm\u00f6glichen. Die ERP-Integration erm\u00f6glichte es dem Administrator, die Daten seiner Patienten und das Krankenhausverwaltungssystem auf einfache Weise zu speichern. Ebenso w\u00fcrden die Kliniken oder \u00c4rzte \u00fcber eine Datenbank verf\u00fcgen, um die Daten ihrer Patienten im System zu aktualisieren.<\/p>\n<p align=\"justify\">In der zweiten Phase wurde auch die mobile Anwendung f\u00fcr den Admin-Benutzer und alle anderen Benutzer entwickelt. Die Anwendung wurde im Hinblick auf Benutzerfreundlichkeit und zuk\u00fcnftige Skalierbarkeit entwickelt. Dadurch war es m\u00f6glich, neue Funktionen unter Ber\u00fccksichtigung der nachfolgenden Phasen der zuk\u00fcnftigen Entwicklung nahtlos zu integrieren.<\/p>\n<h3 class=\"common_sub_head\">Verwendete Technologie<\/h3>\n<p>WordPress (CMS), PHP, MySQL, Javascript, jQuery, Bootstrap, CSS3 und HTML5.<\/p>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\"><\/h2>","protected":false},"excerpt":{"rendered":"<p>About QOL Labs QOL Labs is a line of healthcare practitioner supplements, catering safe, unique, and efficacious products of multiple categories to doctors and their patients. QOL Labs promises to deliver products with clinically backed ingredients, in dosages effective for human body. Business requirement QOL Labs contacted Carmatec for the revamp project of their existing [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31233,"template":"","portfolio_categories":[26,28],"class_list":["post-8811","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce","portfolio_categories-health-care"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio\/8811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media\/31233"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=8811"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio_categories?post=8811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}