{"id":6756,"date":"2015-03-10T07:00:53","date_gmt":"2015-03-10T01:30:53","guid":{"rendered":"http:\/\/www.carmatec.com\/?post_type=project&#038;p=6756"},"modified":"2023-03-13T14:38:04","modified_gmt":"2023-03-13T14:38:04","slug":"kollektiv","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/de\/portfolio\/collective\/","title":{"rendered":"Das Kollektiv"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><a href=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/2_Collective.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-8693\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/2_Collective.jpg\" alt=\"2_Kollektiv\" width=\"1600\" height=\"500\"><\/a><\/div>\n<h3 class=\"common_sub_head\">Projektbeschreibung<\/h3>\n<p class=\"projectdesccommon\" style=\"text-align: justify;\">Das Kundengesch\u00e4ft ist eine E-Commerce-Plattform, auf der die Nutzer Produkte der renommiertesten Marken erwerben k\u00f6nnen. Die Projektanforderung umfasste eine komplette \u00dcberarbeitung des Website-Designs, um ihm ein sch\u00f6nes, frisches Aussehen zu verleihen. Die anf\u00e4ngliche Projektanforderung bestand darin, Entw\u00fcrfe f\u00fcr ihre drei wichtigsten Layouts zu erhalten, die sie auch in ihre aktuelle Website integrieren wollten. Dar\u00fcber hinaus wollten sie ihre mobile Website verbessern, um den App-Benutzern ein interaktiveres Erlebnis zu bieten. Dies war von entscheidender Bedeutung, da ihr Gesch\u00e4ft haupts\u00e4chlich \u00fcber Mobilger\u00e4te erfolgt.<\/p>\n<h3 class=\"common_sub_head\">Angebotene L\u00f6sungen<\/h3>\n<p class=\"projectdesccommon\">Neue Benutzeroberfl\u00e4che \u2013 Carmatec hat neue, frische und interaktive Designs f\u00fcr die drei am h\u00e4ufigsten navigierten Layouts bereitgestellt.<\/p>\n<p>Integration \u2013 Carmatec war f\u00fcr die Integration dieser neuen Layouts in ihren bestehenden Code verantwortlich, wobei die Herausforderung in der Version von ROR in der bestehenden Website bestand.<\/p>\n<h3 class=\"projectdesccommon\">Verwendete Technologie<\/h3>\n<p>Ruby auf Rails, Spree, HTML5, Bootstrap, jQuery und CSS3<\/p>","protected":false},"excerpt":{"rendered":"<p>Project Description The client business is an ecommerce platform where the users can purchase products of the most renowned brands. The project requirement comprised of a complete revamp of their website design in order to give it a nice, fresh appeal. The initial project requirement was to get designs for their three most important layouts [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31276,"template":"","portfolio_categories":[26],"class_list":["post-6756","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-e-commerce"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio\/6756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media\/31276"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=6756"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio_categories?post=6756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}