{"id":14261,"date":"2018-10-26T15:19:39","date_gmt":"2018-10-26T09:49:39","guid":{"rendered":"https:\/\/www.carmatec.com\/?post_type=project&#038;p=14261"},"modified":"2023-03-29T12:13:50","modified_gmt":"2023-03-29T12:13:50","slug":"qic-anaya","status":"publish","type":"portfolio","link":"https:\/\/www.carmatec.com\/de\/portfolio\/qic-anaya\/","title":{"rendered":"QIC ANAYA"},"content":{"rendered":"<div style=\"margin-bottom: 30px;\"><img decoding=\"async\" class=\"alignleft wp-image-14263 size-full\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/09\/qic-anaya-banner.jpg\" alt=\"qic-anaya\" width=\"1600\" height=\"500\"><\/div>\n<h3>&nbsp;<\/h3>\n<h3>Gesch\u00e4ftsanforderung<\/h3>\n<p>QIC hat die Vision, eine mobile App zu entwickeln, die der Zielgruppe verschiedene Produkte und Angebote pr\u00e4sentiert. Dies wird den Kunden helfen, die besten Angebote von QIC in Anspruch zu nehmen. Das ultimative Ziel des Projekts ist der Aufbau einer digitalen Plattform unter Verwendung von CakePHP f\u00fcr die Gesch\u00e4ftslogikentwicklung zusammen mit HTML5 f\u00fcr die Benutzeroberfl\u00e4che und der MySQL-Datenbank. Au\u00dferdem wird eine mobile App f\u00fcr Android und iPhone entwickelt, um potenziellen Kunden und H\u00e4ndlern eine nahtlose Interaktion zu erm\u00f6glichen.<\/p>\n<p>QIC Anaya ist eine Online-Plattform, die es Einzelpersonen in Katar erm\u00f6glicht, Gesundheitsdienstleistungen zu sehr wettbewerbsf\u00e4higen Kosten von erstklassigen Anbietern in Anspruch zu nehmen. Und halten Sie die Kunden auch \u00fcber bevorstehende Angebote auf dem Laufenden.<\/p>\n<h3>Roadmap des Unternehmens<\/h3>\n<p>Carmatec schl\u00e4gt vor, eine einsprachige (englische) native mobile Anwendung zu entwickeln. Die mobile App arbeitet synchron mit der Webanwendung und der Legacy-Anwendung und erm\u00f6glicht den Endbenutzern eine nahtlose Interaktion. Endbenutzer m\u00fcssten die App aus dem Play\/Apple Store herunterladen und sich erneut anmelden (mit QID und Handynummer). Der Benutzer wird mit dem externen\/Legacy-System validiert. Zur Authentifizierung des Benutzers wird ein API-Aufruf durchgef\u00fchrt. Nach der Authentifizierung werden die Benutzerdaten in der lokalen Anwendung gespeichert.<\/p>\n<h3>Highlight der L\u00f6sung<\/h3>\n<p>Die wichtigsten Highlights der L\u00f6sung sind:<\/p>\n<ul>\n<li>Alle Module arbeiten innerhalb der Anwendungssuite nahtlos zusammen und k\u00f6nnen per API erweitert werden.<\/li>\n<li>Benutzerfreundlichkeit: Die Seiten laden schnell und die Navigation innerhalb der Anwendung ist sehr intuitiv und einfach<\/li>\n<li>Design: Das Design ist sehr modular und basiert auf dem DRY-Konzept (Do not Repeat yourself).<\/li>\n<li>Die Anwendung ist responsiv und kann auf verschiedenen Ger\u00e4ten aufgerufen werden.<\/li>\n<li>Das Kundenportal erm\u00f6glicht es Kunden in erster Linie, sich einfach zu registrieren, Geld auf ihr E-Wallet einzuzahlen und Eink\u00e4ufe mit ihrer digitalen Geldb\u00f6rse zu t\u00e4tigen.<\/li>\n<li>Die Anwendung ist skalierbar, sicher und schnell.<\/li>\n<\/ul>\n<h3>Verwendete Technologie<\/h3>\n<p>Die Anwendung basiert auf:<\/p>\n<ul>\n<li>Betriebssystem: Unix, Linux<\/li>\n<li>Webserver: Apache<\/li>\n<li>Datenbankserver: MySQL (5.6.33)<\/li>\n<li>Serverseitige Skriptsprache: PHP (7.1)<\/li>\n<li>PHP-Framework: CakePHP (3.6)<\/li>\n<li>Clientseite: HTML5, CSS3, JQuery, Javascript, Bootstrap3<\/li>\n<li>Hosting-Umgebung: CPanel<\/li>\n<\/ul>\n<h2 style=\"text-transform: uppercase; color: #393939; font-size: 42px; margin-bottom: 20px; text-align: center;\">&nbsp;<\/h2>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Business Requirement QIC has come up with a vision to develop a mobile app which will showcase various products and the offers to the target audience. This will help the customers to avail the best offers provided by QIC. The ultimate objective of the project is to build an digital platform using CakePHP for [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31232,"template":"","portfolio_categories":[28,30,33],"class_list":["post-14261","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-health-care","portfolio_categories-insurance","portfolio_categories-mobile"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio\/14261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media\/31232"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=14261"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/portfolio_categories?post=14261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}