{"id":26989,"date":"2022-02-21T10:52:24","date_gmt":"2022-02-21T10:52:24","guid":{"rendered":"https:\/\/new.carmatec.com\/?post_type=casestudy&#038;p=26989"},"modified":"2023-09-28T08:57:15","modified_gmt":"2023-09-28T08:57:15","slug":"funktionserweiterung","status":"publish","type":"casestudy","link":"https:\/\/www.carmatec.com\/de\/casestudy\/functionality-enhancement\/","title":{"rendered":"Funktionserweiterung"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26989\" class=\"elementor elementor-26989\" data-elementor-post-type=\"casestudy\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edc9968 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc9968\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88460ed\" data-id=\"88460ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2f5178 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a2f5178\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e92733\" data-id=\"0e92733\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0b70d elementor-widget elementor-widget-lae-heading\" data-id=\"9c0b70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Land<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6000696 elementor-widget elementor-widget-text-editor\" data-id=\"6000696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tIndien\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b856e0c\" data-id=\"b856e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee0bc6 elementor-widget elementor-widget-lae-heading\" data-id=\"1ee0bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Industrie<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af1b901 elementor-widget elementor-widget-text-editor\" data-id=\"af1b901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ausbildung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-441399b\" data-id=\"441399b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-333b274 elementor-widget elementor-widget-lae-heading\" data-id=\"333b274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Plattform<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1db07 elementor-widget elementor-widget-text-editor\" data-id=\"4c1db07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Netz<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2731b195 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2731b195\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-532bbb72\" data-id=\"532bbb72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac07876 elementor-widget elementor-widget-lae-heading\" data-id=\"ac07876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-align\" >\n\n    <h3 class=\"lae-title\">Gesch\u00e4ftsanforderung<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0c8da61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c8da61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f081e4a elementor-invisible\" data-id=\"f081e4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70fef06 elementor-widget elementor-widget-text-editor\" data-id=\"70fef06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"common_para\">Als beliebte Website unter den Top-1000-Websites des Landes mit kontinuierlichem Wachstum bestand das Kundengesch\u00e4ft darin, Studenten bei der Vorbereitung von Vorstellungsgespr\u00e4chen im technischen Bereich zu unterst\u00fctzen. Als Technologiepartner hat Carmatec seinem Team dabei geholfen, die Gesch\u00e4ftsziele der Umsatzsteigerung zu erreichen, indem die Website mit verschiedenen Funktionen ausgestattet wurde. Angefangen als kostenlose Website, auf der alle Benutzer das gesamte Lern-\/Vorbereitungsmaterial sehen konnten, entschied sich der Kunde nun angesichts der wachsenden Beliebtheit, kostenpflichtige Benutzerfunktionen hinzuzuf\u00fcgen, um den Benutzern je nach Abonnementstufe unterschiedliche Vorbereitungsmaterialien bereitzustellen. Daher erforderte die aktuelle Anforderung Verbesserungen an der bestehenden Website, einschlie\u00dflich kostenpflichtiger Benutzerfunktionen und einiger anderer Funktionen, die das reibungslose Funktionieren und die Effektivit\u00e4t der digitalen Pr\u00e4senz des Unternehmens des Kunden erleichterten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4697937 elementor-invisible\" data-id=\"4697937\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2765b92 elementor-widget elementor-widget-image\" data-id=\"2765b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"488\" src=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg\" class=\"attachment-full size-full wp-image-28118\" alt=\"Gesch\u00e4ftsziele 2\" srcset=\"https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861.jpg 800w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-300x183.jpg 300w, https:\/\/www.carmatec.com\/wp-content\/uploads\/2022\/01\/Untitled-design-17-e1646223487861-768x468.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c19173b elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c19173b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd4aa0\" data-id=\"0fd4aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7787a9f elementor-widget elementor-widget-lae-heading\" data-id=\"7787a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-aligncenter\" >\n\n    <h3 class=\"lae-title\">Gesch\u00e4ftsziele<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-091858f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"091858f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b6fa688\" data-id=\"b6fa688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69919a5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"69919a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>Zu den Hauptzielen der Initiierung dieses Projekts geh\u00f6rten:<\/b><\/p>\n<ul>\n<li>Die Notwendigkeit, die Funktionalit\u00e4t f\u00fcr kostenpflichtige Benutzer hinzuzuf\u00fcgen, damit sie den Benutzern je nach Abonnementstufe das Lernmaterial unterschiedlich zur Verf\u00fcgung stellen k\u00f6nnen<\/li>\n<li>Eine inkrementelle L\u00f6sung \u2013 Die L\u00f6sung, die ihrem inkrementellen Bedarf gerecht wird, mehr Material f\u00fcr die inkrementell hinzugef\u00fcgten Unternehmen hochzuladen.<\/li>\n<li>Die Notwendigkeit, die Probleme mit der Ladegeschwindigkeit der Website zu \u00fcberwinden \u2013 um den erwarteten starken Datenverkehr auf der Website zu bew\u00e4ltigen, da das Unternehmen weiteres Wachstum verzeichnen w\u00fcrde.<\/li>\n<\/ul>\n<p><!-- \/wp:heading --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d844f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"34d844f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf274af\" data-id=\"cf274af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9161bb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9161bb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b468eb elementor-invisible\" data-id=\"3b468eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f41f7e6 elementor-widget elementor-widget-lae-heading\" data-id=\"f41f7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Angebotene L\u00f6sung<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fedc2 elementor-widget elementor-widget-text-editor\" data-id=\"45fedc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Carmatec schlug eine WordPress-basierte L\u00f6sung zur Verbesserung der Kunden-Website vor. Unter Verwendung dieses kostenlosen und quelloffenen Content-Management-Systems (CMS), das auf PHP und MySQL basiert, wurde die Anwendung so entwickelt, dass sie auf einem eleganten Woo-Commerce-Theme basiert und mit allen unterst\u00fctzenden Plugins, die konfiguriert und installiert sind, perfekt auf jeden ihrer Bed\u00fcrfnisse zugeschnitten ist. Die neu hinzugef\u00fcgte Funktionalit\u00e4t f\u00fcr kostenpflichtige Benutzer stellte sicher, dass der Inhalt f\u00fcr kostenlose und kostenpflichtige Benutzer unterschiedlich sichtbar war, genau wie es zur Unterst\u00fctzung ihres geplanten Umsatzmodells erforderlich war.<\/li>\n<li>Um das Problem mit der Ladegeschwindigkeit ihrer bestehenden Website zu l\u00f6sen, erhielt ihre Website, die damals auf Godaddy gehostet wurde und sehr langsam lief, entsprechende Hosting-Unterst\u00fctzung, um den erwarteten Anstieg des Datenverkehrs in naher Zukunft effektiv bew\u00e4ltigen zu k\u00f6nnen.<\/li>\n<li>Ihnen wurde eine inkrementelle und benutzerfreundliche L\u00f6sung zur Verf\u00fcgung gestellt, mit der sie das vorbereitende Material und die spezifischen Inhalte f\u00fcr jedes neue und bestehende Unternehmen einfach separat verwalten und hochladen konnten, sobald ihnen die neuen Informationen zur Verf\u00fcgung standen.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79ba21a animated-slow elementor-invisible\" data-id=\"79ba21a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0428bb5 elementor-widget elementor-widget-lae-heading\" data-id=\"0428bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Technologie-Stack<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8290b50 elementor-widget elementor-widget-text-editor\" data-id=\"8290b50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Benutzerdefinierte PHP-L\u00f6sung mit Angular JS, unterst\u00fctzt durch eine AWS-basierte Infrastruktur<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd0aa6c elementor-widget elementor-widget-lae-heading\" data-id=\"cd0aa6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-heading lae-style1 lae-alignleft\" >\n\n    <h3 class=\"lae-title\">Ergebnisse<\/h3>\n\n    \n<\/div><!-- .lae-heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7083da9 elementor-widget elementor-widget-text-editor\" data-id=\"7083da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Derzeit geh\u00f6rt die Kunden-Website zu den Top-1000-Websites und erfreut sich mit den erfolgreich hinzugef\u00fcgten neuen Verbesserungen weiterhin wachsender Beliebtheit und Umsatz.<\/li>\n<li>Als ihr Technologiepartner unterst\u00fctzt und unterst\u00fctzt Carmatec den Kunden weiterhin dabei, bei Bedarf weiteres kostenpflichtiges Material hinzuzuf\u00fcgen, und hilft seinem Team auch dabei, die kommerziellen Ziele des Unternehmens zu erreichen.<\/li>\n<li>Mit der vorgeschlagenen AWS-L\u00f6sung kann die Infrastruktur den Leistungserwartungen angesichts des kontinuierlich wachsenden Datenverkehrs auf der Website besser gerecht werden.<\/li>\n<li>Die angebotene benutzerdefinierte PHP-basierte L\u00f6sung mit Angular JS als Frontend ist in der Lage, die Site nach Bedarf inkrementell zu organisieren und zu erstellen.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":3,"featured_media":37922,"template":"","casestudy_categories":[39,45],"class_list":["post-26989","casestudy","type-casestudy","status-publish","has-post-thumbnail","hentry","casestudy_categories-education","casestudy_categories-web-app-development"],"_links":{"self":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/casestudy\/26989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/casestudy"}],"about":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/types\/casestudy"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/casestudy\/26989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media\/37922"}],"wp:attachment":[{"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/media?parent=26989"}],"wp:term":[{"taxonomy":"casestudy_categories","embeddable":true,"href":"https:\/\/www.carmatec.com\/de\/wp-json\/wp\/v2\/casestudy_categories?post=26989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}